{"id":15679,"date":"2014-06-17T19:36:46","date_gmt":"2014-06-17T17:36:46","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/06\/Mirianna-Masella2.jpg"},"modified":"2014-06-17T19:36:46","modified_gmt":"2014-06-17T17:36:46","slug":"mirianna-masella2","status":"inherit","type":"attachment","link":"https:\/\/www.brundisium.net\/index.php\/sabato-21-miss-summer-salento-al-villaggio-acqua-in-le-foto\/mirianna-masella2\/","title":{"rendered":"Mirianna Masella2"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"class_list":["post-15679","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/06\/Mirianna-Masella2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"198\" height=\"300\" src=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/06\/Mirianna-Masella2-198x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/06\/Mirianna-Masella2-198x300.jpg 198w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/06\/Mirianna-Masella2.jpg 464w\" sizes=\"auto, (max-width: 198px) 100vw, 198px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":464,"height":700,"file":"2014\/06\/Mirianna-Masella2.jpg","sizes":{"thumbnail":{"file":"Mirianna-Masella2-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/06\/Mirianna-Masella2-150x150.jpg"},"medium":{"file":"Mirianna-Masella2-198x300.jpg","width":198,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/06\/Mirianna-Masella2-198x300.jpg"},"blog-posts":{"file":"Mirianna-Masella2-270x200.jpg","width":270,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/06\/Mirianna-Masella2-270x200.jpg"},"portfolio_img_th":{"file":"Mirianna-Masella2-300x400.jpg","width":300,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/06\/Mirianna-Masella2-300x400.jpg"},"single_posts":{"file":"Mirianna-Masella2-464x600.jpg","width":464,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/06\/Mirianna-Masella2-464x600.jpg"},"home-slide":{"file":"Mirianna-Masella2-464x350.jpg","width":464,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/06\/Mirianna-Masella2-464x350.jpg"},"bg_slider":{"file":"Mirianna-Masella2-112x70.jpg","width":112,"height":70,"mime_type":"image\/jpeg","source_url":"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/06\/Mirianna-Masella2-112x70.jpg"},"wp-cpl-post-thumb":{"file":"Mirianna-Masella2-60x60.jpg","width":60,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/06\/Mirianna-Masella2-60x60.jpg"},"wp-cpl-sc-thumb":{"file":"Mirianna-Masella2-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/06\/Mirianna-Masella2-150x150.jpg"},"full":{"file":"Mirianna-Masella2.jpg","width":464,"height":700,"mime_type":"image\/jpeg","source_url":"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/06\/Mirianna-Masella2.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":15671,"source_url":"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/06\/Mirianna-Masella2.jpg","_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/15679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=15679"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":15671,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/15671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}