{"id":100639,"date":"2017-04-10T16:57:40","date_gmt":"2017-04-10T14:57:40","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=100639"},"modified":"2017-04-12T14:48:50","modified_gmt":"2017-04-12T12:48:50","slug":"la-msc-musica-a-brindisi-in-sei-mesi-portera-100mila-turisti","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/la-msc-musica-a-brindisi-in-sei-mesi-portera-100mila-turisti\/","title":{"rendered":"La MSC Musica a Brindisi: in sei mesi porter\u00e0 100mila turisti"},"content":{"rendered":"<p>\u201cOggi con l&#8217;arrivo di MSC Musica inizia ufficialmente l&#8217;estate 2017 di MSC Crociere a Brindisi che continuer\u00e0 per 30 settimane consecutive fino alla fine di ottobre&#8221; ha affermato Leonardo Massa. \u201cOgni luned\u00ec la citt\u00e0 sar\u00e0 visitabile da pi\u00f9 di 3.000 turisti che scendono dalla nave o che intendono iniziare la settimana di vacanza in crociera. In tutta la stagione estiva i crocieristi portati a Brindisi da MSC Crociere saranno circa 100.000, generando una ricaduta economica di sicuro impatto per il territorio. Ma questa \u00e8 anche una grande opportunit\u00e0 per far conoscere ai nostri crocieristi le bellezze turistiche e culturali di questa citt\u00e0 con l\u2019obiettivo di farli tornare in futuro per una nuova vacanza pi\u00f9 lunga, utilizzando quindi le crociere come volano per il turismo locale\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>All\u2019inizio della cerimonia a bordo della nave \u00e8 intervenuta per un breve saluto la sindaca di Brindisi Angela Carluccio. Successivamente il Comandante della nave Vincenzo Bono insieme a Leonardo Massa ha chiamato sul palco le massime autorit\u00e0 presenti per il tradizionale scambio dei crest. Tra i rappresentanti delle istituzioni erano presenti il Prefetto Annunziato Vard\u00e8, il Presidente della Provincia Maurizio Bruno, il Direttore Regionale dei Vigili del Fuoco Salvatore Span\u00f2, il Questore di Brindisi Maurizio Masciopinto, il Comandante provinciale dei Carabinieri Nicola Conforti, il neo Presidente dell\u2019Autorit\u00e0 di Sistema Portuale del Mare Adriatico Meridionale Ugo Patroni Griffi che \u00e8 subentrato quindi al Commissario straordinario dell\u2019Autorit\u00e0 Portuale di Brindisi Mario Valente, anche egli a bordo. C\u2019erano anche il Comandante della Capitaneria di porto Salvatore Minervino, il Comandante della Guardia di Finanza Tiziano La Grua, il Capo del Corpo Piloti Pantaleo Morolla, il Capo del Gruppo ormeggiatori Nicola Greco, il Presidente dell\u2019International Propeller Clubs Umberto Masucci, il Presidente di Confindustria Giuseppe Marin\u00f2, il sindaco di Ostuni Gianfranco Coppola, il Presidente dell\u2019Asi Domenico Bianco, l\u2019Assessore del Comune di Mesagne Antonio Marotta e l\u2019agente marittimo dell\u2019agenzia Zaccaria &amp; Company Giuseppe Gorgoni.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Successivamente ha preso la parola il questore Masciopinto che, in onore del 165\u00b0 Anniversario dalla fondazione della Polizia di Stato, ha premiato il personale in quiescenza della Questura di Brindisi.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La giornata di festa si \u00e8 conclusa con una visita della nave durante la quale gli ospiti hanno potuto apprezzare l\u2019eleganza dei numerosi spazi pubblici della nave, dal teatro di bordo al grande ponte piscine che dominava la citt\u00e0 di Brindisi.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Quello di oggi non \u00e8 il primo approdo in assoluto di MSC Crociere a Brindisi, infatti gi\u00e0 durante tutta l\u2019estate del 2015 era stata posizionata MSC Magnifica, con un ottimo riscontro da parte dei crocieristi che hanno visitato la citt\u00e0 anche grazie all\u2019impegno delle istituzioni locali che sono riuscite a rendere possibile per la prima volta l\u2019attracco di una nave di queste dimensioni nel porto interno, offrendo l\u2019opportunit\u00e0 ai crocieristi di sbarcare e trovarsi subito nel centro storico cittadino.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Durante la tappa a Brindisi, MSC Crociere propone ai propri crocieristi un\u2019ampia scelta di escursioni, a partire dal giro panoramico della citt\u00e0 in pullman con una sosta anche alla chiesa di Santa Maria del Casale, classificata come monumento nazionale dal 1875. L\u2019itinerario dell\u2019escursione include anche la Chiesa di San Giovanni al Sepolcro, definita battistero per la sua forma circolare, l\u2019area archeologica di San Pietro degli Schiavoni che presenta elementi dell\u2019antica citt\u00e0 romana e il Teatro Verdi, inaugurato nel dicembre del 2006. Le altre escursioni offrono la possibilit\u00e0, per chi lo desidera, di visitare anche Lecce, Ostuni o Alberobello.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019itinerario della nave prevede 7 scali in 7 giorni per valorizzare al meglio ogni momento della vacanza, andando ogni giorno alla scoperta di un nuovo luogo. Una volta partita da Brindisi, la nave accompagner\u00e0 i viaggiatori a Katakolon, localit\u00e0 costiera greca sulla baia di Agios Andreas, a soli 20 km di distanza dall\u2019antica Olimpia, uno dei pi\u00f9 grandi siti archeologici della Grecia<br \/>\nMercoled\u00ec si giunger\u00e0 a Santorini, una delle mete turistiche estive pi\u00f9 apprezzate del Mediterraneo, dove il mare \u00e8 dominato da brulle scogliere vulcaniche alte centinaia di metri.<br \/>\nIl giorno successivo MSC Musica arriver\u00e0 ad Atene, dove chi non c\u2019\u00e8 mai stato vorr\u00e0 sicuramente visitare l\u2019Acropoli coronata dalle imponenti rovine del Partenone, che domina l\u2019intera citt\u00e0.<br \/>\nL\u2019ultima tappa greca sar\u00e0 Corf\u00f9, isola del mar Ionio. Una volta scesi a terra ci si trover\u00e0 nei quartieri antichi caratterizzati da vicoli stretti e alti che nascondono gli elementi architettonici pi\u00f9 belli di Corf\u00f9. Gli spiriti pi\u00f9 avventurosi potranno scegliere il safari in Jeep per andare alla scoperta del paesaggio e dei paesini incantevoli presenti sull\u2019isola.<br \/>\nLasciata Corf\u00f9 si partir\u00e0 alla volta di Kotor, dove sar\u00e0 possibile visitare la citt\u00e0 medievale di Cattaro, senza dubbio il gioiello del Montenegro. Le mura della citt\u00e0 racchiudono un dedalo di stradine e numerose chiese storiche che sono la parte pi\u00f9 affascinante di questa destinazione, ma anche il percorso della nave all\u2019interno della baia di Risano delle Bocche di Cattaro sar\u00e0 di sicuro uno spettacolo indimenticabile.<br \/>\nPrima di rientrare a Brindisi la nave far\u00e0 un\u2019ultima tappa a Venezia, citt\u00e0 unica al mondo che non finisce mai di stupire anche i turisti pi\u00f9 assidui.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MSC Musica, unit\u00e0 in grado di ospitare 3.200 passeggeri e con una stazza lorda di 92.409 tonnellate, \u00e8 una nave sorprendente, caratterizzata da un design raffinato e dalle forme sinuose. A bordo \u00e8 disponibile un\u2019ampia offerta di intrattenimento in grado di soddisfare i viaggiatori di tutte le et\u00e0. Nel grande teatro di bordo, ad esempio, \u00e8 possibile assistere a un emozionante spettacolo ogni sera diverso. Anche l\u2019offerta gastronomica \u00e8 estremamente ricca grazie ai numerosi ristoranti, bar e lounge presenti a bordo, compreso il grande buffet aperto 20 ore al giorno.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MSC Crociere, compagnia del Gruppo MSC, \u00e8 leader di mercato in Europa, Mediterraneo compreso, in Sud America e in Sud Africa. Naviga tutto l\u2019anno nel Mediterraneo e nei Caraibi offrendo itinerari stagionali anche nel Nord Europa, Oceano Atlantico, Antille Francesi, Sud America, Sud Africa, Abu Dhabi, Dubai e Sir Bani Yas.<br \/>\nL&#8217;esperienza MSC Crociere trae ispirazione dal lato elegante del Mediterraneo per creare emozioni uniche e indimenticabili per i viaggiatori, attraverso la scoperta di culture, bellezze e sapori di tutto il mondo. La sua flotta si compone di 12 moderne navi: MSC Preziosa, MSC Divina, MSC Splendida, MSC Fantasia, MSC Magnifica, MSC Poesia, MSC Orchestra, MSC Musica, MSC Sinfonia, MSC Armonia, MSC Opera e MSC Lirica.<br \/>\nNel 2014 MSC Crociere ha avviato un nuovo piano industriale per sostenere la seconda fase della sua crescita attraverso l&#8217;ordine di due navi di generazione Meraviglia e altre due di generazione Seaside (pi\u00f9 un\u2019opzione di una terza unit\u00e0) e a febbraio del 2016 ha confermato l\u2019opzione esistente per la costruzione di altre due navi Meraviglia Plus con una capacit\u00e0 passeggeri ancora maggiore. Nell\u2019aprile 2016 \u00e8 stata annunciata la firma di una lettera d\u2019intenti per la costruzione di quattro ulteriori navi dotate delle pi\u00f9 evolute tecnologie e di propulsori alimentati a GNL. Il valore complessivo del nuovo piano industriale sale quindi a 9 miliardi di euro e di conseguenza, tra il 2017 e il 2026, entreranno in servizio 11 nuove navi di ultima generazione. La Compagnia \u00e8 il primo brand crocieristico globale ad aver sviluppato un piano di investimenti di tali dimensioni che copre un orizzonte temporale di oltre dieci anni, a partire dal 2014 fino al 2026.<\/p>\n<p>&nbsp;<br \/>\nMSC Crociere sente una profonda responsabilit\u00e0 verso l\u2019ambiente in cui opera ed \u00e8 stata la prima compagnia a ricevere il riconoscimento \u201c7 Golden Pearls\u201d da Bureau Veritas per il suo alto livello di gestione e tutela ambientale. Nel 2009 MSC Crociere ha iniziato una duratura partnership con UNICEF, per sostenere diversi programmi di aiuto rivolti ai bambini di tutto il mondo. Fino ad oggi MSC Crociere ha raccolto pi\u00f9 di 5 milioni di euro grazie a donazioni volontarie degli ospiti a bordo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>COMUNICATO STAMPA MSC CROCIERE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cOggi con l&#8217;arrivo di MSC Musica inizia ufficialmente l&#8217;estate 2017 di MSC Crociere a Brindisi che continuer\u00e0 per 30 settimane consecutive fino alla fine di ottobre&#8221; ha affermato Leonardo Massa. \u201cOgni luned\u00ec la citt\u00e0 sar\u00e0 visitabile da pi\u00f9 di 3.000 turisti che scendono dalla nave o che intendono iniziare la settimana di vacanza in crociera. In tutta la stagione estiva i crocieristi portati a Brindisi da MSC Crociere saranno circa 100.000, generando una ricaduta economica di sicuro impatto per il territorio. Ma questa \u00e8 anche una grande opportunit\u00e0 per far conoscere ai nostri crocieristi le bellezze turistiche e culturali di questa citt\u00e0 con l\u2019obiettivo di farli tornare in futuro per una nuova vacanza pi\u00f9 lunga, utilizzando quindi le crociere come volano per il turismo locale\u201d. &nbsp; &nbsp; All\u2019inizio della cerimonia a bordo della nave \u00e8 intervenuta per un breve saluto la sindaca di Brindisi Angela Carluccio. Successivamente il Comandante della nave Vincenzo Bono insieme a Leonardo Massa ha chiamato sul palco le massime autorit\u00e0 presenti per il tradizionale scambio dei&#8230;<\/p>\n","protected":false},"author":2,"featured_media":100640,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1164,3802],"class_list":["post-100639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-crociere","tag-msc-musica"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/100639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=100639"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/100639\/revisions"}],"predecessor-version":[{"id":100641,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/100639\/revisions\/100641"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/100640"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=100639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=100639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=100639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}