{"id":100799,"date":"2017-04-12T10:20:02","date_gmt":"2017-04-12T08:20:02","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=100799"},"modified":"2017-04-12T10:00:16","modified_gmt":"2017-04-12T08:00:16","slug":"abbandono-di-rifiuti-parte-il-servizio-di-vigilanza-antincendio-boschivo-e-ambientale","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/abbandono-di-rifiuti-parte-il-servizio-di-vigilanza-antincendio-boschivo-e-ambientale\/","title":{"rendered":"Abbandono di rifiuti: parte il servizio di vigilanza antincendio boschivo e ambientale"},"content":{"rendered":"<p>Da domenica 9 aprile 2017 l\u2019Associazione di Volontariato \u201cKailia\u201d, nell\u2019ambito della Convenzione stipulata con il Comune di Ceglie Messapica,  ha dato inizio ad una attivit\u00e0 volta a supportare l\u2019Amministrazione Comunale per l\u2019antincendio boschivo (AIB) e la vigilanza ambientale.<br \/>\nInoltre i volontari dell\u2019Associazione \u201cKailia\u201d, utilizzando l\u2019auto del Servizio di Protezione Civile Comunale, percorreranno il nostro territorio, ed in particolare l\u2019agro, segnalando, immediatamente, alle Forze dell\u2019Ordine (Polizia Locale, Corpo Forestale e NOE) coloro che effettuano l\u2019abbandono indiscriminato di rifiuti,  affinch\u00e9 si attivino per infliggere le relative sanzioni amministrative e penali.<br \/>\nL\u2019Amministrazione Comunale, con questa azione concreta, unita a numerosi altri interventi che si stanno attivando, intende proteggere e tutelare la bellezza del nostro territorio, rendendo la vita difficile agli incivili, investendo ulteriormente sulla sensibilizzazione ambientale e la promozione delle buone pratiche e di uno stile di vita sostenibile.<\/p>\n<p>C.S. COMUNE DI CEGLIE MESSAPICA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da domenica 9 aprile 2017 l\u2019Associazione di Volontariato \u201cKailia\u201d, nell\u2019ambito della Convenzione stipulata con il Comune di Ceglie Messapica, ha dato inizio ad una attivit\u00e0 volta a supportare l\u2019Amministrazione Comunale per l\u2019antincendio boschivo (AIB) e la vigilanza ambientale. Inoltre i volontari dell\u2019Associazione \u201cKailia\u201d, utilizzando l\u2019auto del Servizio di Protezione Civile Comunale, percorreranno il nostro territorio, ed in particolare l\u2019agro, segnalando, immediatamente, alle Forze dell\u2019Ordine (Polizia Locale, Corpo Forestale e NOE) coloro che effettuano l\u2019abbandono indiscriminato di rifiuti, affinch\u00e9 si attivino per infliggere le relative sanzioni amministrative e penali. L\u2019Amministrazione Comunale, con questa azione concreta, unita a numerosi altri interventi che si stanno attivando, intende proteggere e tutelare la bellezza del nostro territorio, rendendo la vita difficile agli incivili, investendo ulteriormente sulla sensibilizzazione ambientale e la promozione delle buone pratiche e di uno stile di vita sostenibile. C.S. COMUNE DI CEGLIE MESSAPICA<\/p>\n","protected":false},"author":2,"featured_media":100800,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[852,577,3920],"class_list":["post-100799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-abbandono-rifiuti","tag-ceglie","tag-servizio-vigilanza"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/100799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=100799"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/100799\/revisions"}],"predecessor-version":[{"id":100801,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/100799\/revisions\/100801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/100800"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=100799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=100799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=100799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}