{"id":100885,"date":"2017-04-12T20:35:26","date_gmt":"2017-04-12T18:35:26","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=100885"},"modified":"2017-04-12T20:35:26","modified_gmt":"2017-04-12T18:35:26","slug":"bbc-il-sottosegretario-cassano-segnala-un-curriculum-in-autorita-portuale-si-faccia-chiarezza","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/bbc-il-sottosegretario-cassano-segnala-un-curriculum-in-autorita-portuale-si-faccia-chiarezza\/","title":{"rendered":"BBC: &#8220;Il Sottosegretario Cassano segnala un curriculum in Autorit\u00e0 Portuale, si faccia chiarezza&#8221;"},"content":{"rendered":"<p>Abbiamo appreso dalla stampa che dalla casella di posta elettronica istituzionale della Segreteria del Senatore Massimo Cassano, Sottosegretario al Ministero del Lavoro, \u00e8 stata inviata una mail all\u2019Autorit\u00e0 Portuale di Brindisi per sottoporre all\u2019attenzione dell\u2019Autorit\u00e0 un curriculum vitae.<\/p>\n<p>&nbsp;<\/p>\n<p>E\u2019 una classica raccomandazione? No si affretta a smentire il Sottosegretario Cassano. E\u2019 un atto di cortesia per un cittadino che neanche conosco e che mi ha chiesto un piacere, uno dei tanti dalle pensioni ai voucher e noi ci limitiamo ad inoltrare.<\/p>\n<p>&nbsp;<\/p>\n<p>Dichiarazioni incommentabili e che stridono con il buon senso . In Italia si passa cos\u00ec dal \u201c a mia insaputa\u201d alla \u201c mail con curriculum per cortesia\u201d cos\u00ec come se niente fosse.<\/p>\n<p>&nbsp;<\/p>\n<p>Chiediamo invece di sapere dall\u2019Autorit\u00e0 Portuale di chi sia il curruculum che \u00e8 stato segnalato, in particolare in questo momento che il nuovo Presidente deve nominare il Segretario Generale e si attendono le indicazioni per il nuovo comitato di gestione.<\/p>\n<p>&nbsp;<\/p>\n<p>Il Nuovo Presidente Patroni Griffi avvii in modo chiaro e trasparente le sue relazioni nel territorio e faccia chiarezza sul nominativo impegnandosi a non nominare la persona segnalata dal Sottosegretario Cassano.<\/p>\n<p>&nbsp;<\/p>\n<p>Evidentemente al Ministero del Lavoro per politiche attive intendono, dopo le partite di calcetto del Ministro Poletti, anche le mail di segnalazione del Sottosegretario Cassano. I cittadini sono avvisati inviate tutti una mail al Senatore Cassano.<\/p>\n<p>&nbsp;<\/p>\n<p>Brindisi Bene Comune<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abbiamo appreso dalla stampa che dalla casella di posta elettronica istituzionale della Segreteria del Senatore Massimo Cassano, Sottosegretario al Ministero del Lavoro, \u00e8 stata inviata una mail all\u2019Autorit\u00e0 Portuale di Brindisi per sottoporre all\u2019attenzione dell\u2019Autorit\u00e0 un curriculum vitae. &nbsp; E\u2019 una classica raccomandazione? No si affretta a smentire il Sottosegretario Cassano. E\u2019 un atto di cortesia per un cittadino che neanche conosco e che mi ha chiesto un piacere, uno dei tanti dalle pensioni ai voucher e noi ci limitiamo ad inoltrare. &nbsp; Dichiarazioni incommentabili e che stridono con il buon senso . In Italia si passa cos\u00ec dal \u201c a mia insaputa\u201d alla \u201c mail con curriculum per cortesia\u201d cos\u00ec come se niente fosse. &nbsp; Chiediamo invece di sapere dall\u2019Autorit\u00e0 Portuale di chi sia il curruculum che \u00e8 stato segnalato, in particolare in questo momento che il nuovo Presidente deve nominare il Segretario Generale e si attendono le indicazioni per il nuovo comitato di gestione. &nbsp; Il Nuovo Presidente Patroni Griffi avvii in modo chiaro e trasparente le sue&#8230;<\/p>\n","protected":false},"author":2,"featured_media":3280,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[215,3843,872],"class_list":["post-100885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-bbc","tag-cellie","tag-rossi"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/100885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=100885"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/100885\/revisions"}],"predecessor-version":[{"id":100887,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/100885\/revisions\/100887"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/3280"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=100885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=100885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=100885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}