{"id":100920,"date":"2017-04-13T13:09:00","date_gmt":"2017-04-13T11:09:00","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=100920"},"modified":"2017-04-13T13:09:00","modified_gmt":"2017-04-13T11:09:00","slug":"under-16-laurora-brindisi-vince-il-campionato-regionale-di-eccellenza","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/under-16-laurora-brindisi-vince-il-campionato-regionale-di-eccellenza\/","title":{"rendered":"Under 16: l&#8217;Aurora Brindisi vince il campionato regionale di eccellenza"},"content":{"rendered":"<p>La squadra Under 16 dell\u2019AURORA Brindisi conquista il titolo di Campione regionale nel campionato d\u2019Eccellenza, battendo in finale il Cus Bari per 83 a 72.<\/p>\n<p>Il gruppo dei ragazzi nati nel 2001 si confermano i migliori in Puglia bissando il titolo U15 vinto lo scorso anno.<\/p>\n<p>&nbsp;<\/p>\n<p>La vittoria nelle Final Four per i ragazzi allenati da\u00a0Gianfranco Patera,\u00a0corona una stagione 2016-2017 da incorniciare: 18 vittorie su 18 partite; 1571 punti segnati contro 1003 subiti; 92,4 punti segnati di media; 59 punti subiti di media e si qualificano\u00a0per il successivo spareggio per la fase interzonale che si disputer\u00e0 il 7 Maggio\u00a0in Molise contro la quarta classificata del Lazio.<\/p>\n<p>&nbsp;<\/p>\n<p>Questo prestigioso risultato \u00e8 il\u00a0riconoscimento oggettivo per il lavoro svolto da tutto lo\u00a0staff tecnico e dirigenziale, ma il plauso maggiore va soprattutto alla dedizione, determinazione e passione di tutti i ragazzi scesi in campo.<\/p>\n<p>&nbsp;<\/p>\n<p>Questi giovani atleti sono stati i veri protagonisti a cominciare da Andrea Travaglini, che per un infortunio non ha potuto dare il suo contributo, a tutto il gruppo dei 2002, recenti vincitori del titolo U15 Eccellenza che durante l&#8217;anno si sono alternati a cominciare da Umberto Barbato, Davide Cesaria, Marco Manisi e Matteo Serse e tra gli artefici delle finali Andrea Arnaldo, Simone Chirizzi, Micky Laquintana e Fabio Min\u00f2.<\/p>\n<p>&nbsp;<\/p>\n<p>Il gruppo dei 2001 \u00e8 costituito dal nucleo storico con capitan Gabriele Marra e Federico Fonseca, che gi\u00e0 dall\u2019et\u00e0 di sei anni hanno iniziato a giocare nel centro di minibasket dell\u2019Aurora, Matteo Cantoro, Antonio Chirizzi, Gabriele Polifemo e Donato Tedeschi ai quali quest&#8217;anno si sono aggiunti Antonio Massagli e Claudio Monaco.<\/p>\n<p>&nbsp;<\/p>\n<p>Dal Minibasket ai campionati senior \u00e8 un iter comune per la maggioranza dei ragazzi cresciuti in Aurora: ragazzi che continuano a giocare in campionati importanti, vicino o lontano da Brindisi, come Angelini e Fontana, per citarne qualcuno, che hanno intrapreso gli studi universitari con profitto o che si sono avviati in ambiente lavorativo.\u00a0Ed \u00e8 questa crescita a 360\u00b0 il fulcro del percorso formativo che la societ\u00e0 brindisina che compie quest\u2019anno il 10\u00b0 Anno di vita. L\u2019integrazione della formazione individuale e di attivit\u00e0 agonistica di eccellenza viene attestata dai progressi individuali e dai successi di squadra.<\/p>\n<p>&nbsp;<\/p>\n<p>Il titolo vinto dagli Under16 \u00e8 il DICIOTTESIMO alloro regionale che in questi dieci anni l\u2019Aurora pu\u00f2 vantare nel suo palmar\u00e8s. La programmazione e il lavoro danno i loro risultati a prescindere dalle vittorie; basti pensare che in quest\u2019annata sportiva l\u2019Aurora \u00e8 e sar\u00e0 presente in tutte le Final Four dei campionati regionali d&#8217;Eccellenza o d\u2019Elite, infatti oltre alla vittoria con gli Under16 e Under 15 Eccellenza l&#8217;Aurora ha raggiunto le Final Four regionali in tutte le categorie: U20,\u00a0U18 Eccellenza ed Elite, U14 \u00e9lite e U13 \u00e9lite. il segreto uno solo: la passione che alimenta il lavoro di tutti gli istruttori e dirigenti.<\/p>\n<p>&nbsp;<\/p>\n<p>Da domani si torna a lavorare in palestra per preparare al meglio l\u2019appuntamento con il durissimo spareggio interzonale ma per adesso un \u201cBravo\u201d a tutti i ragazzi per il raggiungimento di questo prestigioso risultato.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>AURORA BRINDISI<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La squadra Under 16 dell\u2019AURORA Brindisi conquista il titolo di Campione regionale nel campionato d\u2019Eccellenza, battendo in finale il Cus Bari per 83 a 72. Il gruppo dei ragazzi nati nel 2001 si confermano i migliori in Puglia bissando il titolo U15 vinto lo scorso anno. &nbsp; La vittoria nelle Final Four per i ragazzi allenati da\u00a0Gianfranco Patera,\u00a0corona una stagione 2016-2017 da incorniciare: 18 vittorie su 18 partite; 1571 punti segnati contro 1003 subiti; 92,4 punti segnati di media; 59 punti subiti di media e si qualificano\u00a0per il successivo spareggio per la fase interzonale che si disputer\u00e0 il 7 Maggio\u00a0in Molise contro la quarta classificata del Lazio. &nbsp; Questo prestigioso risultato \u00e8 il\u00a0riconoscimento oggettivo per il lavoro svolto da tutto lo\u00a0staff tecnico e dirigenziale, ma il plauso maggiore va soprattutto alla dedizione, determinazione e passione di tutti i ragazzi scesi in campo. &nbsp; Questi giovani atleti sono stati i veri protagonisti a cominciare da Andrea Travaglini, che per un infortunio non ha potuto dare il suo contributo, a tutto il&#8230;<\/p>\n","protected":false},"author":2,"featured_media":100921,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[1447],"class_list":["post-100920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket","tag-aurora-brindisi"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/100920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=100920"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/100920\/revisions"}],"predecessor-version":[{"id":100922,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/100920\/revisions\/100922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/100921"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=100920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=100920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=100920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}