{"id":101453,"date":"2017-04-21T12:51:42","date_gmt":"2017-04-21T10:51:42","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=101453"},"modified":"2017-04-21T14:39:48","modified_gmt":"2017-04-21T12:39:48","slug":"patroni-griffi-subito-lorganismo-di-partenariato-della-risorsa-mare","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/patroni-griffi-subito-lorganismo-di-partenariato-della-risorsa-mare\/","title":{"rendered":"Patroni Griffi: &#8220;subito l\u2019Organismo di partenariato della risorsa mare&#8221;"},"content":{"rendered":"<p>Costituire celermente l\u2019Organismo di partenariato della risorsa mare. Con questo obiettivo il presidente dell\u2019Autorit\u00e0 di Sistema Portuale del Mare Adriatico Meridionale, prof. Ugo Patroni Griffi, ha inviato ai soggetti interessati una richiesta di designazione del nominativo del rappresentante che far\u00e0 parte dell\u2019ente consultore dei privati. \u00c8 una delle novit\u00e0 della riforma delle Autorit\u00e0 Portuali che affiancher\u00e0 il \u201cComitato di gestione\u201d, che resta l\u2019unico ente deliberatore e decisorio (composto da Regione, Comune\/Citt\u00e0 Metropolitana, Capitaneria).<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019Organismo sar\u00e0 cos\u00ec composto: un rappresentante per ognuna delle seguenti categorie professionali: armatori (indicato da Confitarma e Fedarlinea), industriali (nominato da Confindustria e Confcommercio); poi un rappresentante ciascuno per i seguenti operatori: imprese portuali\/concessionarie di banchine, spedizionieri, operatori logistici, operatori ferroviari, agenti marittimi, autotrasportatori, operatori del turismo. Infine, tre rappresentanti per i sindacati (FILT\u2013CGIL, FIT-CISL, UIL-TRASPORTI). Tra i componenti, anche il comandante del porto e Ugo Patroni Griffi che lo presieder\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>Entro 7 giorni le associazioni dovranno indicare il nominativo del loro rappresentante. L\u2019Organismo durer\u00e0 in carica quattro anni; referente il segretario generale che stabilir\u00e0 le modalit\u00e0 per l&#8217;espletamento delle sue funzioni.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019Organismo, come gi\u00e0 anticipato, non avr\u00e0 poteri vincolanti per l&#8217;AdSP ma solo \u00abfunzioni consultive\u00bb. Potr\u00e0, comunque, esprimere pareri sugli aspetti chiave delle attivit\u00e0 amministrative di un porto: adozione del piano regolatore portuale e del piano operativo triennale, il bilancio preventivo e consuntivo. Avr\u00e0 facolt\u00e0, inoltre, di esprimere pareri su qualsiasi questione che sia sottoposta dal presidente Patroni Griffi, o su richiesta della maggioranza dei componenti.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cE\u2019 necessario- commenta il presidente- procedere speditamente alla costituzione degli Organi della nuova Autorit\u00e0 di Sistema Portuale del Mare Adriatico Meridionale al fine di consentire all\u2019Ente di iniziare ad operare s\u00ec da incrementare l\u2019efficienza degli scali in una strategia di multi porto.\u201d<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #365f91;\"><span style=\"font-family: Baskerville Old Face, serif;\"><span style=\"font-size: large;\"><b>Autorit\u00e0 di Sistema Portuale del Mare Adriatico Meridionale<br \/>\n<\/b><\/span><\/span><\/span><span style=\"color: #365f91;\"><span style=\"font-family: Baskerville Old Face, serif;\"><span style=\"font-size: small;\"><i>Porti di Bari, Brindisi, Manfredonia, Barletta, Monopoli<\/i><\/span><\/span><\/span><i> <\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Costituire celermente l\u2019Organismo di partenariato della risorsa mare. Con questo obiettivo il presidente dell\u2019Autorit\u00e0 di Sistema Portuale del Mare Adriatico Meridionale, prof. Ugo Patroni Griffi, ha inviato ai soggetti interessati una richiesta di designazione del nominativo del rappresentante che far\u00e0 parte dell\u2019ente consultore dei privati. \u00c8 una delle novit\u00e0 della riforma delle Autorit\u00e0 Portuali che affiancher\u00e0 il \u201cComitato di gestione\u201d, che resta l\u2019unico ente deliberatore e decisorio (composto da Regione, Comune\/Citt\u00e0 Metropolitana, Capitaneria). &nbsp; L\u2019Organismo sar\u00e0 cos\u00ec composto: un rappresentante per ognuna delle seguenti categorie professionali: armatori (indicato da Confitarma e Fedarlinea), industriali (nominato da Confindustria e Confcommercio); poi un rappresentante ciascuno per i seguenti operatori: imprese portuali\/concessionarie di banchine, spedizionieri, operatori logistici, operatori ferroviari, agenti marittimi, autotrasportatori, operatori del turismo. Infine, tre rappresentanti per i sindacati (FILT\u2013CGIL, FIT-CISL, UIL-TRASPORTI). Tra i componenti, anche il comandante del porto e Ugo Patroni Griffi che lo presieder\u00e0. &nbsp; Entro 7 giorni le associazioni dovranno indicare il nominativo del loro rappresentante. L\u2019Organismo durer\u00e0 in carica quattro anni; referente il segretario generale che stabilir\u00e0&#8230;<\/p>\n","protected":false},"author":2,"featured_media":99269,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[2384,3945],"class_list":["post-101453","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-authority","tag-patroni-griffi"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/101453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=101453"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/101453\/revisions"}],"predecessor-version":[{"id":101454,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/101453\/revisions\/101454"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/99269"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=101453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=101453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=101453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}