{"id":102731,"date":"2017-05-05T16:46:49","date_gmt":"2017-05-05T14:46:49","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=102731"},"modified":"2017-05-05T17:52:52","modified_gmt":"2017-05-05T15:52:52","slug":"approvata-la-mozione-sulla-stabilizzazione-dei-vigili-del-fuoco-discontinui","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/approvata-la-mozione-sulla-stabilizzazione-dei-vigili-del-fuoco-discontinui\/","title":{"rendered":"Approvata la mozione sulla stabilizzazione dei Vigili del Fuoco discontinui"},"content":{"rendered":"<p>E\u2019 stata approvata all\u2019unanimit\u00e0 dal Consiglio regionale una mozione sottoscritta da consiglieri di maggioranza e di opposizione (Cosimo Borraccino, Napoleone Cera, Vincenzo Colonna, Michele Mazzarano, Giuseppe Romano, Paolo Pellegrino, Sabino Zinni, Antonella Laricchia, Gianluca Bozzetti, Andrea Caroppo, Nicola Marmo), con cui si impegna il Presidente della Regione Puglia e la Giunta regionale \u201cad adoperarsi presso il Governo centrale e il Parlamento della Repubblica affinch\u00e9 vengano poste in essere tutte le iniziative necessarie, sul piano normativo e regolamentare, per consentire la stabilizzazione dei Vigili del Fuoco \u201cdiscontinui\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Di seguito il testo della mozione.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Premesso che<\/em><\/p>\n<p>&nbsp;<br \/>\n<em> \u2022 L\u2019art. 1 del Decreto Legislativo 8 marzo 2006, n. 139 stabilisce che \u201cIl Corpo nazionale dei Vigili del Fuoco \u00e8 una struttura dello Stato ad ordinamento civile, incardinata nel Ministero dell\u2019Interno \u2013 Dipartimento dei Vigili del Fuoco, del soccorso pubblico e della difesa civile, per mezzo della quale il Ministero dell\u2019Interno assicura, anche per la difesa civile, il servizio di soccorso pubblico e di prevenzione ed estinzione degli incendi su tutto il territorio nazionale, nonch\u00e9 lo svolgimento delle altre attivit\u00e0 assegnate al Corpo nazionale dalle leggi e dai regolamenti. Il Corpo nazionale \u00e8 componente fondamentale del servizio di protezione civile, ai sensi dell\u2019art. 11 della legge 24 febbraio 1992, n. 225\u201d;<\/em><\/p>\n<p>&nbsp;<br \/>\n<em> \u2022 Il Corpo dei Vigili del Fuoco, quindi, rappresenta un presidio insostituibile e fondamentale per la salvaguardia dei cittadini e del nostro Paese, e ha sempre svolto efficacemente, con impegno straordinario, alle attese della popolazione civile in tutti i compiti di prevenzione, vigilanza e soccorso tecnico urgente ai quali \u00e8 preposto per legge, rivelandosi spesso decisivo per garantire l\u2019incolumit\u00e0 e la salvezza di numerose vite umane, come accaduto anche di recente in occasione di drammatici eventi naturali;<\/em><\/p>\n<p>&nbsp;<br \/>\n<em> \u2022 Negli ultimi anni il Corpo nazionale dei Vigili del Fuoco ha dovuto far fronte alla progressiva diminuzione delle risorse finanziarie stanziate dallo Stato, sempre pi\u00f9 scarse, e a rilevantissime carenze di organico, riuscendo comunque, con uno sforzo encomiabile e straordinario, a rispondere efficacemente alle numerose richieste di intervento della popolazione per emergenze grandi o piccole, meritandosi cos\u00ec il rispetto, la stima e l\u2019affetto di tutti gli italiani;<\/em><br \/>\n<em> Considerato che<\/em><\/p>\n<p>&nbsp;<br \/>\n<em> \u2022 Il Corpo dei Vigili del Fuoco vede, da tempo, la presenza al suo interno di una rilevantissima componente di personale precario, composto da Vigili del fuoco cosiddetti \u201cdiscontinui\u201d che rappresentano, comunque, una risorsa imprescindibile del Corpo nazionale, senza dei quali i servizi in molti casi si paralizzerebbero e non sarebbe possibile rispondere con tempestivit\u00e0 alle richieste dei cittadini;<\/em><\/p>\n<p>&nbsp;<br \/>\n<em> \u2022 I Vigili del Fuoco cosiddetti \u201cdiscontinui\u201d sono privi di contratto a tempo indeterminato e non possono essere chiamati in servizio per pi\u00f9 di 14 giorni consecutivi e per pi\u00f9 di 160 giorni l\u2019anno;<\/em><\/p>\n<p>&nbsp;<br \/>\n<em> \u2022 Questi Vigili del Fuoco discontinui vengono frequentemente richiamati in servizio per far fronte alle croniche carenze di organico, garantendo sempre l\u2019operativit\u00e0 dei comandi e\/o integrando le squadre di intervento, venendo spesso utilizzati anche per svolgere attivit\u00e0 di ordinaria amministrazione;<\/em><\/p>\n<p>&nbsp;<br \/>\n<em> \u2022 La figura del Vigile del Fuoco discontinuo va, peraltro, distinta da quella dei Vigili del Fuoco volontari che svolgono la loro attivit\u00e0 nei distaccamenti volontari;<\/em><\/p>\n<p>&nbsp;<br \/>\n<em> \u2022 Nonostante la netta distinzione tra le due figure, le stesse vengono considerate entrambe come \u201cvolontarie\u201d, con la precisazione (contenuta all\u2019art. 6, comma 1, del decreto legislativo 8 marzo 2006, n. 139) che \u201cil personale volontario non \u00e8 legato da un rapporto di impiego all\u2019Amministrazione\u201d, escludendo cos\u00ec qualsiasi possibilit\u00e0 di incardinare tra i Vigili discontinui e il Ministero un rapporto di pubblico impiego;<\/em><\/p>\n<p>&nbsp;<br \/>\n<em> \u2022 La condizione di precariato all\u2019interno del Corpo nazionale dei Vigili del Fuoco riguarda, a livello nazionale, migliaia di persone e, nella nostra regione, interessa centinaia di operatori i quali, da anni, svolgono funzioni in tutto e per tutto equiparate a quelle svolte dai colleghi a tempo indeterminato, pur non avendo lo stesso trattamento giuridico e le stesse tutele;<\/em><\/p>\n<p>&nbsp;<br \/>\n<em> \u2022 Appare indispensabile adoperarsi presso il Governo centrale e il Parlamento della Repubblica per avviare un percorso che porti quanto prima alla stabilizzazione dei Vigili del Fuoco discontinui<\/em><\/p>\n<p>&nbsp;<br \/>\n<em> Tutto quanto premesso e considerato il Consiglio Regionale della Puglia<\/em><br \/>\n<em> Impegna il Presidente della Regione Puglia e la Giunta regionale ad adoperarsi presso il Governo centrale e il Parlamento della Repubblica affinch\u00e8 vengano poste in essere tutte le iniziative necessarie, sul piano normativo e regolamentare, per consentire la stabilizzazione dei Vigili del Fuoco \u201cdiscontinui\u201d.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>E\u2019 stata approvata all\u2019unanimit\u00e0 dal Consiglio regionale una mozione sottoscritta da consiglieri di maggioranza e di opposizione (Cosimo Borraccino, Napoleone Cera, Vincenzo Colonna, Michele Mazzarano, Giuseppe Romano, Paolo Pellegrino, Sabino Zinni, Antonella Laricchia, Gianluca Bozzetti, Andrea Caroppo, Nicola Marmo), con cui si impegna il Presidente della Regione Puglia e la Giunta regionale \u201cad adoperarsi presso il Governo centrale e il Parlamento della Repubblica affinch\u00e9 vengano poste in essere tutte le iniziative necessarie, sul piano normativo e regolamentare, per consentire la stabilizzazione dei Vigili del Fuoco \u201cdiscontinui\u201d. &nbsp; &nbsp; Di seguito il testo della mozione. &nbsp; Premesso che &nbsp; \u2022 L\u2019art. 1 del Decreto Legislativo 8 marzo 2006, n. 139 stabilisce che \u201cIl Corpo nazionale dei Vigili del Fuoco \u00e8 una struttura dello Stato ad ordinamento civile, incardinata nel Ministero dell\u2019Interno \u2013 Dipartimento dei Vigili del Fuoco, del soccorso pubblico e della difesa civile, per mezzo della quale il Ministero dell\u2019Interno assicura, anche per la difesa civile, il servizio di soccorso pubblico e di prevenzione ed estinzione degli incendi su tutto&#8230;<\/p>\n","protected":false},"author":2,"featured_media":11206,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[134],"class_list":["post-102731","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-vigili-del-fuoco"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/102731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=102731"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/102731\/revisions"}],"predecessor-version":[{"id":102733,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/102731\/revisions\/102733"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/11206"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=102731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=102731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=102731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}