{"id":103459,"date":"2017-05-13T11:51:48","date_gmt":"2017-05-13T09:51:48","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=103459"},"modified":"2017-05-14T18:45:42","modified_gmt":"2017-05-14T16:45:42","slug":"i-porti-pugliesi-al-al-transportlogistic-di-monaco-di-baviera","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/i-porti-pugliesi-al-al-transportlogistic-di-monaco-di-baviera\/","title":{"rendered":"I porti pugliesi al Transport&#038;Logistic di Monaco di Baviera"},"content":{"rendered":"<p>Anche una delegazione dell\u2019Autorit\u00e0 di Sistema Portuale dell\u2019Adriatico Meridionale \u00e8 stata presente alla Fiera Transport and Logistic di Monaco di Baviera, che si \u00e8 conclusa ieri nella citt\u00e0 tedesca.<\/p>\n<p>&nbsp;<\/p>\n<p>Tutti i porti compresi nelle circoscrizioni delle neo-istituite Autorit\u00e0 di Sistema Portuale hanno aderito alla manifestazione coordinata, come di consueto, dall\u2019Associazione dei Porti Italiani.<br \/>\nUn\u2019agenda fitta di incontri e visite per tutti i rappresentanti dei porti con diversi eventi organizzati sia nello stand istituzionale \u201cItaly \u2013 One Country, All the Logistics\u201d \u2013 che negli spazi dedicati ai forum e agli incontri.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La delegazione dell\u2019Autorit\u00e0 di Sistema Portuale dell\u2019Adriatico Meridionale, guidata dal segretario generale della soppressa Autorit\u00e0 portuale di Brindisi, amm. Salvatore Giuffr\u00e8, ha avuto l\u2019opportunit\u00e0 di svolgere numerosi incontri con possibili interlocutori futuri, rappresentando le peculiarit\u00e0 e le potenzialit\u00e0 che contraddistinguono e connotano i porti dell\u2019Adriatico meridionale.<br \/>\nNel corso della manifestazione \u00e8 stata altres\u00ec organizzata una tavola rotonda presieduta dal neo-Presidente di Assoporti Zeno D\u2019Agostino, alla quale hanno partecipato anche i presidenti Paolo Emilio Signorini e Sergio Prete, che hanno avuto modo di illustrare le novit\u00e0 della riforma portuale italiana e le necessit\u00e0 del settore. In platea a seguire la tavola rotonda, i Presidenti Carla Roncallo, Rodolfo Giampieri e Pino Musolino oltre al Segretario Generale Francesco Messineo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Marco Spinedi dell\u2019Interporto di Bologna e Alessandro Panaro di SRM, hanno poi illustrato i dati statistici ed economici riferiti alla portualit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>A margine della tavola rotonda D\u2019Agostino ha detto: \u201cL\u2019Italia \u00e8 un paese strategico per gli scambi commerciali. Adesso \u00e8 ora di fare sistema ed essere uniti. La promozione e la comunicazione devono diventare centrali nell\u2019azione di Assoporti. Occorre fare squadra sia quando ci si presenta sui mercati internazionali, sia quando si affrontano tutti quei temi che influiscono sull\u2019attivit\u00e0 quotidiana delle Autorit\u00e0 di Sistema Portuale e quindi sui porti.<br \/>\nSoltanto a titolo esemplificativo; il ruolo delle ferrovie in porto oppure il delicato tema delle concessioni demaniali e la loro regolazione.\u201d<\/p>\n<p>&nbsp;<\/p>\n<p>Voci unanimi sono arrivate anche dai successivi interventi con grande apprezzamento per l\u2019iniziativa dei porti italiani.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>COMUNICATO STAMPA ASSOPORTI<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anche una delegazione dell\u2019Autorit\u00e0 di Sistema Portuale dell\u2019Adriatico Meridionale \u00e8 stata presente alla Fiera Transport and Logistic di Monaco di Baviera, che si \u00e8 conclusa ieri nella citt\u00e0 tedesca. &nbsp; Tutti i porti compresi nelle circoscrizioni delle neo-istituite Autorit\u00e0 di Sistema Portuale hanno aderito alla manifestazione coordinata, come di consueto, dall\u2019Associazione dei Porti Italiani. Un\u2019agenda fitta di incontri e visite per tutti i rappresentanti dei porti con diversi eventi organizzati sia nello stand istituzionale \u201cItaly \u2013 One Country, All the Logistics\u201d \u2013 che negli spazi dedicati ai forum e agli incontri. &nbsp; &nbsp; La delegazione dell\u2019Autorit\u00e0 di Sistema Portuale dell\u2019Adriatico Meridionale, guidata dal segretario generale della soppressa Autorit\u00e0 portuale di Brindisi, amm. Salvatore Giuffr\u00e8, ha avuto l\u2019opportunit\u00e0 di svolgere numerosi incontri con possibili interlocutori futuri, rappresentando le peculiarit\u00e0 e le potenzialit\u00e0 che contraddistinguono e connotano i porti dell\u2019Adriatico meridionale. Nel corso della manifestazione \u00e8 stata altres\u00ec organizzata una tavola rotonda presieduta dal neo-Presidente di Assoporti Zeno D\u2019Agostino, alla quale hanno partecipato anche i presidenti Paolo Emilio Signorini e Sergio Prete,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":32099,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[4098],"class_list":["post-103459","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-autorita-di-sistema"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/103459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=103459"}],"version-history":[{"count":2,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/103459\/revisions"}],"predecessor-version":[{"id":103487,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/103459\/revisions\/103487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/32099"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=103459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=103459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=103459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}