{"id":104812,"date":"2017-05-27T09:16:02","date_gmt":"2017-05-27T07:16:02","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=104812"},"modified":"2017-05-30T16:46:14","modified_gmt":"2017-05-30T14:46:14","slug":"la-culla-delle-albe-mise-en-scene-con-il-maestro-uccio-biondi-torna-il-progetto-espositivo-map-a-brindisi","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/la-culla-delle-albe-mise-en-scene-con-il-maestro-uccio-biondi-torna-il-progetto-espositivo-map-a-brindisi\/","title":{"rendered":"La Culla delle Albe mise en sc\u00e8ne: con il maestro Uccio Biondi torna il progetto espositivo MAP a Brindisi"},"content":{"rendered":"<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/05\/Domenico-Uccio-Biondi-La-Culla-delle-Albe-.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-104814\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/05\/Domenico-Uccio-Biondi-La-Culla-delle-Albe--244x300.png\" alt=\"\" width=\"244\" height=\"300\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/05\/Domenico-Uccio-Biondi-La-Culla-delle-Albe--244x300.png 244w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/05\/Domenico-Uccio-Biondi-La-Culla-delle-Albe-.png 492w\" sizes=\"auto, (max-width: 244px) 100vw, 244px\" \/><\/a>Ideata e organizzata dall\u2019associazione culturale Arte Antica e Contemporanea \u201cLe Colonne\u201d e dalla spin off CRACC dell\u2019Universit\u00e0 del Salento, con la fattiva collaborazione culturale dell\u2019Associazione Amici dei Musei di Brindisi, dal 31 maggio e sino a tutto settembre le opere plastiche dell\u2019artista Biondi saranno esposte in una suggestiva mostra personale: \u201cLa Culla delle Albe mise en sc\u00e8ne\u201d<br \/>\nBiondi mette in scena la sua altopittura intitolata La Culla delle Albe, un\u2019idea di terra madre o matrigna a cui fanno riferimento delle maschere monocrome, poste su steli metallici, che vanno oltre la scultura per essere solo delle apparenze, delle \u201cfantasmine\u201d che occuperanno uno spazio per loro insolito quello della Fondazione Faldetta, con il suo carico di reperti archeologici, tra i siti culturali di eccellenza della citt\u00e0 e dell\u2019intera regione e con una invidiabile collocazione sul porto.<br \/>\nL\u2019iniziativa patrocinata dal Comune di Brindisi e sotto l\u2019egida scientifica del Dipartimento di Beni Culturali dell\u2019ateneo salentino, grazie allo sponsor \u201cIl Focolare. Residenza per gli anziani\u201d e i partner \u201cLeonardo Studio. Immagine &amp; comunicazione\u201d e l\u2019\u201cAzienda agricola Vincenzo Pugliese\u201d, propone un singolare abbinamento tra arte contemporanea e testimonianze archeologiche, due realt\u00e0 cronologicamente distanti ma non senza qualche analogia, se pensiamo alle maschere teatrali femminili raffigurate sul cratere a campana di produzione protoapula del IV secolo, attribuito alla Cerchia del Pittore di Tarpoley, pezzo forte della collezione Faldetta .<\/p>\n<p>&nbsp;<br \/>\nPer presentare l\u2019iniziativa \u00e8 prevista una conferenza stampa Luned\u00ec 29 maggio alle ore 11 presso la palazzina del Belvedere; con la padrona di casa Anna Cinti presidente dell\u2019associazione \u201cLe Colonne\u201d ne parleranno il curatore prof. Massimo Guastella, docente di Storia dell\u2019Arte Contemporanea dell\u2019Universit\u00e0 del Salento, Letizia Molfetta, editorial designer di CRACC srl, la dott.ssa Antonella Grassi responsabile Servizi culturali del Comune di Brindisi, la dott.ssa Franca Mariani presidente dell\u2019Associazione Amici dei Musei della Provincia di Brindisi, la dott.ssa Giovanna Rizzo coordinatore di struttura della casa di riposo \u201cIl Focolare\u201d, e i rappresentanti dei partner della mostra Claudio Fornaro, di Leonardo Studio, e Vincenzo Pugliese, dell\u2019Azienda Agricola Pugliese; inoltre \u00e8 prevista la presenza di Chiara Leuzzi che con Sara Stifani saranno le voci di \u201cApparenze\u201d la perfomance che inaugurer\u00e0 la mostra.<br \/>\nLa nostra missione, afferma Anna Cinti, ha l\u2019obiettivo \u201cdi stimolare la coscienza civica, promuovendo la Palazzina del Belvedere (sede della Collezione Archeologica) non solo come luogo di conservazione, ma anche come spazio dell\u2019incontro, del dibattito e della riflessione sulla contemporaneit\u00e0\u201d. Da qui il progetto di riportare nella citt\u00e0 adriatica la produzione artistica di una tra le pi\u00f9 interessanti personalit\u00e0 originarie di questo territorio, che mancava dalla scena brindisina dal 1988, anno della sua personale alla Galleria Multimedia di Emanuele Amoruso. Biondi si caratterizza non solo per il \u201cmestiere arguto\u201d sostiene il curatore della mostra Massimo Guastella, per sottolineare l\u2019unione di mente intelligente e abile manualit\u00e0 dell\u2019artista cegliese, ma innanzitutto per la variet\u00e0 dei suoi interessi tra cui il teatro. Perci\u00f2 non c\u2019\u00e8 da meravigliarsi, infatti, se il progetto La Culla delle Albe nasce, nel 2012, ispirato dallo scritto drammaturgico di Sarah Kane, \u201c4:48 Psycosis\u201d, ultimo suo testo teatrale incentrato sulle ore 4 e 48 statisticamente appuntamento con il suicidio, come fu per la stessa autrice. Da questo lavoro autobiografico Biondi ha tratto stimoli per dare alle sue creazioni un doppio significato: unire il senso della morte e il senso della vita, quindi della rinascita. La Culla delle Albe \u00e8 circondata da aloni di forte ironia, le sue maschere si fanno spaventapasseri ninnabili, posti accanto alle teche che raccontano la cultura del passato e la comune mediterraneit\u00e0.<\/p>\n<p>Franca Mariani, presidente dell\u2019Associazione Amici dei Musei della Provincia di Brindisi, al dodicesimo anno di attivit\u00e0, da sempre tesa a promuovere la conoscenza non solo delle realt\u00e0 museali e culturali ma anche a diffondere l&#8217;immagine assicura che \u201cospitare nel percorso museale episodi di arte contemporanea, favorisce la percezione del museo come luogo della creativit\u00e0. Ospitare all&#8217;interno della Collezione Archeologica Faldetta le opere dell&#8217;artista Uccio Biondi significa valorizzare il genius loci di questa terra\u201d.<\/p>\n<p>&nbsp;<br \/>\nBIOGRAFIA<br \/>\nDomenico Uccio Biondi (Ceglie Messapica, 1946) inizia l&#8217;attivit\u00e0 artistica da autodidatta nel 1973, con una pittura di matrice realista sociale. Dal 1977 al 1980, frequenta l&#8217;Accademia di Belle Arti di Lecce. Dagli anni 80 si occupa di ricerca teatrale, con la fondazione del collettivo del Teatro, e realizza incisioni e inchiostri legati alla produzione poetica di Pietro Gatti. Dal 1986, sviluppa un linguaggio visivo aniconico, di carattere autobiografico, influenzato dall&#8217;action painting americana e dall&#8217;informale europeo. Le Reincartazioni, degli anni &#8217;90, si arricchiscono di inserti polimaterici, segnici, grafici, scritturali e figurativi. Apre ai linguaggi della multimedialit\u00e0, sulla scia di una costante attenzione all&#8217;arte del presente e, fra i due secoli, propone lo &#8220;zapping pittorico&#8221; in cui, accanto a gestualit\u00e0 informali, ricompaiono motivi figurativi. Affascinato dai calchi ingessati di Segal, ammirati nella mostra dell\u2019artista americano (Brindisi, 1999), approda alla scultura creando con bende gessate opere monocrome e fluorescenti, di derivazione neopop e concettuale.<br \/>\nBiondi indaga le potenzialit\u00e0 di tutti i linguaggi comunicativi anche con performance teatrali e video-installazioni, creando le Installazioni intermediali, lavori in cui coniuga i video, gli oggetti plastici e le azioni performative. Fra queste, Durch den Kamin, realizzata per la mostra itinerante Il treno della memoria che, fra il 2006 e il 2007, fa tappa nelle stazioni ferroviarie pugliesi: il dramma delle deportazioni nei vagoni merci nel corso dell\u2019ultimo conflitto mondiale \u00e8 interpretato da Biondi attraverso l\u2019interazione tra un video e tre forme plastiche.<br \/>\nIl dialogo fra cromie e figura femminile compare nella ritrattistica con il ciclo pittorico Monne Terranee (2006).<br \/>\nLe Installazioni sotto forma di scultura assimilano la concezione contemporanea del superamento dei generi artistici tradizionali e si presentano come soluzioni plastico-pittoriche. Il colorismo acceso delle sue icone muliebri irrompe sulla loro staticit\u00e0 sottolineandone, al contempo, l&#8217;aspetto di effigi inanimate. In continuit\u00e0, le Altopitture coniugano abilmente il dato cromatico con la terza dimensione: \u00e8 il caso di La Rivoluzione sono io.1, altopittura esposta nella sezione leccese del Padiglione Italia della 54\u00b0 edizione della Biennale di Venezia curata da Vittorio Sgarbi (2011). Federica Coi<br \/>\n<strong>infomostra<\/strong><br \/>\nUCCIO BIONDI<br \/>\nLA CULLA DELLE ALBE<br \/>\nmise en sc\u00e8ne<br \/>\nPalazzina del Belvedere Coll. Archeologica Faldetta<br \/>\nInaugurazione mercoled\u00ec 31 maggio ore 19.00<br \/>\ndal 31 maggio al 30 settembre 2017<br \/>\na cura di Massimo Guastella<br \/>\norari apertura:<br \/>\n10,00-13,00 \/16,00-19,00 (Giugno)<br \/>\n10,00-13,00 \/18,00-20,00 (Luglio-Settembre)<br \/>\nMarted\u00ec chiuso<br \/>\n0831 562800<br \/>\nassociazioneleconne@gmail.com<br \/>\ncraccsrl@gmail.com<br \/>\nwww.ucciobiondi.it<br \/>\nIngresso libero<br \/>\nIdeazione e organizzazione:<br \/>\nAssociazione culturale arte antica e contemporanea \u201c Le Colonne\u201d<br \/>\nCRACCsrl Spin Off Universit\u00e0 del Salento \u2013 MAP (Museo Mediterraneo dell\u2019Arte Presente)<br \/>\nAssociazione culturale \u201cAmici dei Musei\u201d della Provincia di Brindisi<br \/>\nPatrocini:<br \/>\nComune di Brindisi<br \/>\nUniversit\u00e0 del Salento Dipartimento dei Beni Culturali Universit\u00e0 del Salento<br \/>\n<strong>Sponsor:<\/strong><br \/>\n\u201cIl focolare\u201d residenza per anziani<br \/>\nPartner:<br \/>\nLeonardo Studio. Comunicazione &amp; Immagine<br \/>\nAzienda agricola Vincenzo Pugliese<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ideata e organizzata dall\u2019associazione culturale Arte Antica e Contemporanea \u201cLe Colonne\u201d e dalla spin off CRACC dell\u2019Universit\u00e0 del Salento, con la fattiva collaborazione culturale dell\u2019Associazione Amici dei Musei di Brindisi, dal 31 maggio e sino a tutto settembre le opere plastiche dell\u2019artista Biondi saranno esposte in una suggestiva mostra personale: \u201cLa Culla delle Albe mise en sc\u00e8ne\u201d Biondi mette in scena la sua altopittura intitolata La Culla delle Albe, un\u2019idea di terra madre o matrigna a cui fanno riferimento delle maschere monocrome, poste su steli metallici, che vanno oltre la scultura per essere solo delle apparenze, delle \u201cfantasmine\u201d che occuperanno uno spazio per loro insolito quello della Fondazione Faldetta, con il suo carico di reperti archeologici, tra i siti culturali di eccellenza della citt\u00e0 e dell\u2019intera regione e con una invidiabile collocazione sul porto. L\u2019iniziativa patrocinata dal Comune di Brindisi e sotto l\u2019egida scientifica del Dipartimento di Beni Culturali dell\u2019ateneo salentino, grazie allo sponsor \u201cIl Focolare. Residenza per gli anziani\u201d e i partner \u201cLeonardo Studio. Immagine &amp; comunicazione\u201d e l\u2019\u201cAzienda&#8230;<\/p>\n","protected":false},"author":2,"featured_media":104813,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[112,7],"tags":[182,4323],"class_list":["post-104812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte","category-news","tag-map","tag-uccio-biondi"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/104812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=104812"}],"version-history":[{"count":3,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/104812\/revisions"}],"predecessor-version":[{"id":104818,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/104812\/revisions\/104818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/104813"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=104812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=104812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=104812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}