{"id":106838,"date":"2017-06-19T17:06:14","date_gmt":"2017-06-19T15:06:14","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=106838"},"modified":"2017-06-19T17:52:18","modified_gmt":"2017-06-19T15:52:18","slug":"domenica-25-donazione-di-sangue-presso-la-chiesa-cristo-salvatore-del-quartiere-santelia","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/domenica-25-donazione-di-sangue-presso-la-chiesa-cristo-salvatore-del-quartiere-santelia\/","title":{"rendered":"Domenica 25 donazione di sangue presso la Chiesa Cristo Salvatore del Quartiere Sant&#8217;Elia"},"content":{"rendered":"<p>E\u2019 passato quasi un anno dall\u2019incidente ferroviario avvenuto tra Andria e Corato e, allora, centinaia di persone, anche a Brindisi, fecero la fila negli ospedali per donare il proprio sangue.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Di sangue, purtroppo, c\u2019\u00e8 sempre bisogno, ed \u00e8 necessario che ci sia continuit\u00e0 nella disponibilit\u00e0 di questo tessuto liquido umano che, ad oggi, non si pu\u00f2 ancora fabbricare, c\u2019\u00e8 sempre bisogno di donne, uomini che donino una parte di s\u00e9, sacrificando un po\u2019 del proprio tempo, compiendo un piccolo gesto che rende grandi, ecco perch\u00e9:<\/p>\n<p>CerchiamoDonatoriDi Sangue<\/p>\n<p>#ConOgniMezzo<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Proprio con il proposito di cercare donatori di sangue, il Gruppo Fratres San Lorenzo da Brindisi (Sant\u2019Elia), un\u2019associazione di volontari di ispirazione cristiana che crede nell\u2019importanza della donazione come gesto di solidariet\u00e0 e generosit\u00e0, replicano si \u00e8 fatto promotore di una raccolta di sangue che avverr\u00e0 domenica 25 giugno,dalle 8 alle 12, presso la Parrocchia di Cristo Salvatore (Sant\u2019Elia), in concomitanza con la festa parrocchiale della stessa.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Ricordiamo che per donare \u00e8 necessario essere maggiorenni, in buona salute, non aver assunto farmci nel periodo precedente la donazione (es. antibiotici, antinfiammatori), non aver fatto di recente interventi chirurgici , piercing e tatuaggi ed occorre presentarsi a digiuno, \u00e8 permessa una piccola colazione (un caff\u00e8 o un th\u00e8 o un frutto o un paio di fette biscottare o un paio di biscotti secchi (l\u2019importante \u00e8 non ingerire latte e\/o derivati) e, se prima donazione, con un elettrocardiogramma (ECG); relativamente a quest\u2019ultimo \u00e8 possibile eseguirlo, gratuitamente, presso il Centro Trasfusionale nei giorni feriali predenti la donazione e, comunque, il Gruppo Fratres San Lorenzo da Brindisi, per incoraggiare le prime donazioni, rimborser\u00e0, fino ad importo massimo di 25 \u20ac, previa presentazione della ricevuta il giorno della donazione, il costo dell\u2019ECG effettuato , ad esempio, presso le farmacie cittadine che offrono tale servizio.<\/p>\n<p>Ci trovate su Facebook \u201cSan Lorenzo Fratres\u201d<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Gruppo Fratres San Lorenzo da Brindisi (Sant\u2019Elia)<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>E\u2019 passato quasi un anno dall\u2019incidente ferroviario avvenuto tra Andria e Corato e, allora, centinaia di persone, anche a Brindisi, fecero la fila negli ospedali per donare il proprio sangue. &nbsp; &nbsp; Di sangue, purtroppo, c\u2019\u00e8 sempre bisogno, ed \u00e8 necessario che ci sia continuit\u00e0 nella disponibilit\u00e0 di questo tessuto liquido umano che, ad oggi, non si pu\u00f2 ancora fabbricare, c\u2019\u00e8 sempre bisogno di donne, uomini che donino una parte di s\u00e9, sacrificando un po\u2019 del proprio tempo, compiendo un piccolo gesto che rende grandi, ecco perch\u00e9: CerchiamoDonatoriDi Sangue #ConOgniMezzo &nbsp; &nbsp; Proprio con il proposito di cercare donatori di sangue, il Gruppo Fratres San Lorenzo da Brindisi (Sant\u2019Elia), un\u2019associazione di volontari di ispirazione cristiana che crede nell\u2019importanza della donazione come gesto di solidariet\u00e0 e generosit\u00e0, replicano si \u00e8 fatto promotore di una raccolta di sangue che avverr\u00e0 domenica 25 giugno,dalle 8 alle 12, presso la Parrocchia di Cristo Salvatore (Sant\u2019Elia), in concomitanza con la festa parrocchiale della stessa. &nbsp; &nbsp; Ricordiamo che per donare \u00e8 necessario essere maggiorenni, in&#8230;<\/p>\n","protected":false},"author":2,"featured_media":106841,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[803,4460],"class_list":["post-106838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-donazione-sangue","tag-gruppo-frates"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/106838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=106838"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/106838\/revisions"}],"predecessor-version":[{"id":106842,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/106838\/revisions\/106842"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/106841"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=106838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=106838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=106838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}