{"id":107332,"date":"2017-06-26T12:22:41","date_gmt":"2017-06-26T10:22:41","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=107332"},"modified":"2017-06-26T12:37:38","modified_gmt":"2017-06-26T10:37:38","slug":"caporalato-ligorio-flai-cgil-dare-attuazione-alla-seconda-parte-della-199","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/caporalato-ligorio-flai-cgil-dare-attuazione-alla-seconda-parte-della-199\/","title":{"rendered":"Caporalato, Ligorio (Flai Cgil): &#8220;dare attuazione alla seconda parte della 199&#8221;"},"content":{"rendered":"<p>La legge contro il caporalato sta dando i primi risultati concreti, \u00e8 quanto afferma il Segretario Generale della FLAI-CGIL Brindisi Antonio Ligorio, la Legge \u00e8 entrata in vigore il 4 novembre 2016 da allora, sta producendo importanti effetti sul piano penale, sono stati portati avanti alcuni interventi da parte delle forze dell\u2019ordine, per quanto riguarda la parte penale, non solo in Puglia ma anche in altre regioni, questo dimostra che la piaga del caporalato \u00e8 trasversale e riguarda tutta l\u2019Italia, basti pensare che la prima sentenza a seguito della 199\/2016 \u00e8 avvenuta nel Mantovano.<\/p>\n<p>&nbsp;<\/p>\n<p>Infatti, secondo i dati dell\u2019osservatorio Placido Rizzotto della FLAI CGIL Nazionale, oltre 400.000 lavoratori sono vittime dei fenomeni di intermediazione illecita di manodopera, caporalato e riduzione in schiavit\u00f9.<\/p>\n<p>&nbsp;<\/p>\n<p>In Puglia tali fenomeni coinvolgono otre 40.000 lavoratori in nero, prevalentemente immigrati e in particolare impegnati nelle grandi campagne di raccolta e oltre 60.000 lavoratori e lavoratrici in grigio, immigrati e pugliesi, a cui si registrano parzialmente le giornate lavorative, con un tasso di evasioni contrattuali, previdenziali e fiscali, che assumono dimensioni eclatanti, tutte vittime del caporalato indigeno, tali fenomeni dimostrano l\u2019estrema violenza e comportamenti di quanto sia grave il fenomeno, come ribadito dal Segretario Generale FLAI-CGIL Puglia Antonio Gagliardi.<\/p>\n<p>&nbsp;<\/p>\n<p>Ma non solo con il penale si pu\u00f2 risolve un problema cosi diffuso nel paese.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La 199\/2016 \u00e8 composta da due parti, la parte penale la quale contiene strumenti innovativi e che sta funzionando, poi c\u2019\u00e8 la parte propositiva, sostenere le aziende che si caratterizzano per l\u2019eccellenza delle produzioni e per le buone pratiche di rispetto delle leggi e dei contratti.<\/p>\n<p>&nbsp;<\/p>\n<p>Quindi bisogna promuovere e diffondere tra le imprese la necessit\u00e0 e l\u2019interesse ad aderire alla Rete Nazionale del Lavoro agricolo di qualit\u00e0, per coglierne le ricadute e per distinguersi nel contesto generale in cui le aziende operano.<\/p>\n<p>&nbsp;<\/p>\n<p>Esiste la cabina di regia che si \u00e8 insediata nella sede nazionale dell\u2019INPS che sta funzionando, anche se in modo parziale, in quanto ad oggi sta solo provvedendo alla iscrizione e cancellazione delle imprese alla Rete Nazionale del Lavoro agricolo di qualit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>Una rete che in un certo qual modo dovrebbe iscrivere le imprese che attraverso un\u2019autocertificazione dichiarano di essere limpide e pulite e che dimostrano di non violare le leggi sul lavoro e soprattutto di applicare i contratti di lavoro.<\/p>\n<p>&nbsp;<\/p>\n<p>Mancano, per\u00f2 tutti gli altri aspetti che riguarda i nodi territoriali della rete, perch\u00e9 non si potrebbe chiamare rete se non fosse formata da una cabina di regia nazionale con sede a Roma che \u00e8 operativa anche se in modo parziale, se poi non si costituiscono i nodi territoriali che ad oggi non ci sono e faticano a prendere corpo e a decollare, i quali sarebbero allocati presso le commissioni CISOA provinciali, che si trovano in ogni provincia d\u2019Italia e che dovrebbero vedere a loro volta una sorta di reticolo sul territorio, che tiene insieme il centro per l\u2019impiego, il centro d\u2019immigrazione, l\u2019ente bilaterale-osservatorio provinciale dei lavoratori, ma soprattutto le societ\u00e0 di trasporto che devono garantire il servizio, affinch\u00e9 si possano sperimentare nuove forme di collocamento pubblico, che permetta l\u2019incontro tra domanda e l\u2019offerta di lavoro in agricoltura in un luogo pubblico e a gestione pubblica, perch\u00e8 i centri per l\u2019impiego spesso sono inadeguati al collocamento agricolo.<\/p>\n<p>&nbsp;<\/p>\n<p>Questo \u00e8 un elemento di grande forza della legge, perch\u00e8 darebbe la possibilit\u00e0 sul territorio di sviluppare e di togliere lo strumento vitale dei caporali, sia per il trasporto ma soprattutto l\u2019intermediazione.<br \/>\nMa tutto questo stenta a decollare, motivo per cui si fa appello alla sensibilit\u00e0 dimostrata dal Prefetto, di avviare a breve il tavolo istituzionale che coinvolga le organizzazioni sindacali e datoriali, le istituzioni territoriali, l\u2019INPS e il centro per l\u2019impiego, affinch\u00e9 si arrivi a dare attuazione della parte della legge 199\/2016 che non riguarda la repressione, che sta dando risultati, ma le azioni che garantiscano la legalit\u00e0 e la trasparenza nel mercato del lavoro agricolo, l\u2019accoglienza e il trasporto, sottoscrivendo un protocollo d\u2019intesa contro l\u2019illegalit\u00e0 in agricoltura.<\/p>\n<p>&nbsp;<\/p>\n<p>Ritenendo indispensabile successivamente un coordinamento interregionale, come proposto dalla FLAI CGIL Puglia, che coinvolga i territori di Brindisi, Taranto, Bari e Matera, sulla base dei flussi di manodopera agricola che interessa storicamente queste province.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>FLAI CGIL Brindisi<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La legge contro il caporalato sta dando i primi risultati concreti, \u00e8 quanto afferma il Segretario Generale della FLAI-CGIL Brindisi Antonio Ligorio, la Legge \u00e8 entrata in vigore il 4 novembre 2016 da allora, sta producendo importanti effetti sul piano penale, sono stati portati avanti alcuni interventi da parte delle forze dell\u2019ordine, per quanto riguarda la parte penale, non solo in Puglia ma anche in altre regioni, questo dimostra che la piaga del caporalato \u00e8 trasversale e riguarda tutta l\u2019Italia, basti pensare che la prima sentenza a seguito della 199\/2016 \u00e8 avvenuta nel Mantovano. &nbsp; Infatti, secondo i dati dell\u2019osservatorio Placido Rizzotto della FLAI CGIL Nazionale, oltre 400.000 lavoratori sono vittime dei fenomeni di intermediazione illecita di manodopera, caporalato e riduzione in schiavit\u00f9. &nbsp; In Puglia tali fenomeni coinvolgono otre 40.000 lavoratori in nero, prevalentemente immigrati e in particolare impegnati nelle grandi campagne di raccolta e oltre 60.000 lavoratori e lavoratrici in grigio, immigrati e pugliesi, a cui si registrano parzialmente le giornate lavorative, con un tasso di evasioni contrattuali,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":107335,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[4482],"class_list":["post-107332","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-arresti-caporalato"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/107332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=107332"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/107332\/revisions"}],"predecessor-version":[{"id":107336,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/107332\/revisions\/107336"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/107335"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=107332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=107332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=107332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}