{"id":107860,"date":"2017-07-03T15:32:06","date_gmt":"2017-07-03T13:32:06","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=107860"},"modified":"2017-07-03T18:40:35","modified_gmt":"2017-07-03T16:40:35","slug":"i-lavoratori-tecnomessapia-protestano-a-bari-cisl-scongiurare-i-licenziamenti-a-fine-commessa-leonardo","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/i-lavoratori-tecnomessapia-protestano-a-bari-cisl-scongiurare-i-licenziamenti-a-fine-commessa-leonardo\/","title":{"rendered":"I lavoratori Tecnomessapia protestano a Bari, Cisl: &#8220;Scongiurare i licenziamenti a fine commessa Leonardo&#8221;"},"content":{"rendered":"<p><a href=\"http:\/\/www.brundisium.net\/index.php\/i-lavoratori-tecnomessapia-protestano-a-bari-cisl-scongiurare-i-licenziamenti-a-fine-commessa-leonardo\/tecnomessapia_14\/\" rel=\"attachment wp-att-107864\"><\/a><a href=\"http:\/\/www.brundisium.net\/index.php\/i-lavoratori-tecnomessapia-protestano-a-bari-cisl-scongiurare-i-licenziamenti-a-fine-commessa-leonardo\/tecnomessapia_14\/\" rel=\"attachment wp-att-107864\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-107864 size-medium\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/TECNOMESSAPIA_14-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/TECNOMESSAPIA_14-300x225.jpg 300w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/TECNOMESSAPIA_14-768x576.jpg 768w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/TECNOMESSAPIA_14-1024x768.jpg 1024w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/TECNOMESSAPIA_14.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Grande manifestazione di protesta, questa mattina a Bari, davanti la sede di via Capruzzi della Regione Puglia. La mobilitazione ha visto protagoniste le sigle sindacali dei metalmeccanici di Fiom, Fim e Uilm, a sostegno dei lavoratori a rischio della ditta cegliese Tecnomessapia, operante nel settore dell\u2019aeronautica, che il 28 giugno scorso ha avviato la procedura per il licenziamento collettivo di 177 persone. \u00abChiediamo \u2013 ha dichiarato il segretario della Fim \u2013 Cisl, Michele Tamburrano &#8211; che Regione e Governo diano risposte in merito, garantendo la certezza del futuro lavorativo di tutte le maestranze e delle loro famiglie\u00bb. I lavoratori sono giunti a Bari con due autobus messi a disposizione dal Comune di Ceglie Messapica, nella circostanza presente con il primo cittadino Luigi Caroli.<br \/>\nA seguito della protesta, si sono aperte le porte del Palazzo della Regione, con i rappresentanti sindacali ricevuti dall\u2019assessore alla Formazione e Lavoro, Sebastiano Leo e dal presidente della task force regionale della Puglia, Leo Caroli. Un incontro proficuo in vista del faccia a faccia romano al Mise, gi\u00e0 programmato per il prossimo 12 luglio.<br \/>\n\u00abCi siamo aggiornati al 10 luglio, per un incontro programmatico in Regione \u2013 spiega Tamburrano \u2013 finalizzato alla stesura di un piano congiunto tra ente regionale ed organizzazioni sindacali. Nello specifico ci stiamo attivando, affinch\u00e9 all\u2019ordine del giorno non vi sia solo la vertenza Tecnomessapia, ma si parli pi\u00f9 in generale delle problematiche dell\u2019intero settore aeronautico che, nell\u2019ultimo anno, ha perso un migliaio di posti di lavoro. Inoltre \u2013 conclude Tamburrano \u2013 chiediamo che al tavolo presso il Ministero dello Sviluppo sia presente anche la committente Leonardo\u00bb.<br \/>\nBrindisi, 3 luglio 2017 L\u2019Ufficio Stampa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grande manifestazione di protesta, questa mattina a Bari, davanti la sede di via Capruzzi della Regione Puglia. La mobilitazione ha visto protagoniste le sigle sindacali dei metalmeccanici di Fiom, Fim e Uilm, a sostegno dei lavoratori a rischio della ditta cegliese Tecnomessapia, operante nel settore dell\u2019aeronautica, che il 28 giugno scorso ha avviato la procedura per il licenziamento collettivo di 177 persone. \u00abChiediamo \u2013 ha dichiarato il segretario della Fim \u2013 Cisl, Michele Tamburrano &#8211; che Regione e Governo diano risposte in merito, garantendo la certezza del futuro lavorativo di tutte le maestranze e delle loro famiglie\u00bb. I lavoratori sono giunti a Bari con due autobus messi a disposizione dal Comune di Ceglie Messapica, nella circostanza presente con il primo cittadino Luigi Caroli. A seguito della protesta, si sono aperte le porte del Palazzo della Regione, con i rappresentanti sindacali ricevuti dall\u2019assessore alla Formazione e Lavoro, Sebastiano Leo e dal presidente della task force regionale della Puglia, Leo Caroli. Un incontro proficuo in vista del faccia a faccia romano al&#8230;<\/p>\n","protected":false},"author":2,"featured_media":107864,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[418,4542],"class_list":["post-107860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-cisl","tag-tecnomessapia"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/107860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=107860"}],"version-history":[{"count":2,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/107860\/revisions"}],"predecessor-version":[{"id":107866,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/107860\/revisions\/107866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/107864"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=107860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=107860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=107860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}