{"id":108659,"date":"2017-07-13T13:21:17","date_gmt":"2017-07-13T11:21:17","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=108659"},"modified":"2017-07-13T13:21:17","modified_gmt":"2017-07-13T11:21:17","slug":"tecnomessapia-ce-limpegno-del-governo-per-salvare-177-posti-di-lavoro-le-reazioni-di-sindacato-e-politica","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/tecnomessapia-ce-limpegno-del-governo-per-salvare-177-posti-di-lavoro-le-reazioni-di-sindacato-e-politica\/","title":{"rendered":"Tecnomessapia, c&#8217;\u00e8 l&#8217;impegno del Governo per salvare 177 posti di lavoro: le reazioni di sindacato e politica"},"content":{"rendered":"<p>C&#8217;\u00e8 la volont\u00e0 del governo di scongiurare i 177 licenziamenti dei lavoratori Tecnomessapia.<br \/>\nE&#8217; quanto emerso ieri dall&#8217;incontro svolto presso il Mise con la partecipazione del viceministro allo sviluppo economico Teresa Bellanova.<br \/>\nPer il 20 luglio &#8211; data fissata per un nuovo incontro &#8211; il Governo si \u00e8 impegnato a reperire almeno una commessa per consentire all&#8217;azienda di Ceglie di poter attingere ad un anno di cassa integrazione straordinaria.<br \/>\nL&#8217;incontro di ieri segue quelli svolti a livello regionale alla presenza dell\u2019assessore Loredana Capone.<\/p>\n<p>La Fim Cisl \u00e8 &#8220;moderatamente soddisfatta, perch\u00e9 s\u2019incomincia ad intravedere una piccola luce infondo al tunnel. Sicuramente ancora non c\u2019\u00e8 la risoluzione definitiva del problema, ma tra otto giorni potrebbero essere bloccati definitivamente i licenziamenti per i 177 lavoratori.<br \/>\n\u00abAbbiamo posto, ancora una volta all\u2019attenzione del Mise \u2013 aggiunge il segretario Fim Cisl, Michele Tamburrano &#8211;  la necessit\u00e0 di parlare dei problemi del comparto aeronautico in generale, difendendo anche i lavoratori gi\u00e0 usciti dal sistema lavorativo, in quanto licenziati e passati nel silenzio pi\u00f9 assoluto da parte dell\u2019intera opinione pubblica e delle istituzioni, poich\u00e9 rappresentavano un numero esiguo rispetto ai 177 della Tecnomessapia. Come sindacato abbiamo il dovere di tutelare anche qui lavoratori ed \u00e8 per questo che chiediamo, ancora una volta, alla Regione Puglia e al Mise di individuare il percorso utile \u2013 conclude &#8211; che possa portare alla risoluzione del problema di tutti i lavoratori dell\u2019indotto.<\/p>\n<p>Elisa Mariano (PD) esprime &#8220;soddisfazione per l&#8217;efficienza, la sensibilit\u00e0 e l&#8217;attenzione mostrata dalla Vice Ministro che in soli 4 giorni, dalla richiesta dei sindacati, ha convocato il tavolo. La richiesta del Governo all&#8217;azienda di revoca dei licenziamenti va nella direzione auspicata. Bene, quindi, il coinvolgimento del Ministero del lavoro e la previsione di accedere ad un anno di cassa integrazione straordinaria, cos\u00ec come proposto. L&#8217;esito odierno del tavolo dimostra, ancora una volta, semmai ce ne fosse stato bisogno, che il Governo italiano \u00e8 vicino ai lavoratori e che risponde subito quando chiamato in causa dalle rappresentanze sociali, per quanto di sua competenza, e perseguendo strade concrete a tutela del lavoro e della produzione. Questo \u00e8 il nostro modo di lavorare, ai colleghi dell&#8217;opposizione lasciamo volentieri le straripanti e, in non pochi casi, gratuitamente aggressive dichiarazioni, buone per la personale campagna elettorale e per qualche titolo sulla stampa, ma evidentemente poco utili per giungere a soluzioni concrete. L&#8217;auspicio, ora, \u00e8 che anche la Regione Puglia possa finalmente impegnarsi e collaborare pienamente alla risoluzione di questa vertenza sfruttando in modo utile il tempo che grazie al Governo i lavoratori e l&#8217;azienda hanno guadagnato&#8221;.<\/p>\n<p>Meno soddisfatto il rappresentante di Direzione Italia: &#8220;Nel corso dell&#8217;incontro, la vice ministra Teresa Bellanova, cegliese d&#8217;origine, ha accusato l&#8217;On. Cirac\u00ec di aver strumentalizzato la vicenda. Un&#8217;accusa sulla quale il diretto interessato, almeno in questa fase, preferisce glissare: \u00abIo ho sempre agito in buona fede e sono con la coscienza a posto, spero sinceramene e senza polemica che possa dire altrettanto la collega Bellanova\u00bb. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&#8217;\u00e8 la volont\u00e0 del governo di scongiurare i 177 licenziamenti dei lavoratori Tecnomessapia. E&#8217; quanto emerso ieri dall&#8217;incontro svolto presso il Mise con la partecipazione del viceministro allo sviluppo economico Teresa Bellanova. Per il 20 luglio &#8211; data fissata per un nuovo incontro &#8211; il Governo si \u00e8 impegnato a reperire almeno una commessa per consentire all&#8217;azienda di Ceglie di poter attingere ad un anno di cassa integrazione straordinaria. L&#8217;incontro di ieri segue quelli svolti a livello regionale alla presenza dell\u2019assessore Loredana Capone. La Fim Cisl \u00e8 &#8220;moderatamente soddisfatta, perch\u00e9 s\u2019incomincia ad intravedere una piccola luce infondo al tunnel. Sicuramente ancora non c\u2019\u00e8 la risoluzione definitiva del problema, ma tra otto giorni potrebbero essere bloccati definitivamente i licenziamenti per i 177 lavoratori. \u00abAbbiamo posto, ancora una volta all\u2019attenzione del Mise \u2013 aggiunge il segretario Fim Cisl, Michele Tamburrano &#8211; la necessit\u00e0 di parlare dei problemi del comparto aeronautico in generale, difendendo anche i lavoratori gi\u00e0 usciti dal sistema lavorativo, in quanto licenziati e passati nel silenzio pi\u00f9 assoluto da parte&#8230;<\/p>\n","protected":false},"author":2,"featured_media":107168,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[4542],"class_list":["post-108659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-tecnomessapia"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/108659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=108659"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/108659\/revisions"}],"predecessor-version":[{"id":108660,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/108659\/revisions\/108660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/107168"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=108659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=108659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=108659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}