{"id":109199,"date":"2017-07-20T18:43:59","date_gmt":"2017-07-20T16:43:59","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=109199"},"modified":"2017-07-22T17:23:39","modified_gmt":"2017-07-22T15:23:39","slug":"tecnomessapia-fim-cisl-nuovi-spiragli-per-i-lavoratori","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/tecnomessapia-fim-cisl-nuovi-spiragli-per-i-lavoratori\/","title":{"rendered":"Tecnomessapia, Fim Cisl: &#8220;nuovi spiragli per i lavoratori&#8221;"},"content":{"rendered":"<p>Si apre uno spiraglio per un ritorno al lavoro dei dipendenti della Tecnomessapia. Proficuo incontro questo pomeriggio a Roma, dove al Ministero dello Sviluppo Economico, al termine di una trattativa sindacale intensa, si \u00e8 aperta una concreta possibilit\u00e0 di ridare dignit\u00e0 ai 177 lavoratori, dopo la sospensione dei licenziamenti annunciata la settimana scorsa.<\/p>\n<p>&nbsp;<\/p>\n<p>Grazie al deciso intervento del Mise, nella persona del viceministro Teresa Bellanova, Leonardo Company ha effettuato un apertura verso Tecnomessapia, garantendo una commessa \u2013 come specificato dal viceministro \u2013 per poche decine di unit\u00e0, con un\u2019unica clausola che l\u2019azienda Tecnomessapia si doti di una sede propria, cosa che al momento non ha.<br \/>\nL\u2019azienda dopo una pausa di riflessione ha accettato. Alla luce di ci\u00f2, luned\u00ec prossimo le organizzazioni sindacali e la Tecnomessapia si incontreranno presso la sede di Confindustria Brindisi per definire ogni dettaglio tecnico.<\/p>\n<p>&nbsp;<\/p>\n<p>Considerata la ripresa dell\u2019attivit\u00e0 lavorativa, le parti sottoscriveranno un accordo di Cigs per tutti i lavoratori.<\/p>\n<p>&nbsp;<\/p>\n<p>Al tavolo la Fim ha da subito chiesto a Tecnomessapia di cogliere immediatamente l&#8217;apertura del governo, reclamando una risposta repentina. Cosa che \u00e8 avvenuta dopo la ristretta con i rappresentanti del Ministero.<\/p>\n<p>&nbsp;<\/p>\n<p>Consideriamo questo risultato come un piccolo passo in avanti, utile a mettere momentaneamente in sicurezza il destino di 177 famiglie e, nello stesso tempo, che consente di allungare di un anno la possibilit\u00e0 di trovare ulteriori soluzioni, anche per tutti gli altri lavoratori dell\u2019indotto, i cui numeri si aggirano intorno alle mille unit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>Ringraziamo il viceministro Bellanova per il deciso e puntuale intervento e il governo, che hanno permesso di compiere questo primo passo in avanti, che per noi rappresenta solo il punto di partenza dal quale partire per rivendicare su tutti i tavoli \u2013 compreso quello regionale \u2013 certezze per tutti i lavoratori dell\u2019indotto aeronautico, specialmente quelli gi\u00e0 fuoriusciti dal sistema produttivo.<br \/>\n&nbsp;<\/p>\n<p>FIM CISL<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si apre uno spiraglio per un ritorno al lavoro dei dipendenti della Tecnomessapia. Proficuo incontro questo pomeriggio a Roma, dove al Ministero dello Sviluppo Economico, al termine di una trattativa sindacale intensa, si \u00e8 aperta una concreta possibilit\u00e0 di ridare dignit\u00e0 ai 177 lavoratori, dopo la sospensione dei licenziamenti annunciata la settimana scorsa. &nbsp; Grazie al deciso intervento del Mise, nella persona del viceministro Teresa Bellanova, Leonardo Company ha effettuato un apertura verso Tecnomessapia, garantendo una commessa \u2013 come specificato dal viceministro \u2013 per poche decine di unit\u00e0, con un\u2019unica clausola che l\u2019azienda Tecnomessapia si doti di una sede propria, cosa che al momento non ha. L\u2019azienda dopo una pausa di riflessione ha accettato. Alla luce di ci\u00f2, luned\u00ec prossimo le organizzazioni sindacali e la Tecnomessapia si incontreranno presso la sede di Confindustria Brindisi per definire ogni dettaglio tecnico. &nbsp; Considerata la ripresa dell\u2019attivit\u00e0 lavorativa, le parti sottoscriveranno un accordo di Cigs per tutti i lavoratori. &nbsp; Al tavolo la Fim ha da subito chiesto a Tecnomessapia di cogliere immediatamente&#8230;<\/p>\n","protected":false},"author":2,"featured_media":107864,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1040,4542],"class_list":["post-109199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-fim-cisl","tag-tecnomessapia"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/109199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=109199"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/109199\/revisions"}],"predecessor-version":[{"id":109201,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/109199\/revisions\/109201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/107864"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=109199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=109199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=109199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}