{"id":109225,"date":"2017-07-20T18:58:38","date_gmt":"2017-07-20T16:58:38","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=109225"},"modified":"2017-07-22T17:22:21","modified_gmt":"2017-07-22T15:22:21","slug":"tecnomessapia-mariano-dopo-il-tavolo-a-roma-ritirati-i-licenziamenti-ora-lazienda-faccia-il-suo","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/tecnomessapia-mariano-dopo-il-tavolo-a-roma-ritirati-i-licenziamenti-ora-lazienda-faccia-il-suo\/","title":{"rendered":"Tecnomessapia, Mariano dopo il tavolo a Roma: &#8220;ritirati i licenziamenti, ora l&#8217;azienda faccia il suo&#8221;"},"content":{"rendered":"<p>Grazie all&#8217;impegno del Governo e del Vice Ministro Teresa Bellanova in persona sono stati ritirati i licenziamenti da Tecnomessapia, i lavoratori potranno accedere ad un ulteriore anno di cassa integrazione e Leonardo si \u00e8 impegnata a formulare nuove proposte di commessa per il futuro.<br \/>\nTutto questo, per\u00f2, a patto che Tecnomessapia diventi realmente un&#8217;impresa e non rimanga semplicemente un&#8217;azienda con sede legale in uno studio di consulenza e priva di un proprio stabilimento.<\/p>\n<p>&nbsp;<\/p>\n<p>C&#8217;\u00e8 una bella differenza, infatti, tra un&#8217;impresa produttiva e radicata, dotata di un proprio stabilimento e con un management attento e capace di reinvestire gli utili in innovazione di processo e di prodotto e un&#8217;agenzia di intermediazione di manodopera la cui propriet\u00e0 ha tenuto per s\u00e8 tutti gli utili maturati in questi anni di commesse da Finmeccanica.<\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217;intervento del Governo, quindi, non solo \u00e8 servito a mettere in sicurezza i lavoratori che rischiavano di andare a casa, ma anche a chiarire che questo tavolo non ha la finalit\u00e0 di soddisfare il business di qualcuno, ma quello di salvaguardare maestranze e lavoratori e dare una mano affinch\u00e8 si sviluppi un modo di fare impresa per davvero sano e capace di arricchire il sistema industriale del territorio e non solo le tasche di qualcuno.<\/p>\n<p><strong><br \/>\nELISA MARIANO &#8211; PARTITO DEMOCRATICO<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grazie all&#8217;impegno del Governo e del Vice Ministro Teresa Bellanova in persona sono stati ritirati i licenziamenti da Tecnomessapia, i lavoratori potranno accedere ad un ulteriore anno di cassa integrazione e Leonardo si \u00e8 impegnata a formulare nuove proposte di commessa per il futuro. Tutto questo, per\u00f2, a patto che Tecnomessapia diventi realmente un&#8217;impresa e non rimanga semplicemente un&#8217;azienda con sede legale in uno studio di consulenza e priva di un proprio stabilimento. &nbsp; C&#8217;\u00e8 una bella differenza, infatti, tra un&#8217;impresa produttiva e radicata, dotata di un proprio stabilimento e con un management attento e capace di reinvestire gli utili in innovazione di processo e di prodotto e un&#8217;agenzia di intermediazione di manodopera la cui propriet\u00e0 ha tenuto per s\u00e8 tutti gli utili maturati in questi anni di commesse da Finmeccanica. &nbsp; L&#8217;intervento del Governo, quindi, non solo \u00e8 servito a mettere in sicurezza i lavoratori che rischiavano di andare a casa, ma anche a chiarire che questo tavolo non ha la finalit\u00e0 di soddisfare il business di qualcuno, ma&#8230;<\/p>\n","protected":false},"author":2,"featured_media":36298,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[751,4542],"class_list":["post-109225","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-mariano","tag-tecnomessapia"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/109225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=109225"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/109225\/revisions"}],"predecessor-version":[{"id":109228,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/109225\/revisions\/109228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/36298"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=109225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=109225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=109225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}