{"id":109398,"date":"2017-07-23T14:59:13","date_gmt":"2017-07-23T12:59:13","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=109398"},"modified":"2017-07-24T08:03:16","modified_gmt":"2017-07-24T06:03:16","slug":"vitali-difende-oggiano-clamore-vergognoso","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/vitali-difende-oggiano-clamore-vergognoso\/","title":{"rendered":"Vitali difende Oggiano: &#8220;clamore vergognoso&#8221;"},"content":{"rendered":"<p>&#8220;Totale solidariet\u00e0 a Massimiliano Oggiano, vittima di un linciaggio inaudito per un evento goliardico svoltosi nella sua abitazione privata. Siamo assolutamente senza parole per un clamore irrispettoso della sfera privata di un cittadino. Potrebbe persino avere dei profili giuridicamente rilevanti&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>Cos\u00ec il coordinatore regionale di Forza Italia, l&#8217;on Luigi Vitali, intervenendo sulla polemica nata dai festeggiamenti avvenuti in forma privata a casa dell&#8217;ex consigliere comunale brindisino.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Una distorsione della realt\u00e0, tipica della doppia morale di certa sinistra che lavora per l&#8217;appiattimento culturale e la vittoria del pensiero unico, -aggiunge- che fa scoppiare un caso persino per un fatto avvenuto tra le mura domestiche di un cittadino, scippando senza diritto ogni diritto alla privacy. Un pericolosissimo precedente che stigmatizziamo e la cui gravit\u00e0 dovrebbe far riflettere giuristi e cittadini tutti.<\/p>\n<p>A lui tutto il nostro sostegno -conclude Vitali- perch\u00e9 ci vergogneremmo di accostarci a chi, evidentemente a corto di argomenti, si permette di intromettersi in fatti privati, peraltro scherzosi in modo chiaro e netto&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>COMUNICATO STAMPA LUIGI VITALI &#8211; COORDINATORE REGIONALE FI<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Totale solidariet\u00e0 a Massimiliano Oggiano, vittima di un linciaggio inaudito per un evento goliardico svoltosi nella sua abitazione privata. Siamo assolutamente senza parole per un clamore irrispettoso della sfera privata di un cittadino. Potrebbe persino avere dei profili giuridicamente rilevanti&#8221;. &nbsp; Cos\u00ec il coordinatore regionale di Forza Italia, l&#8217;on Luigi Vitali, intervenendo sulla polemica nata dai festeggiamenti avvenuti in forma privata a casa dell&#8217;ex consigliere comunale brindisino. &nbsp; &#8220;Una distorsione della realt\u00e0, tipica della doppia morale di certa sinistra che lavora per l&#8217;appiattimento culturale e la vittoria del pensiero unico, -aggiunge- che fa scoppiare un caso persino per un fatto avvenuto tra le mura domestiche di un cittadino, scippando senza diritto ogni diritto alla privacy. Un pericolosissimo precedente che stigmatizziamo e la cui gravit\u00e0 dovrebbe far riflettere giuristi e cittadini tutti. A lui tutto il nostro sostegno -conclude Vitali- perch\u00e9 ci vergogneremmo di accostarci a chi, evidentemente a corto di argomenti, si permette di intromettersi in fatti privati, peraltro scherzosi in modo chiaro e netto&#8221;. &nbsp; COMUNICATO STAMPA LUIGI VITALI&#8230;<\/p>\n","protected":false},"author":2,"featured_media":109259,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[4646,250,865],"class_list":["post-109398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-ciullo","tag-forza-italia","tag-oggiano"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/109398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=109398"}],"version-history":[{"count":2,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/109398\/revisions"}],"predecessor-version":[{"id":109406,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/109398\/revisions\/109406"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/109259"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=109398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=109398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=109398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}