{"id":109754,"date":"2017-07-27T18:15:52","date_gmt":"2017-07-27T16:15:52","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=109754"},"modified":"2017-07-28T09:44:14","modified_gmt":"2017-07-28T07:44:14","slug":"occupa-il-triplo-della-spiaggia-concessa-sequestrati-40-ombrelloni-e-80-lettini-in-zona-monacelle","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/occupa-il-triplo-della-spiaggia-concessa-sequestrati-40-ombrelloni-e-80-lettini-in-zona-monacelle\/","title":{"rendered":"Occupa il triplo della spiaggia concessa: sequestrati 40 ombrelloni e 80 lettini in zona Monacelle"},"content":{"rendered":"<p>Aveva limitato arbitrariamente la libera fruizione del mare e della spiaggia da parte dei cittadini, occupando con un consistente numero di attrezzature balneari, circa 1.000 metri quadrati di area demaniale marittima.<br \/>\nA conclusione di un\u2019attivit\u00e0 d\u2019indagine, nella mattinata odierna, i militari della Sezione Polizia Marittima della Capitaneria di Porto &#8211; Guardia Costiera di Brindisi, sotto il Comando del C.V.(CP) Salvatore Minervino, sono intervenuti presso il litorale nord di competenza del Comune di Carovigno provvedendo a sgomberare l\u2019area illecitamente ed arbitrariamente occupata ed a restituirla alla libera fruizione da parte di bagnanti e turisti.<\/p>\n<p>Dal raffronto incrociato dei rilievi eseguiti e delle autorizzazioni di cui il concessionario era in possesso, l\u2019area oggetto dell\u2019abuso \u00e8 risultata essere estesa per circa tre volte rispetto a quella legalmente concessa. A questo punto, d\u2019intesa con la competente Autorit\u00e0 Giudiziaria, nella persona del Sostituto Procuratore di Turno Dr.ssa Iolanda Daniela Chimienti, le attrezzature balneari &#8211; ben 40 ombrelloni e 80 lettini &#8211; sono state sottoposte a sequestro penale mentre l\u2019amministratore unico \u00e8 stato deferito a piede libero per le violazioni riscontrate.<\/p>\n<p>&nbsp;<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-109754 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.brundisium.net\/index.php\/occupa-il-triplo-della-spiaggia-concessa-sequestrati-40-ombrelloni-e-80-lettini-in-zona-monacelle\/sequestro-lettini-e-ombrelloni-monacelle-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/sequestro-lettini-e-ombrelloni-monacelle-3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/sequestro-lettini-e-ombrelloni-monacelle-3-150x150.jpg 150w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/sequestro-lettini-e-ombrelloni-monacelle-3-600x600.jpg 600w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/sequestro-lettini-e-ombrelloni-monacelle-3-60x60.jpg 60w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.brundisium.net\/index.php\/occupa-il-triplo-della-spiaggia-concessa-sequestrati-40-ombrelloni-e-80-lettini-in-zona-monacelle\/sequestro-lettini-e-ombrelloni-monacelle-4\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/sequestro-lettini-e-ombrelloni-monacelle-4-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/sequestro-lettini-e-ombrelloni-monacelle-4-150x150.jpg 150w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/sequestro-lettini-e-ombrelloni-monacelle-4-600x600.jpg 600w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/sequestro-lettini-e-ombrelloni-monacelle-4-60x60.jpg 60w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.brundisium.net\/index.php\/occupa-il-triplo-della-spiaggia-concessa-sequestrati-40-ombrelloni-e-80-lettini-in-zona-monacelle\/sequestro-lettini-e-ombrelloni-monacelle-5\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/sequestro-lettini-e-ombrelloni-monacelle-5-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/sequestro-lettini-e-ombrelloni-monacelle-5-150x150.jpg 150w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/sequestro-lettini-e-ombrelloni-monacelle-5-600x600.jpg 600w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/sequestro-lettini-e-ombrelloni-monacelle-5-60x60.jpg 60w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.brundisium.net\/index.php\/occupa-il-triplo-della-spiaggia-concessa-sequestrati-40-ombrelloni-e-80-lettini-in-zona-monacelle\/sequestro-lettini-e-ombrelloni-monacelle-6\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/sequestro-lettini-e-ombrelloni-monacelle-6-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/sequestro-lettini-e-ombrelloni-monacelle-6-150x150.jpg 150w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/sequestro-lettini-e-ombrelloni-monacelle-6-600x600.jpg 600w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/sequestro-lettini-e-ombrelloni-monacelle-6-60x60.jpg 60w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.brundisium.net\/index.php\/occupa-il-triplo-della-spiaggia-concessa-sequestrati-40-ombrelloni-e-80-lettini-in-zona-monacelle\/sequestro-lettini-e-ombrelloni-monacelle-1\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/sequestro-lettini-e-ombrelloni-monacelle-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/sequestro-lettini-e-ombrelloni-monacelle-1-150x150.jpg 150w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/sequestro-lettini-e-ombrelloni-monacelle-1-600x600.jpg 600w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/sequestro-lettini-e-ombrelloni-monacelle-1-60x60.jpg 60w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.brundisium.net\/index.php\/occupa-il-triplo-della-spiaggia-concessa-sequestrati-40-ombrelloni-e-80-lettini-in-zona-monacelle\/sequestro-lettini-e-ombrelloni-monacelle-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/sequestro-lettini-e-ombrelloni-monacelle-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/sequestro-lettini-e-ombrelloni-monacelle-2-150x150.jpg 150w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/sequestro-lettini-e-ombrelloni-monacelle-2-600x600.jpg 600w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/07\/sequestro-lettini-e-ombrelloni-monacelle-2-60x60.jpg 60w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>L\u2019attivit\u00e0 si inserisce nel contesto dell\u2019operazione \u201cMare Sicuro 2017\u201d in atto ce he vede impegnati le donne e gli uomini della Guardia Costiera in mare ed a terra su tutto l\u2019ambito di competenza della Capitaneria di Porto di Brindisi. L\u2019attenzione dei militari \u00e8 concentrata sul rispetto delle norme in materia di sicurezza e salvaguardia della vita umana in mare oltre che della libera fruizione del mare e delle spiagge.<\/p>\n<p>In tale contesto si inseriscono le attivit\u00e0 di controllo sulla filiera ittica che, quotidianamente vengono espletate a tutela della salute di ignari consumatori, specialmente nel periodo in cui, l\u2019elevato afflusso di turisti e villeggianti, vede in azione i c.d. \u201cfurbetti\u201d della ristorazione oltre a quelli dell\u2019ombrellone.<\/p>\n<p>Nel richiamare tutti gli operatori del settore turistico-ricreativo ad un preciso assoluto rispetto delle norme, il Comandante Minervino garantisce che i controlli continueranno, senza soluzione di continuit\u00e0, nei confronti di tutte le tipologie di attivit\u00e0 commerciali di interesse.<br \/>\nPer qualsiasi segnalazione si ricorda che sono attivi 24 ore su 24, 7 giorni su 7 il numero di centralino della Sala Operativa 0831521022 e la casella di posta elettronica so.cpbrindisi@mit.gov.it mentre, per le sole emergenze in mare, il numero blu 1530.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aveva limitato arbitrariamente la libera fruizione del mare e della spiaggia da parte dei cittadini, occupando con un consistente numero di attrezzature balneari, circa 1.000 metri quadrati di area demaniale marittima. A conclusione di un\u2019attivit\u00e0 d\u2019indagine, nella mattinata odierna, i militari della Sezione Polizia Marittima della Capitaneria di Porto &#8211; Guardia Costiera di Brindisi, sotto il Comando del C.V.(CP) Salvatore Minervino, sono intervenuti presso il litorale nord di competenza del Comune di Carovigno provvedendo a sgomberare l\u2019area illecitamente ed arbitrariamente occupata ed a restituirla alla libera fruizione da parte di bagnanti e turisti. Dal raffronto incrociato dei rilievi eseguiti e delle autorizzazioni di cui il concessionario era in possesso, l\u2019area oggetto dell\u2019abuso \u00e8 risultata essere estesa per circa tre volte rispetto a quella legalmente concessa. A questo punto, d\u2019intesa con la competente Autorit\u00e0 Giudiziaria, nella persona del Sostituto Procuratore di Turno Dr.ssa Iolanda Daniela Chimienti, le attrezzature balneari &#8211; ben 40 ombrelloni e 80 lettini &#8211; sono state sottoposte a sequestro penale mentre l\u2019amministratore unico \u00e8 stato deferito a piede&#8230;<\/p>\n","protected":false},"author":2,"featured_media":109758,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[801,4662],"class_list":["post-109754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-guardia-costiera","tag-monacelle"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/109754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=109754"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/109754\/revisions"}],"predecessor-version":[{"id":109761,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/109754\/revisions\/109761"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/109758"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=109754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=109754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=109754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}