{"id":110785,"date":"2017-08-10T10:20:38","date_gmt":"2017-08-10T08:20:38","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=110785"},"modified":"2017-08-10T10:20:38","modified_gmt":"2017-08-10T08:20:38","slug":"ops-e-giuffre-concordano-il-segretario-dellauthority-dovra-essere-brindisino","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/ops-e-giuffre-concordano-il-segretario-dellauthority-dovra-essere-brindisino\/","title":{"rendered":"OPS e Giuffr\u00e8 concordano: il segretario dell&#8217;Authority dovr\u00e0 essere brindisino"},"content":{"rendered":"<p>Su richiesta dell&#8217;Associazione OPS (Operatori Portuali Salentini), il Commissario  Straordinario del Comune di Brindisi, Santi Giuffr\u00e8, ha ricevuto una delegazione di OPS formata dal Presidente e dal Consiglio Direttivo.<br \/>\nL&#8217;incontro \u00e8 stato incentrato sulla discussione della situazione del porto di Brindisi e, in particolare, della imminente nomina del Segretario Generale dell\u2019Autorit\u00e0 di Sistema Portuale dell\u2019Adriatico Meridionale.<br \/>\nLa richiesta &#8211; condivisa da operatori ed ente &#8211; \u00e8 che la prossima nomina costituisca condizione che non penalizzi ulteriormente la realt\u00e0 portuale brindisina.<\/p>\n<p>Per questo &#8211; scrivono da OPS &#8211; si \u00e8 condivisa &#8220;la necessit\u00e0 che il futuro Segretario Generale debba rappresentare, nell\u2019ambito delle sue funzioni, gli interessi della collettivit\u00e0 dei porti aderenti alla nuova Autorit\u00e0 Portuale in maniera equa e con ci\u00f2 rivendicando il ruolo primario del porto di Brindisi nell\u2019ambito del sistema portuale dell\u2019intero paese&#8221;.<\/p>\n<p>&#8220;Senza voler improntare ragionamenti campanilistici &#8211; si legge nel comunicato dell&#8217;Amministrazione Comunale &#8211; l&#8217;Associazione ha illustrato i trascorsi del Porto di Brindisi che, gradualmente, hanno determinato uno spostamento dei centri decisionali verso gli interessi specificatamente rappresentati dal capoluogo di Regione&#8221;.<\/p>\n<p>L\u2019associazione ha ringraziato il Commissario per la sensibilit\u00e0 dimostrata verso i problemi del porto e per la determinazione a voler contribuire a risolvere con immediatezza le tante criticit\u00e0 mentre da parte di Giuffr\u00e8 c&#8217;\u00e8 stata la piena assunzione di responsabilit\u00e0 affinch\u00e9 &#8220;il futuro Segretario Generale dell&#8217;Autorit\u00e0 di Sistema&#8221; possa &#8220;rappresentare, in una logica di pari dignit\u00e0 tra i due porti di Bari e Brindisi, non tanto gli interessi particolari quanto la stessa fondamentale funzione del Porto di Brindisi, accanto a quella del Porto di Bari, gi\u00e0 titolato al pi\u00f9 alto livello con la figura del Presidente&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Su richiesta dell&#8217;Associazione OPS (Operatori Portuali Salentini), il Commissario Straordinario del Comune di Brindisi, Santi Giuffr\u00e8, ha ricevuto una delegazione di OPS formata dal Presidente e dal Consiglio Direttivo. L&#8217;incontro \u00e8 stato incentrato sulla discussione della situazione del porto di Brindisi e, in particolare, della imminente nomina del Segretario Generale dell\u2019Autorit\u00e0 di Sistema Portuale dell\u2019Adriatico Meridionale. La richiesta &#8211; condivisa da operatori ed ente &#8211; \u00e8 che la prossima nomina costituisca condizione che non penalizzi ulteriormente la realt\u00e0 portuale brindisina. Per questo &#8211; scrivono da OPS &#8211; si \u00e8 condivisa &#8220;la necessit\u00e0 che il futuro Segretario Generale debba rappresentare, nell\u2019ambito delle sue funzioni, gli interessi della collettivit\u00e0 dei porti aderenti alla nuova Autorit\u00e0 Portuale in maniera equa e con ci\u00f2 rivendicando il ruolo primario del porto di Brindisi nell\u2019ambito del sistema portuale dell\u2019intero paese&#8221;. &#8220;Senza voler improntare ragionamenti campanilistici &#8211; si legge nel comunicato dell&#8217;Amministrazione Comunale &#8211; l&#8217;Associazione ha illustrato i trascorsi del Porto di Brindisi che, gradualmente, hanno determinato uno spostamento dei centri decisionali verso gli interessi specificatamente rappresentati&#8230;<\/p>\n","protected":false},"author":2,"featured_media":77111,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[3344,4338],"class_list":["post-110785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-ops","tag-santi-giuffre"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/110785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=110785"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/110785\/revisions"}],"predecessor-version":[{"id":110786,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/110785\/revisions\/110786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/77111"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=110785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=110785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=110785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}