{"id":111232,"date":"2017-08-17T12:35:33","date_gmt":"2017-08-17T10:35:33","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=111232"},"modified":"2017-08-17T12:37:45","modified_gmt":"2017-08-17T10:37:45","slug":"natura-in-jazz-alla-stazione-ferroviaria-dismessa-di-fontevecchia","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/natura-in-jazz-alla-stazione-ferroviaria-dismessa-di-fontevecchia\/","title":{"rendered":"Natura in Jazz alla stazione ferroviaria dismessa di Fontevecchia"},"content":{"rendered":"<p>Il 21 Agosto 2017 dalle ore 20.30 continua nella cornice della stazione ferroviaria dismessa di Fontevecchia a Ostuni divenuta casa del Parco Regionale Dune Costiere Torre Canne Torre S. Leonardo, la rassegna &#8220;Casa del Parco Green&#8221; tra natura, arte, musica, cinema e mostre con l\u2019appuntamento \u201cNatura in Jazz\u201d a cura dell\u2019Associazione di Promozione Sociale Gran Teatro del Click nature&amp;food.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La serata \u201cNatura in Jazz\u201d si apre con il gruppo musicale Fast Jazz Quartet e Geos Ostuni Gruppo Escursionistico Speleologico Ostunese che propone giochi di speleologia per bambini in contemporanea a brevi proiezioni sul patrimonio carsico pugliese.<\/p>\n<p>&nbsp;<\/p>\n<p>Luca Palazzo Presidente dell\u2019Associazione di Promozione Sociale Luzzart, ci racconter\u00e0 della sua recente esperienza in Africa, nella capitale del Mali, Bamako, presenter\u00e0 la nascente associazione umanitaria &#8220;Briciole&#8221; e i progetti di cooperazione internazionale sinora avviati, tra cui ABC Aiuta i Bambini a Contare!, e come ciascuno di noi pu\u00f2 farne parte anche a distanza.<\/p>\n<p>&nbsp;<\/p>\n<p>Durante la serata sar\u00e0 visibile la mostra della scenografa illustratrice multimaterica Marzia Ghezzo e dell\u2019illustratore Federico Mancini, l\u2019appuntamento si concluder\u00e0 con la proiezione di un fuori programma: il suggestivo docufilm \u201cIl cammino dell\u2019Appia Antica la madre di tutte le vie d\u2019Europa\u201d regia Alessandro Scillitani.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La rassegna chiuder\u00e0 il 2 Settembre con \u201cCinema Natura\u201d proiezione del film \u201cAnni Ruggenti\u201d di Luigi Zampa, in mostra le fotografie di scena e alcuni protagonisti ostunesi delle riprese cinematografiche.<\/p>\n<p>&nbsp;<\/p>\n<p>Durante gli eventi saranno presenti le artigiane del Parco: Apicoltura Alveare Bianco Ostuni, Labo Naturae e StampalaNatura progetto del Gran Teatro del Click nature&amp;food; contemporaneamente ci saranno le degustazioni di prodotti biologici tipici a cura di Bio Solequo Coop &#8211; I Giardini della Grata eWalkingWine progetto con ApeCar Piaggio vintage volto alla promozione e vendita di vino esclusivamente pugliese.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Comunicato stampa &#8220;Folletti e Folli&#8221;<br \/>\nSezione Teatro &#8220;Folletti e Folli&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 21 Agosto 2017 dalle ore 20.30 continua nella cornice della stazione ferroviaria dismessa di Fontevecchia a Ostuni divenuta casa del Parco Regionale Dune Costiere Torre Canne Torre S. Leonardo, la rassegna &#8220;Casa del Parco Green&#8221; tra natura, arte, musica, cinema e mostre con l\u2019appuntamento \u201cNatura in Jazz\u201d a cura dell\u2019Associazione di Promozione Sociale Gran Teatro del Click nature&amp;food. &nbsp; &nbsp; La serata \u201cNatura in Jazz\u201d si apre con il gruppo musicale Fast Jazz Quartet e Geos Ostuni Gruppo Escursionistico Speleologico Ostunese che propone giochi di speleologia per bambini in contemporanea a brevi proiezioni sul patrimonio carsico pugliese. &nbsp; Luca Palazzo Presidente dell\u2019Associazione di Promozione Sociale Luzzart, ci racconter\u00e0 della sua recente esperienza in Africa, nella capitale del Mali, Bamako, presenter\u00e0 la nascente associazione umanitaria &#8220;Briciole&#8221; e i progetti di cooperazione internazionale sinora avviati, tra cui ABC Aiuta i Bambini a Contare!, e come ciascuno di noi pu\u00f2 farne parte anche a distanza. &nbsp; Durante la serata sar\u00e0 visibile la mostra della scenografa illustratrice multimaterica Marzia Ghezzo e dell\u2019illustratore Federico&#8230;<\/p>\n","protected":false},"author":2,"featured_media":111233,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[4749,640],"class_list":["post-111232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-folli-e-folletti","tag-parco-dune-costiere"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/111232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=111232"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/111232\/revisions"}],"predecessor-version":[{"id":111234,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/111232\/revisions\/111234"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/111233"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=111232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=111232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=111232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}