{"id":111597,"date":"2017-08-23T15:49:22","date_gmt":"2017-08-23T13:49:22","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=111597"},"modified":"2017-08-23T16:52:56","modified_gmt":"2017-08-23T14:52:56","slug":"attivo-ad-ostuni-il-servizio-di-consulenza-pediatrica-ambulatoriale-scap","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/attivo-ad-ostuni-il-servizio-di-consulenza-pediatrica-ambulatoriale-scap\/","title":{"rendered":"Attivo ad Ostuni il Servizio di Consulenza Pediatrica Ambulatoriale (SCAP)"},"content":{"rendered":"<p>Parte da Ostuni il Servizio di Consulenza Pediatrica Ambulatoriale (SCAP), che sar\u00e0 attivo dal prossimo 26 agosto negli ambulatori pediatrici, situati al primo piano del Presidio Ospedaliero. Il servizio SCAP funzioner\u00e0 i giorni prefestivi e festivi dalle ore 8.00 alle ore 20.00.<\/p>\n<p>&nbsp;<\/p>\n<p>Il progetto SCAP \u00e8 una buona pratica gi\u00e0 sperimentata positivamente nella ASL BT ed estesa oggi a tutto il territorio regionale con provvedimento adottato dalla Giunta della Regione Puglia nel mese di febbraio scorso.<\/p>\n<p>&nbsp;<\/p>\n<p>Lo SCAP dovr\u00e0 garantire il servizio di consulenza pediatrica, rivolto ai bambini che giungono presso il Pronto Soccorso con l\u2019ipotesi di un codice bianco e verde e contribuir\u00e0 a ridurre le lunghe attese e i ricoveri impropri.<\/p>\n<p>&nbsp;<\/p>\n<p>Il rilancio su tutto il territorio regionale del progetto SCAP, uno dei pochi esempi nel mezzogiorno, si inserisce nell\u2019ottica di integrazione, in maniera sempre pi\u00f9 innovativa, tra i servizi ospedalieri e quelli territoriali, realizzando un modello di assistenza evoluto e compatibile con i bisogni assistenziali dei cittadini.<\/p>\n<p>&nbsp;<\/p>\n<p>Per la ASL di Brindisi sono state gi\u00e0 avviate le procedure per l\u2019attivazione del Servizio SCAP anche nelle altre sedi previste (Presidio Ospedaliero di Brindisi e Presidio Ospedaliero di Francavilla Fontana).<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>UFFICIO STAMPA ASL BR<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parte da Ostuni il Servizio di Consulenza Pediatrica Ambulatoriale (SCAP), che sar\u00e0 attivo dal prossimo 26 agosto negli ambulatori pediatrici, situati al primo piano del Presidio Ospedaliero. Il servizio SCAP funzioner\u00e0 i giorni prefestivi e festivi dalle ore 8.00 alle ore 20.00. &nbsp; Il progetto SCAP \u00e8 una buona pratica gi\u00e0 sperimentata positivamente nella ASL BT ed estesa oggi a tutto il territorio regionale con provvedimento adottato dalla Giunta della Regione Puglia nel mese di febbraio scorso. &nbsp; Lo SCAP dovr\u00e0 garantire il servizio di consulenza pediatrica, rivolto ai bambini che giungono presso il Pronto Soccorso con l\u2019ipotesi di un codice bianco e verde e contribuir\u00e0 a ridurre le lunghe attese e i ricoveri impropri. &nbsp; Il rilancio su tutto il territorio regionale del progetto SCAP, uno dei pochi esempi nel mezzogiorno, si inserisce nell\u2019ottica di integrazione, in maniera sempre pi\u00f9 innovativa, tra i servizi ospedalieri e quelli territoriali, realizzando un modello di assistenza evoluto e compatibile con i bisogni assistenziali dei cittadini. &nbsp; Per la ASL di Brindisi sono&#8230;<\/p>\n","protected":false},"author":2,"featured_media":111600,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[3758],"class_list":["post-111597","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-asl-br"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/111597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=111597"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/111597\/revisions"}],"predecessor-version":[{"id":111601,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/111597\/revisions\/111601"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/111600"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=111597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=111597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=111597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}