{"id":111908,"date":"2017-08-28T18:52:53","date_gmt":"2017-08-28T16:52:53","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=111908"},"modified":"2017-08-31T12:18:37","modified_gmt":"2017-08-31T10:18:37","slug":"community-hub-una-biblioteca-sociale-a-servizio-dellaula-studio-per-studenti-appello-per-la-donazione-di-libri","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/community-hub-una-biblioteca-sociale-a-servizio-dellaula-studio-per-studenti-appello-per-la-donazione-di-libri\/","title":{"rendered":"Community Hub: una Biblioteca Sociale a servizio dell&#8217;aula studio per studenti. Appello per la donazione di libri"},"content":{"rendered":"<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/08\/community-hub-1.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-111493\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/08\/community-hub-1-300x212.jpeg\" alt=\"\" width=\"300\" height=\"212\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/08\/community-hub-1-300x212.jpeg 300w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/08\/community-hub-1-768x543.jpeg 768w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/08\/community-hub-1-1024x724.jpeg 1024w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/08\/community-hub-1.jpeg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><br \/>\n<\/a>La nascente Associazione Community Hub Brindisi, al fine di allargare ancora di pi\u00f9 l\u2019offerta della sede e agevolare i giovani nella propria crescita culturale, ha allestito una Biblioteca Sociale all&#8217;interno degli spazi della sede in Via Saponea 58.<\/p>\n<p>&nbsp;<\/p>\n<p>Chiunque voglia donare i propri libri, dalla narrativa alla saggistica, pu\u00f2 contattarci contribuendo cos\u00ec alla crescita di un nuovo polo culturale della citt\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cCome Community Hub Brindisi, vogliamo promuovere la Cultura anche con semplici gesti ed iniziative: per questo chiediamo ai cittadini, alle librerie, alle case editrici presenti sul territorio, di aiutarci a costruire un vero e proprio polo della condivisione del sapere.\u201d<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/08\/community-hub-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-111491 alignleft\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/08\/community-hub-2-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/08\/community-hub-2-300x225.jpg 300w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/08\/community-hub-2-768x576.jpg 768w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/08\/community-hub-2.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><br \/>\n<\/a>Un altro passo in avanti che segue quello dell\u2019apertura dell\u2019aula studio, simbolo che la nuova realt\u00e0 \u00e8 attenta alle esigenze della comunit\u00e0 studentesca e che a Brindisi ci sono dei ragazzi che si organizzano e che collaborano per il bene comune.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cRaccogliamo i libri, cataloghiamoli, leggiamoli, discutiamone, scambiamoceli. Autorganizziamo un nuovo modo di fare cultura, di renderla una risposta pratica ad un bisogno collettivo e diffuso. La condivisione e la comunit\u00e0 sono il mezzo e lo strumento per arrivare a ci\u00f2.\u201d<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/08\/Porta-un-Libro-community-hub.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-111909\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/08\/Porta-un-Libro-community-hub-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/08\/Porta-un-Libro-community-hub-300x300.jpg 300w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/08\/Porta-un-Libro-community-hub-150x150.jpg 150w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/08\/Porta-un-Libro-community-hub-768x768.jpg 768w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/08\/Porta-un-Libro-community-hub-600x600.jpg 600w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/08\/Porta-un-Libro-community-hub-60x60.jpg 60w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/08\/Porta-un-Libro-community-hub.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Tutti coloro che volessero aiutarci, donando un libro per far crescere la nostra Biblioteca Sociale, possono scrivere una mail al seguente indirizzo communityhubrindisi@gmail.com o possono contattare la pagina Facebook dell\u2019Associazione Community Hub \u2013 Brindisi.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Continueremo a offrire spazio e ospitalit\u00e0 a chiunque ne faccia richiesta, cos\u00ec come attenderemo a braccia aperte le realt\u00e0 che intendono collaborare con noi. Vi aspettiamo presto la nostra sede in Via Saponea 58. Condividiamo esperienze, saperi e momenti&#8221;<\/p>\n<p>#DettoFatto #CommunityHuBrindisi<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Community Hub Brindisi<a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/08\/community-hub-2.jpg\"><br \/>\n<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La nascente Associazione Community Hub Brindisi, al fine di allargare ancora di pi\u00f9 l\u2019offerta della sede e agevolare i giovani nella propria crescita culturale, ha allestito una Biblioteca Sociale all&#8217;interno degli spazi della sede in Via Saponea 58. &nbsp; Chiunque voglia donare i propri libri, dalla narrativa alla saggistica, pu\u00f2 contattarci contribuendo cos\u00ec alla crescita di un nuovo polo culturale della citt\u00e0. &nbsp; \u201cCome Community Hub Brindisi, vogliamo promuovere la Cultura anche con semplici gesti ed iniziative: per questo chiediamo ai cittadini, alle librerie, alle case editrici presenti sul territorio, di aiutarci a costruire un vero e proprio polo della condivisione del sapere.\u201d &nbsp; Un altro passo in avanti che segue quello dell\u2019apertura dell\u2019aula studio, simbolo che la nuova realt\u00e0 \u00e8 attenta alle esigenze della comunit\u00e0 studentesca e che a Brindisi ci sono dei ragazzi che si organizzano e che collaborano per il bene comune. &nbsp; \u201cRaccogliamo i libri, cataloghiamoli, leggiamoli, discutiamone, scambiamoceli. Autorganizziamo un nuovo modo di fare cultura, di renderla una risposta pratica ad un bisogno collettivo e&#8230;<\/p>\n","protected":false},"author":2,"featured_media":111910,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[4759],"class_list":["post-111908","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-community-hub"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/111908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=111908"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/111908\/revisions"}],"predecessor-version":[{"id":111911,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/111908\/revisions\/111911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/111910"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=111908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=111908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=111908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}