{"id":112505,"date":"2017-09-07T12:53:50","date_gmt":"2017-09-07T10:53:50","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=112505"},"modified":"2017-09-08T11:12:22","modified_gmt":"2017-09-08T09:12:22","slug":"abusi-su-suolo-pubblico-pesante-multa-a-noto-lido-di-specchiolla","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/abusi-su-suolo-pubblico-pesante-multa-a-noto-lido-di-specchiolla\/","title":{"rendered":"Abusi su suolo pubblico: pesante multa a noto lido di Specchiolla"},"content":{"rendered":"<p>Nella giornata di marted\u00ec \u00e8 stato controllato un noto stabilimento balneare in localit\u00e0 Specchiolla del comune di Carovigno. Ad eseguire i controlli nello stabilimento balneare sono stati i militari del nucleo di Polizia Giudiziaria della Capitaneria di Porto di Brindisi e i militari del Comando Legione Carabinieri Puglia della Stazione di Carovigno. Il titolare dello stabilimento balneare e il gestore, avevano installato opere abusive prive delle prescritte autorizzazioni su suolo del demanio marittimo in concessione, occupato un\u2019area demaniale senza autorizzazione e violato norme ambientali.<\/p>\n<p>&nbsp;<\/p>\n<p>In particolare, occupavano un\u2019area demaniale marittima di mq 350 mq circa per adibirla a parcheggio asservito alla struttura balneare, delimitandola con paletti e catena. All\u2019interno della stessa area demaniale marittima retrostante la loro concessione, avevano creato un\u2019 aiuola rettangolare realizzata in legno di 30 mq; mentre all\u2019interno dell\u2019area demaniale marittima in concessione realizzavano senza autorizzazione una struttura di mq. 30 composta da intelaiatura in ferro, pedane in legno e copertura in cannucciato adibita a locale Cucina. Realizzavano sempre all\u2019interno dell\u2019area in concessione e senza autorizzazione una struttura rettangolare sopraelevata di mq. 36 composta da opere in legno con al centro una vasca idromassaggio.<\/p>\n<p>&nbsp;<\/p>\n<p>\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-112505 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.brundisium.net\/index.php\/abusi-su-suolo-pubblico-pesante-multa-a-noto-lido-di-specchiolla\/guardia-costiera-specchiolla-5\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/09\/GUARDIA-COSTIERA-SPECCHIOLLA-5-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/09\/GUARDIA-COSTIERA-SPECCHIOLLA-5-150x150.jpg 150w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/09\/GUARDIA-COSTIERA-SPECCHIOLLA-5-600x600.jpg 600w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/09\/GUARDIA-COSTIERA-SPECCHIOLLA-5-60x60.jpg 60w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.brundisium.net\/index.php\/abusi-su-suolo-pubblico-pesante-multa-a-noto-lido-di-specchiolla\/guardia-costiera-specchiolla-6\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/09\/GUARDIA-COSTIERA-SPECCHIOLLA-6-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/09\/GUARDIA-COSTIERA-SPECCHIOLLA-6-150x150.jpg 150w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/09\/GUARDIA-COSTIERA-SPECCHIOLLA-6-600x600.jpg 600w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/09\/GUARDIA-COSTIERA-SPECCHIOLLA-6-60x60.jpg 60w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.brundisium.net\/index.php\/abusi-su-suolo-pubblico-pesante-multa-a-noto-lido-di-specchiolla\/guardia-costiera-specchiolla-7\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/09\/GUARDIA-COSTIERA-SPECCHIOLLA-7-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/09\/GUARDIA-COSTIERA-SPECCHIOLLA-7-150x150.jpg 150w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/09\/GUARDIA-COSTIERA-SPECCHIOLLA-7-600x600.jpg 600w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/09\/GUARDIA-COSTIERA-SPECCHIOLLA-7-60x60.jpg 60w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n<br \/>\n&nbsp;<\/p>\n<p>Per tali abusi, i responsabili sono stati deferiti all\u2019Autorit\u00e0 Giudiziaria in violazioni agli artt. 142, 146 e 181 del D.Lgs. 42\/2004, artt. 54, e 1161 del Codice della Navigazione, art. 24 del Regolamento di Attuazione del Codice di Navigazione e le opere sequestrate.<\/p>\n<p>&nbsp;<\/p>\n<p>Sul posto \u00e8 stato richiesto, l\u2019intervento del Servizio Igiene e Sanit\u00e0 dell\u2019Asl di Brindisi che procedevano ai sensi dell\u2019art. 54 del Reg. CEE 852\/04 alla chiusura dell\u2019attivit\u00e0 di ristorazione in quanto non autorizzata.<\/p>\n<p>&nbsp;<\/p>\n<p>Durante il controllo, si riscontravano delle irregolarit\u00e0 in materia ambientale, relative allo scarico di acque reflue proveniente dai servizi della struttura balneare, non autorizzato ai sensi dell\u2019articolo 124 del Decreto Legislativo 152\/2006 (Testo Unico sull\u2019Ambiente) che prevede una sanzione massima di \u20ac. 60.000,00 (sessantamila); inoltre veniva elevata una sanzione si sensi dell\u2019Ordinanza Balneare della Regione Puglia, per aver asportato la Posidonia Oceanica dalla spiaggia in concessione stoccandola in un\u2019area demaniale adiacente, per tale violazione veniva comminata una sanzione amministrativa dell\u2019importo massimo di 3.098 euro.<\/p>\n<p>&nbsp;<\/p>\n<p>Anche questa volta, gli abusi non sono passati inosservati grazie anche alla preziosa e sinergica collaborazione dei militari del nucleo di Polizia Giudiziaria della Capitaneria di Porto di Brindisi, dei militari del Comando Legione Carabinieri Puglia della Stazione di Carovigno e del Servizio Igiene e Sanit\u00e0 dell\u2019Asl di Brindisi.<br \/>\nTali attivit\u00e0 sono tese a ristabilire un regime di equit\u00e0 a favore degli operatori del settore turistico che, operano nel rispetto delle regole.<br \/>\n&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>COMUNICATO STAMPA GUARDIA COSTIERA<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella giornata di marted\u00ec \u00e8 stato controllato un noto stabilimento balneare in localit\u00e0 Specchiolla del comune di Carovigno. Ad eseguire i controlli nello stabilimento balneare sono stati i militari del nucleo di Polizia Giudiziaria della Capitaneria di Porto di Brindisi e i militari del Comando Legione Carabinieri Puglia della Stazione di Carovigno. Il titolare dello stabilimento balneare e il gestore, avevano installato opere abusive prive delle prescritte autorizzazioni su suolo del demanio marittimo in concessione, occupato un\u2019area demaniale senza autorizzazione e violato norme ambientali. &nbsp; In particolare, occupavano un\u2019area demaniale marittima di mq 350 mq circa per adibirla a parcheggio asservito alla struttura balneare, delimitandola con paletti e catena. All\u2019interno della stessa area demaniale marittima retrostante la loro concessione, avevano creato un\u2019 aiuola rettangolare realizzata in legno di 30 mq; mentre all\u2019interno dell\u2019area demaniale marittima in concessione realizzavano senza autorizzazione una struttura di mq. 30 composta da intelaiatura in ferro, pedane in legno e copertura in cannucciato adibita a locale Cucina. Realizzavano sempre all\u2019interno dell\u2019area in concessione e senza autorizzazione&#8230;<\/p>\n","protected":false},"author":2,"featured_media":112511,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[801,543],"class_list":["post-112505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-guardia-costiera","tag-specchiolla"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/112505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=112505"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/112505\/revisions"}],"predecessor-version":[{"id":112515,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/112505\/revisions\/112515"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/112511"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=112505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=112505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=112505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}