{"id":113205,"date":"2017-09-16T18:27:42","date_gmt":"2017-09-16T16:27:42","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=113205"},"modified":"2017-09-16T18:27:42","modified_gmt":"2017-09-16T16:27:42","slug":"mons-galantino-segretario-generale-cei-apre-il-convegno-ecclesiale-della-diocesi-di-oria","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/mons-galantino-segretario-generale-cei-apre-il-convegno-ecclesiale-della-diocesi-di-oria\/","title":{"rendered":"Mons. Galantino, Segretario generale CEI, apre il Convegno ecclesiale della Diocesi di Oria"},"content":{"rendered":"<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/09\/Manifesto-Convegno-Diocesano-2017-Oria.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/09\/Manifesto-Convegno-Diocesano-2017-Oria-209x300.jpg\" alt=\"\" width=\"209\" height=\"300\" class=\"alignleft size-medium wp-image-113206\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/09\/Manifesto-Convegno-Diocesano-2017-Oria-209x300.jpg 209w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/09\/Manifesto-Convegno-Diocesano-2017-Oria-714x1024.jpg 714w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/09\/Manifesto-Convegno-Diocesano-2017-Oria.jpg 738w\" sizes=\"auto, (max-width: 209px) 100vw, 209px\" \/><\/a> <\/p>\n<p>Dal 18 al 20 settembre 2017, presso il Santuario di San Cosimo alla Macchia in Oria (Br), si terr\u00e0 l&#8217;annuale Convegno ecclesiale diocesano.<\/p>\n<p>I lavori del convegno, dal titolo &#8220;Il seminatore usc\u00ec a seminare&#8221;, si svolgeranno secondo il programma di seguito indicato e saranno introdotti dall&#8217;intervento di S.E. mons. Nunzio Galantino, segretario generale della Conferenza Episcopale Italiana.<\/p>\n<p>PROGRAMMA<\/p>\n<p>luned\u00ec 18 settembre 2017<\/p>\n<p>ore 18.00 &#8211; Solenne santa Messa nella nuova chiesa di San Giovanni Paolo II presso il Santuario di San Cosimo alla Macchia, presieduta da mons. Nunzio Galantino, segretario generale della Conferenza Episcopale Italiana.<\/p>\n<p>ore 19.00 &#8211; Intervento introduttivo al convegno di mons. Nunzio Galantino.<\/p>\n<p>marted\u00ec 19 settembre 2017<\/p>\n<p>(i lavori si svolgeranno nei tre Vicariati della Diocesi, nei luoghi che saranno indicati)<\/p>\n<p>ore 19.30 &#8211; Incontro di confronto e condivisione per Vicariati.<\/p>\n<p>mercoled\u00ec 20 settembre 2017<\/p>\n<p>ore 19.30 &#8211; Ascolto del lavoro prodotto nei tre Vicariati. Conclusioni e indicazioni pastorale di S.E. mons. Vincenzo Pisanello, vescovo di Oria.<\/p>\n<p>Ufficio per le Comunicazioni sociali e la Cultura della Diocesi di Oria<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal 18 al 20 settembre 2017, presso il Santuario di San Cosimo alla Macchia in Oria (Br), si terr\u00e0 l&#8217;annuale Convegno ecclesiale diocesano. I lavori del convegno, dal titolo &#8220;Il seminatore usc\u00ec a seminare&#8221;, si svolgeranno secondo il programma di seguito indicato e saranno introdotti dall&#8217;intervento di S.E. mons. Nunzio Galantino, segretario generale della Conferenza Episcopale Italiana. PROGRAMMA luned\u00ec 18 settembre 2017 ore 18.00 &#8211; Solenne santa Messa nella nuova chiesa di San Giovanni Paolo II presso il Santuario di San Cosimo alla Macchia, presieduta da mons. Nunzio Galantino, segretario generale della Conferenza Episcopale Italiana. ore 19.00 &#8211; Intervento introduttivo al convegno di mons. Nunzio Galantino. marted\u00ec 19 settembre 2017 (i lavori si svolgeranno nei tre Vicariati della Diocesi, nei luoghi che saranno indicati) ore 19.30 &#8211; Incontro di confronto e condivisione per Vicariati. mercoled\u00ec 20 settembre 2017 ore 19.30 &#8211; Ascolto del lavoro prodotto nei tre Vicariati. Conclusioni e indicazioni pastorale di S.E. mons. Vincenzo Pisanello, vescovo di Oria. Ufficio per le Comunicazioni sociali e la Cultura della Diocesi&#8230;<\/p>\n","protected":false},"author":2,"featured_media":113206,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1790,294],"class_list":["post-113205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-diocesi-di-oria","tag-oria"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/113205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=113205"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/113205\/revisions"}],"predecessor-version":[{"id":113207,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/113205\/revisions\/113207"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/113206"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=113205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=113205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=113205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}