{"id":11450,"date":"2014-04-18T16:00:25","date_gmt":"2014-04-18T14:00:25","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=11450"},"modified":"2014-04-22T12:58:50","modified_gmt":"2014-04-22T10:58:50","slug":"messaggio-del-vescovo-di-oria-per-la-pasqua-2014","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/messaggio-del-vescovo-di-oria-per-la-pasqua-2014\/","title":{"rendered":"Messaggio del Vescovo di Oria per la Pasqua 2014"},"content":{"rendered":"<p><em>Poich\u00e9 dunque i figli hanno in comune il sangue e la carne, anche Cristo allo stesso modo ne \u00e8 divenuto partecipe, per ridurre all\u2019impotenza mediante la morte colui che della morte ha il potere, cio\u00e8 il diavolo, e liberare cos\u00ec quelli che, per timore della morte, erano soggetti a schiavit\u00f9 per tutta la vita<\/em>\u201d (Eb 2, 14-15).<\/p>\n<p>&nbsp;<\/p>\n<p>Siamo stati ridotti in schiavit\u00f9 per tutta la vita e non ce ne accorgiamo! Credo che sia giunto il momento in cui chiederci in tutta verit\u00e0: di chi siamo schiavi? E come siamo tenuti in schiavit\u00f9?<\/p>\n<p>La lettera agli Ebrei ci aiuta a fare chiarezza della nostra situazione e del dono che ci \u00e8 stato fatto dal Padre della misericordia. Siamo schiavi di chi ha il potere della morte, e siamo tenuti in schiavit\u00f9 perch\u00e9 abbiamo timore della morte.<\/p>\n<p>La morte \u00e8 entrata nella vita dell\u2019uomo e nel mondo a causa del peccato (Sap 2, 24), ed ogni peccato, anche di lieve entit\u00e0, genera morte perch\u00e9 interrompe il flusso della grazia, della linfa vitale che proviene da Dio e dal Suo Spirito, \u201c<em>che \u00e8 Signore e d\u00e0 la vita<\/em>\u201d.<\/p>\n<p>L\u2019uomo \u00e8 stato creato per la vita, non solamente quella biologica, ma anche e soprattutto quella soprannaturale e quando l\u2019inganno del principe di questo mondo gli fa percepire che la morte \u00e8 la fine di ogni cosa, questa fragile creatura s\u2019intimorisce e, desiderando la vita per sempre, si lascia incatenare da questa paura. Cos\u00ec il peccato genera la morte e la morte, incutendoci paura,ci tiene prigionieri.<\/p>\n<p>&nbsp;<\/p>\n<p>Come poter uscire da questo labirinto?<\/p>\n<p>Dobbiamo riconoscere, in tutta verit\u00e0, che non siamo capaci di liberarci dalla paura della morte, e cos\u00ec rimaniamo schiavi!<\/p>\n<p>Anche Ges\u00f9 ha avuto paura della morte e della prigionia che questa sembra portare: \u201c<em>Padre mio, se \u00e8 possibile, passi da me questo calice!\u201d<\/em>. Ma il Suo atto di fiducia e di obbedienza al Padre &#8211; \u201c<em>Per\u00f2 non come voglio io, ma come vuoi tu!<\/em>\u201d(Mt 26, 39) \u2013 lo ha fatto entrare proprio nella morte perch\u00e9 questa fosse sconfitta nell\u2019unico modo possibile: dal di dentro!<\/p>\n<p>E cos\u00ec lo Spirito di Dio, \u201c<em>che \u00e8 Signore e d\u00e0 la vita<\/em>\u201d, resuscitando Ges\u00f9 dalla morte ha infranto definitivamente le catene della schiavit\u00f9 dell\u2019uomo.<\/p>\n<p>Cos\u00ec il grido della notte di Pasqua \u201c<em>\u00c8 risorto<\/em>!\u201d non si riferisce solo alla persona di Ges\u00f9, ma all\u2019intera umanit\u00e0! Tutto l\u2019uomo, ogni uomo che si consegna nelle mani del Padre attraverso l\u2019umanit\u00e0 di Ges\u00f9, \u00e8 risorto, \u00e8 vivo, ha sconfitto la morte e la paura di questa! L\u2019uomo non \u00e8 pi\u00f9 schiavo, \u00e8 libero, \u00e8 liberato dal Cristo risorto.<\/p>\n<p>&nbsp;<\/p>\n<p>Ecco la nostra nuova condizione: non pi\u00f9 schiavi, perch\u00e9 la morte e la paura che di essa ci teneva prigionieri \u00e8 stata sconfitta dalla morte e resurrezione di Ges\u00f9, ma uomini liberi, figli beati perch\u00e9 amati ed in grado di amare.<\/p>\n<p>Professare la propria fede nella resurrezione \u00e8 riconoscere il proprio stato di libert\u00e0. Non lasciamoci incatenare dal peccato per non cadere nuovamente nella paura della morte, ma viviamo da figli della resurrezione. Cristo \u00e8 risorto. E anche noi con Lui. Auguri.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>+ Vincenzo Pisanello<\/strong><\/p>\n<p>Vescovo di Oria<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Poich\u00e9 dunque i figli hanno in comune il sangue e la carne, anche Cristo allo stesso modo ne \u00e8 divenuto partecipe, per ridurre all\u2019impotenza mediante la morte colui che della morte ha il potere, cio\u00e8 il diavolo, e liberare cos\u00ec quelli che, per timore della morte, erano soggetti a schiavit\u00f9 per tutta la vita\u201d (Eb 2, 14-15). &nbsp; Siamo stati ridotti in schiavit\u00f9 per tutta la vita e non ce ne accorgiamo! Credo che sia giunto il momento in cui chiederci in tutta verit\u00e0: di chi siamo schiavi? E come siamo tenuti in schiavit\u00f9? La lettera agli Ebrei ci aiuta a fare chiarezza della nostra situazione e del dono che ci \u00e8 stato fatto dal Padre della misericordia. Siamo schiavi di chi ha il potere della morte, e siamo tenuti in schiavit\u00f9 perch\u00e9 abbiamo timore della morte. La morte \u00e8 entrata nella vita dell\u2019uomo e nel mondo a causa del peccato (Sap 2, 24), ed ogni peccato, anche di lieve entit\u00e0, genera morte perch\u00e9 interrompe il flusso della grazia, della&#8230;<\/p>\n","protected":false},"author":2,"featured_media":11451,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1675,1754],"class_list":["post-11450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-pasqua-2014","tag-vescovo-di-oria"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/11450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=11450"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/11450\/revisions"}],"predecessor-version":[{"id":11452,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/11450\/revisions\/11452"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/11451"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=11450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=11450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=11450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}