{"id":115524,"date":"2017-10-14T08:00:39","date_gmt":"2017-10-14T06:00:39","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=115524"},"modified":"2017-10-14T11:58:52","modified_gmt":"2017-10-14T09:58:52","slug":"io-non-rischio-oggi-a-brindisi-la-campagna-nazionale-per-le-buone-pratiche-di-protezione-civile","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/io-non-rischio-oggi-a-brindisi-la-campagna-nazionale-per-le-buone-pratiche-di-protezione-civile\/","title":{"rendered":"Io non rischio: oggi a Brindisi la campagna nazionale per le buone pratiche di protezione civile"},"content":{"rendered":"<p>Il volontariato di protezione civile, le istituzioni e il mondo della ricerca scientifica si impegnano insieme per comunicare sui rischi naturali che interessano il nostro Paese. Il 14 ottobre volontari e volontarie di protezione civile allestiranno punti informativi \u201cIo non rischio\u201d nelle piazze dei capoluoghi di provincia italiani, per diffondere la cultura della prevenzione e sensibilizzare i propri concittadini sul rischio sismico, sul rischio alluvione e sul maremoto.<\/p>\n<p>&nbsp;<\/p>\n<p>Il cuore dell\u2019iniziativa \u2013 giunta quest\u2019anno alla settima edizione \u2013 \u00e8 il momento dell\u2019incontro in piazza tra i volontari formati e la cittadinanza. Ma l\u2019edizione 2017 sar\u00e0 un\u2019occasione speciale, perch\u00e9 le piazze si arricchiranno di iniziative ed eventi: i volontari, infatti, accompagneranno la cittadinanza in un percorso legato alla conoscenza dei rischi specifici del territorio e alla memoria dei luoghi.<\/p>\n<p>&nbsp;<\/p>\n<p>Sabato 14 ottobre, in contemporanea con le altre citt\u00e0 in tutta Italia, anche Brindisi partecipa alla campagna \u201cIo non rischio\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Per scoprire cosa ciascuno di noi pu\u00f2 fare per ridurre il rischio terremoto, rischio maremoto, rischio alluvione l\u2019appuntamento \u00e8 in Piazza Vittoria, Piazza Duomo e Piazza Santa Teresa. Oltre al punto informativo, quest\u2019anno i volontari invitano ad un appuntamento speciale: trekking urbano con partenza in varie fasce orarie.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019edizione 2017 coinvolge volontari e volontarie appartenenti a oltre 700 realt\u00e0 associative, tra sezioni locali delle organizzazioni nazionali di volontariato, gruppi comunali e associazioni locali di tutte le regioni d\u2019Italia.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cIo non rischio\u201d \u2013 campagna nata nel 2011 per sensibilizzare la popolazione sul rischio sismico \u2013 \u00e8 promossa dal Dipartimento della Protezione Civile con Anpas-Associazione Nazionale Pubbliche Assistenze, Ingv-Istituto Nazionale di Geofisica e Vulcanologia e Reluis-Rete dei Laboratori Universitari di Ingegneria Sismica. L\u2019inserimento del rischio maremoto e del rischio alluvione ha visto il coinvolgimento di Ispra-Istituto superiore per la Protezione e la Ricerca Ambientale, Ogs-Istituto Nazionale di Oceanografia e di Geofisica Sperimentale, AiPo-Agenzia Interregionale per il fiume Po, Arpa Emilia-Romagna, Autorit\u00e0 di Bacino del fiume Arno, CamiLab-Universit\u00e0 della Calabria, Fondazione Cima e Irpi-Istituto di ricerca per la Protezione idro-geologica.<\/p>\n<p>&nbsp;<\/p>\n<p>Sul sito ufficiale della campagna, www.iononrischio.it, \u00e8 possibile consultare i materiali informativi su cosa sapere e cosa fare prima, durante e dopo un terremoto o un maremoto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il volontariato di protezione civile, le istituzioni e il mondo della ricerca scientifica si impegnano insieme per comunicare sui rischi naturali che interessano il nostro Paese. Il 14 ottobre volontari e volontarie di protezione civile allestiranno punti informativi \u201cIo non rischio\u201d nelle piazze dei capoluoghi di provincia italiani, per diffondere la cultura della prevenzione e sensibilizzare i propri concittadini sul rischio sismico, sul rischio alluvione e sul maremoto. &nbsp; Il cuore dell\u2019iniziativa \u2013 giunta quest\u2019anno alla settima edizione \u2013 \u00e8 il momento dell\u2019incontro in piazza tra i volontari formati e la cittadinanza. Ma l\u2019edizione 2017 sar\u00e0 un\u2019occasione speciale, perch\u00e9 le piazze si arricchiranno di iniziative ed eventi: i volontari, infatti, accompagneranno la cittadinanza in un percorso legato alla conoscenza dei rischi specifici del territorio e alla memoria dei luoghi. &nbsp; Sabato 14 ottobre, in contemporanea con le altre citt\u00e0 in tutta Italia, anche Brindisi partecipa alla campagna \u201cIo non rischio\u201d. &nbsp; Per scoprire cosa ciascuno di noi pu\u00f2 fare per ridurre il rischio terremoto, rischio maremoto, rischio alluvione l\u2019appuntamento \u00e8&#8230;<\/p>\n","protected":false},"author":2,"featured_media":115525,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[5049,128],"class_list":["post-115524","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-io-non-rischio","tag-protezione-civile"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/115524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=115524"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/115524\/revisions"}],"predecessor-version":[{"id":115526,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/115524\/revisions\/115526"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/115525"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=115524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=115524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=115524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}