{"id":115944,"date":"2017-10-18T20:25:22","date_gmt":"2017-10-18T18:25:22","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=115944"},"modified":"2017-10-19T15:04:38","modified_gmt":"2017-10-19T13:04:38","slug":"biodiversita-nel-parco-delle-dune-costiere-domenica-appuntamento-con-le-farfalle-del-parco","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/biodiversita-nel-parco-delle-dune-costiere-domenica-appuntamento-con-le-farfalle-del-parco\/","title":{"rendered":"Biodiversit\u00e0 nel Parco delle Dune Costiere: domenica appuntamento con &#8220;Le farfalle del Parco&#8221;"},"content":{"rendered":"<p>Continuano gli incontri e le passeggiate tematiche sulla biodiversit\u00e0 nel Parco delle Dune Costiere.<\/p>\n<p>&nbsp;<\/p>\n<p>Domenica 22 Ottobre appuntamento alle 9:30 all\u00b4Albergabici con &#8220;Le farfalle del Parco&#8221;, dove saranno presentati i risultati delle ricerche che l\u00b4associazione Polyxena ha condotto negli ultimi anni nei diversi habitat del Parco. Si parler\u00e0 delle metodologie, dei risultati e delle importanti sviluppi che il progetto RADAR avr\u00e0 nel prossimo futuro. La mattinata si concluder\u00e0 con una passeggiata nell\u00b4 ex-cava di Pezze Caldara, dove i partecipanti saranno coinvolti nelle attivit\u00e0 di ricerca diventando &#8220;scienziati per un giorno&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>Sar\u00e0 anche l\u00b4occasione per presentare la pubblicazione &#8220;Ali sulle Dune&#8221; (Grecale Edizioni) che illustra le numerose specie di farfalle che \u00e8 possibile incontrare sui sentieri del Parco. Un utile strumento per far s\u00ec che ognuno possa vivere, in prima persona, l\u00b4emozione di osservare questi bellissimi insetti in modo ravvicinato, oltre che l\u00b4ideale compagno di viaggio del &#8220;turista lento&#8221; e del &#8220;curioso di natura&#8221; per una escursione nell\u00b4Area protetta.<\/p>\n<p>&nbsp;<\/p>\n<p>Per raggiungere l\u00b4Albergabici: Ex-Casa Cantoniera Anas di Montalbano di Fasano, ex S.S. 16 Fasano-Ostuni km 870.(Coordinate geografiche: 40\u00b046\u00b451.41&#8243;N 17\u00b029\u00b41.06&#8243;E).<\/p>\n<p>&nbsp;<\/p>\n<p>Per info<\/p>\n<p>Cell: +39 392 252 5812<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Continuano gli incontri e le passeggiate tematiche sulla biodiversit\u00e0 nel Parco delle Dune Costiere. &nbsp; Domenica 22 Ottobre appuntamento alle 9:30 all\u00b4Albergabici con &#8220;Le farfalle del Parco&#8221;, dove saranno presentati i risultati delle ricerche che l\u00b4associazione Polyxena ha condotto negli ultimi anni nei diversi habitat del Parco. Si parler\u00e0 delle metodologie, dei risultati e delle importanti sviluppi che il progetto RADAR avr\u00e0 nel prossimo futuro. La mattinata si concluder\u00e0 con una passeggiata nell\u00b4 ex-cava di Pezze Caldara, dove i partecipanti saranno coinvolti nelle attivit\u00e0 di ricerca diventando &#8220;scienziati per un giorno&#8221;. &nbsp; Sar\u00e0 anche l\u00b4occasione per presentare la pubblicazione &#8220;Ali sulle Dune&#8221; (Grecale Edizioni) che illustra le numerose specie di farfalle che \u00e8 possibile incontrare sui sentieri del Parco. Un utile strumento per far s\u00ec che ognuno possa vivere, in prima persona, l\u00b4emozione di osservare questi bellissimi insetti in modo ravvicinato, oltre che l\u00b4ideale compagno di viaggio del &#8220;turista lento&#8221; e del &#8220;curioso di natura&#8221; per una escursione nell\u00b4Area protetta. &nbsp; Per raggiungere l\u00b4Albergabici: Ex-Casa Cantoniera Anas di Montalbano di&#8230;<\/p>\n","protected":false},"author":2,"featured_media":115945,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[640],"class_list":["post-115944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-parco-dune-costiere"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/115944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=115944"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/115944\/revisions"}],"predecessor-version":[{"id":115946,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/115944\/revisions\/115946"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/115945"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=115944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=115944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=115944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}