{"id":116182,"date":"2017-10-21T22:39:20","date_gmt":"2017-10-21T20:39:20","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=116182"},"modified":"2017-10-21T22:39:20","modified_gmt":"2017-10-21T20:39:20","slug":"sporcatevi-le-mani-prosegue-a-brindisi-la-campagna-di-sensibilizzazione-nei-confronti-dellautismo","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/sporcatevi-le-mani-prosegue-a-brindisi-la-campagna-di-sensibilizzazione-nei-confronti-dellautismo\/","title":{"rendered":"Sporcatevi le mani: prosegue a Brindisi la campagna di sensibilizzazione nei confronti dell&#8217;Autismo"},"content":{"rendered":"<p>Prosegue a Brindisi la campagna di sensibilizzazione a favore dell\u2019Autismo con Fata Anna di Brindisi, la mamma di un bimbo autistico di nove anni e Fata Rosella di Mesagne entrambe sostenitrici e promotrici della Campagna Nazionale di raccolta fondi SPORCATEVI LE MANI, a sostegno dell\u2019Associazione &#8220;Il Bene che Ti Voglio&#8221; per la realizzazione di un importante progetto per Bambini e Ragazzi autistici di Brindisi e provincia.<\/p>\n<p>&nbsp;<\/p>\n<p>Luned\u00ec 23 ottobre alle ore 20.00 presso Venti &amp; Venti interverranno il responsabile della Campagna SPORCATEVI LE MANI promossa dall\u2019Associazione Nazionale I Bambini delle Fate, Samuel Mazzolin, l\u2019Associazione Il Bene che ti Voglio e Fate Anna e Rosella.<\/p>\n<p>L\u2019evento rappresenta un momento di condivisione con i gi\u00e0 sostenitori del Progetto ma la partecipazione \u00e8 aperta a tutti .<\/p>\n<p>&nbsp;<\/p>\n<p>La Campagna SPORCATEVI LE MANI vuole essere una risposta concreta alle necessit\u00e0 di molteplici famiglie, che grazie ai \u201cDonatori Responsabili\u201d, possono cos\u00ec far accedere i propri figli a progetti che migliorano sensibilmente la prognosi e le prospettive di inserimento sociale, contribuendo a realizzare una vera e propria inclusione sociale.<\/p>\n<p>&nbsp;<\/p>\n<p>Diversi sono i progetti attivati gi\u00e0 finanziati da I Bambini delle Fate in tutta Italia.<\/p>\n<p>&nbsp;<\/p>\n<p>Questa \u00e8 un\u2019opportunit\u00e0 anche per Brindisi e provincia per tutti i nostri Bambini e Ragazzi Speciali.<\/p>\n<p>&nbsp;<\/p>\n<p>Rinunciare ad un caffe\u2019 al giorno significa \u201coffrire il pane quotidiano a chi ne ha bisogno\u201d e avere nel cuore un po\u2019 pi\u00f9 di felicit\u00e0: Questo il messaggio che si vuole trasmettere con questa lodevole l\u2019iniziativa a tutta la collettivit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prosegue a Brindisi la campagna di sensibilizzazione a favore dell\u2019Autismo con Fata Anna di Brindisi, la mamma di un bimbo autistico di nove anni e Fata Rosella di Mesagne entrambe sostenitrici e promotrici della Campagna Nazionale di raccolta fondi SPORCATEVI LE MANI, a sostegno dell\u2019Associazione &#8220;Il Bene che Ti Voglio&#8221; per la realizzazione di un importante progetto per Bambini e Ragazzi autistici di Brindisi e provincia. &nbsp; Luned\u00ec 23 ottobre alle ore 20.00 presso Venti &amp; Venti interverranno il responsabile della Campagna SPORCATEVI LE MANI promossa dall\u2019Associazione Nazionale I Bambini delle Fate, Samuel Mazzolin, l\u2019Associazione Il Bene che ti Voglio e Fate Anna e Rosella. L\u2019evento rappresenta un momento di condivisione con i gi\u00e0 sostenitori del Progetto ma la partecipazione \u00e8 aperta a tutti . &nbsp; La Campagna SPORCATEVI LE MANI vuole essere una risposta concreta alle necessit\u00e0 di molteplici famiglie, che grazie ai \u201cDonatori Responsabili\u201d, possono cos\u00ec far accedere i propri figli a progetti che migliorano sensibilmente la prognosi e le prospettive di inserimento sociale, contribuendo a realizzare una&#8230;<\/p>\n","protected":false},"author":2,"featured_media":110632,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[3680,5086],"class_list":["post-116182","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-autismo","tag-sporcatevi-le-mani"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/116182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=116182"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/116182\/revisions"}],"predecessor-version":[{"id":116183,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/116182\/revisions\/116183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/110632"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=116182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=116182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=116182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}