{"id":117111,"date":"2017-11-02T18:59:17","date_gmt":"2017-11-02T17:59:17","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=117111"},"modified":"2017-11-08T16:44:24","modified_gmt":"2017-11-08T15:44:24","slug":"travel-enjoy-respect-la-puglia-e-di-tutti-lo-splendido-video-girato-al-parco-dune-costiere","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/travel-enjoy-respect-la-puglia-e-di-tutti-lo-splendido-video-girato-al-parco-dune-costiere\/","title":{"rendered":"TRAVEL. ENJOY. RESPECT. La Puglia \u00e8 di tutti: lo splendido video girato al Parco Dune Costiere"},"content":{"rendered":"<p>Vogliamo diffondere questo video e farlo vedere al maggior numero di persone possibile.<br \/>\n<iframe loading=\"lazy\" style=\"border: currentColor; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?href=https%3A%2F%2Fwww.facebook.com%2Fviaggiareinpuglia.it%2Fvideos%2F10154631581206324%2F&amp;show_text=0&amp;width=560\" width=\"560\" height=\"315\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Lo ha realizzato il Parco delle Dune Costiere e parla di sostenibilit\u00e0, di turismo responsabile e, quindi, anche di rispetto dell\u2019ambiente.<br \/>\nInteressa quindi tutti noi pugliesi e chiunque ami e abbia a cuore la Puglia &#x1f60a;<br \/>\nDedicategli un minuto, mettete un Like e condividetelo sul vostro profilo Facebook o sulle pagine che gestite.<br \/>\nInsieme, come sempre, lo possiamo far arrivare lontano!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vogliamo diffondere questo video e farlo vedere al maggior numero di persone possibile. Lo ha realizzato il Parco delle Dune Costiere e parla di sostenibilit\u00e0, di turismo responsabile e, quindi, anche di rispetto dell\u2019ambiente. Interessa quindi tutti noi pugliesi e chiunque ami e abbia a cuore la Puglia &#x1f60a; Dedicategli un minuto, mettete un Like e condividetelo sul vostro profilo Facebook o sulle pagine che gestite. Insieme, come sempre, lo possiamo far arrivare lontano!<\/p>\n","protected":false},"author":2,"featured_media":117112,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[640],"class_list":["post-117111","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-video","tag-parco-dune-costiere"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/117111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=117111"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/117111\/revisions"}],"predecessor-version":[{"id":117113,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/117111\/revisions\/117113"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/117112"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=117111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=117111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=117111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}