{"id":117785,"date":"2017-11-10T12:36:21","date_gmt":"2017-11-10T11:36:21","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=117785"},"modified":"2017-11-10T16:37:47","modified_gmt":"2017-11-10T15:37:47","slug":"la-cestistica-ostuni-si-separa-dal-greco-rafail-tsourakis","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/la-cestistica-ostuni-si-separa-dal-greco-rafail-tsourakis\/","title":{"rendered":"La Cestistica Ostuni si separa dal greco  Rafail Tsourakis"},"content":{"rendered":"<p>La Cestistica Ostuni comunica di aver raggiunto un accordo per la rescissione consensuale del contratto con Rafail Tsourakis, centro greco classe 1990 in giallobl\u00f9 dall&#8217;inizio di questa stagione. <\/p>\n<p>Nel ringraziare Rafail per quanto dato alla Cestistica in questo pur breve periodo, la societ\u00e0 gli augura il meglio per il futuro e un grande in bocca al lupo per la sua carriera.<\/p>\n<p>In 6 partite con la maglia ostunese, Tsourakis ha totalizzato 53 punti (8.8 punti a partita) con 6.2 rimbalzi, dando un buon contributo nelle 4 vittorie ottenute a Vieste, Santeramo, Ceglie e al PalaGentile contro Manfredonia.<\/p>\n<p>La Cestistica sta gi\u00e0 lavorando per individuare un sostituto allo stesso livello, che sia all&#8217;altezza delle ambizioni della societ\u00e0 e della citt\u00e0 e che sia compatibile a livello tecnico con il resto del roster. Nei prossimi giorni ulteriori novit\u00e0.<\/p>\n<p>Ufficio stampa e comunicazione &#8211; CESTISTICA OSTUNI<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Cestistica Ostuni comunica di aver raggiunto un accordo per la rescissione consensuale del contratto con Rafail Tsourakis, centro greco classe 1990 in giallobl\u00f9 dall&#8217;inizio di questa stagione. Nel ringraziare Rafail per quanto dato alla Cestistica in questo pur breve periodo, la societ\u00e0 gli augura il meglio per il futuro e un grande in bocca al lupo per la sua carriera. In 6 partite con la maglia ostunese, Tsourakis ha totalizzato 53 punti (8.8 punti a partita) con 6.2 rimbalzi, dando un buon contributo nelle 4 vittorie ottenute a Vieste, Santeramo, Ceglie e al PalaGentile contro Manfredonia. La Cestistica sta gi\u00e0 lavorando per individuare un sostituto allo stesso livello, che sia all&#8217;altezza delle ambizioni della societ\u00e0 e della citt\u00e0 e che sia compatibile a livello tecnico con il resto del roster. Nei prossimi giorni ulteriori novit\u00e0. Ufficio stampa e comunicazione &#8211; CESTISTICA OSTUNI<\/p>\n","protected":false},"author":2,"featured_media":2494,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[506],"class_list":["post-117785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket","tag-cestistica-ostuni"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/117785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=117785"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/117785\/revisions"}],"predecessor-version":[{"id":117786,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/117785\/revisions\/117786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/2494"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=117785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=117785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=117785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}