{"id":11818,"date":"2014-04-24T11:03:35","date_gmt":"2014-04-24T09:03:35","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=11818"},"modified":"2014-04-24T11:03:35","modified_gmt":"2014-04-24T09:03:35","slug":"corradino-de-pascalis-e-il-nuovo-presidente-della-azione-cattolica-della-diocesi-di-oria","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/corradino-de-pascalis-e-il-nuovo-presidente-della-azione-cattolica-della-diocesi-di-oria\/","title":{"rendered":"Corradino De Pascalis \u00e8 il nuovo Presidente della Azione Cattolica della Diocesi di Oria"},"content":{"rendered":"<p>Il Vescovo della Diocesi di Oria, S.E. Mons. Vincenzo Pisanello, con decreto del 17 aprile 2014 ha nominato il Sig. Corradino De Pascalis, Presidente della Azione Cattolica Diocesana per il triennio 2014-2017.<br \/>\nIl neo Presidente, sposato e con due figli, \u00e8 funzionario bibliotecario presso l\u2019Archivio di Stato di Brindisi, Ministero BAC, ha alle spalle una lunga militanza sindacale ed \u00e8 da sempre impegnato nel sociale. E\u2019socio di AC dal 2008 ed attualmente \u00e8 Presidente di AC parrocchiale Maria Immacolata di Ceglie Messapica.<\/p>\n<p>&nbsp;<\/p>\n<p>La Diocesi di Oria ha competenza territoriale su undici comuni ( Avetrana, Ceglie Messapica, Erchie, Francavilla Fontana, Latiano, Manduria, Maruggio, Oria, Sava, Torre S.Susanna, Villa Castelli) e conta 43 Parrocchie. Azione Cattolica in questo territorio conta associati, con una capillare presenza in tutte le parrocchie, dove svolge un servizio prezioso a sostegno dei parroci e dei sacerdoti.<\/p>\n<p>&nbsp;<\/p>\n<p>Nel corso del primo consiglio diocesano del, sono stati nominati vicepresidenti :<br \/>\nAntonio Carriere vice presidente settore adulti, Elena Palumbo e Giuseppe Elia vice presidenti settore giovani, Antonio Martina responsabile ACR ed Elisa Cosma vic responsabile ACR. Infine Mimma Venerito \u00e8 stata nominata amministratore di AC Diocesana<\/p>\n<p>&nbsp;<\/p>\n<p>Il Presidente diocesano, ha rilasciato la seguente dichiarazione: ringrazio S.E. Mons. Pisanello per questo inaspettato e sicuramente immeritato onore, cos\u00ec come ringrazio di cuore i consiglieri diocesani per la fiducia accordatami. Il compito che ci aspettata tutti, come soci e come dirigenti di AC diocesana, non \u00e8 semplice n\u00e9 facile. La nostra societ\u00e0, ormai in camminata verso un laicismo privo di umanit\u00e0, dove tutto nasce dal rapporto costo\/beneficio, ha pi\u00f9 che mai bisogno, al contrario, di ritrovare quei valori di fratellanza, amore per il prossimo, accoglienza, comprensione e compassione reciproca, rispetto ai quali le vuote parole devono lasciare spazio all\u2019agire, all\u2019operare, in una parola all\u2019essere quell\u2019azione, su cui si fonda il concetto stesso, l\u2019intima essenza dell\u2019Azione Cattolica. In particolare nella nostra Diocesi dobbiamo sentire forte la responsabilit\u00e0 di affiancare e sostenere il nostro Pastore e tutti i sacerdoti, nel loro impegno quotidiano di diffusione della Parola del Vangelo e di testimonianza concreta di attenzione ai bisogni di ciascuno e delle collettivit\u00e0. Non \u00e8 pi\u00f9 tempo di assistere passivamente a quanto ci accade intorno, quasi che tutto questo non sia un problema nostro, un problema della Chiesa. E\u2019 nostro impegno e su questo intendo fondare l\u2019attivit\u00e0 che insieme agli amici della presidenza cercheremo di sviluppare nei prossimi anni, sfuggire a quell\u2019accidia che pare stringere i nostri cuori e le nostre menti, di cattolici e di cittadini. Quindi, care amiche e cari amici, cos\u00ec come ci ha chiesto il nostro vescovo nell\u2019assemblea diocesana dello scorso 23 febbraio alziamoci e mettiamoci in cammino.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>COMUNICATO STAMPA<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Vescovo della Diocesi di Oria, S.E. Mons. Vincenzo Pisanello, con decreto del 17 aprile 2014 ha nominato il Sig. Corradino De Pascalis, Presidente della Azione Cattolica Diocesana per il triennio 2014-2017. Il neo Presidente, sposato e con due figli, \u00e8 funzionario bibliotecario presso l\u2019Archivio di Stato di Brindisi, Ministero BAC, ha alle spalle una lunga militanza sindacale ed \u00e8 da sempre impegnato nel sociale. E\u2019socio di AC dal 2008 ed attualmente \u00e8 Presidente di AC parrocchiale Maria Immacolata di Ceglie Messapica. &nbsp; La Diocesi di Oria ha competenza territoriale su undici comuni ( Avetrana, Ceglie Messapica, Erchie, Francavilla Fontana, Latiano, Manduria, Maruggio, Oria, Sava, Torre S.Susanna, Villa Castelli) e conta 43 Parrocchie. Azione Cattolica in questo territorio conta associati, con una capillare presenza in tutte le parrocchie, dove svolge un servizio prezioso a sostegno dei parroci e dei sacerdoti. &nbsp; Nel corso del primo consiglio diocesano del, sono stati nominati vicepresidenti : Antonio Carriere vice presidente settore adulti, Elena Palumbo e Giuseppe Elia vice presidenti settore giovani, Antonio Martina&#8230;<\/p>\n","protected":false},"author":2,"featured_media":11819,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1789,1790],"class_list":["post-11818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-de-pascalis","tag-diocesi-di-oria"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/11818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=11818"}],"version-history":[{"count":0,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/11818\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/11819"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=11818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=11818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=11818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}