{"id":119716,"date":"2017-12-01T19:36:54","date_gmt":"2017-12-01T18:36:54","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=119716"},"modified":"2017-12-01T18:41:05","modified_gmt":"2017-12-01T17:41:05","slug":"banca-apulica-condannata-per-la-vendita-di-azioni-veneto-banca","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/banca-apulica-condannata-per-la-vendita-di-azioni-veneto-banca\/","title":{"rendered":"Banca Apulica condannata per la vendita di azioni Veneto Banca"},"content":{"rendered":"<p>Caso Veneto Banca, l\u2019Arbitro per le controversie finanziarie riconosce il diritto di un associato della Confconsumatori ad ottenere da Banca Apulia il risarcimento del danno patito pari all\u2019intero importo investito in azioni della Veneto Banca.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019Arbitro ha, infatti, stabilito che la responsabilit\u00e0 per la condotta grava sull\u2019intermediario.<\/p>\n<p>&nbsp;<\/p>\n<p>Si apre, cos\u00ec, la strada alle azioni legali di tutti quei risparmiatori che hanno visto andare in fumo i propri risparmi.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cDopo circa tre anni di dure battaglie legali \u2013 afferma l\u2019avv. Emilio Graziuso, Responsabile del Coordinamento Confconsumatori \u2013 Dalla Parte del Consumatore, il quale segue legalmente moltissimi risparmiatori vittime del caso Veneto Banca \u2013 finalmente cominciano a registrarsi le prime pronunzie. L\u2019Arbitro, infatti, ha accolto la tesi da noi sostenuta circa la violazione da parte dell\u2019intermediario nella vendita delle azioni Veneto Banca degli obblighi di diligenza e correttezza. Il risparmiatore, nel caso di specie, cos\u00ec come in molti altri casi che abbiamo portato nelle aule di Tribunale, non era stato adeguatamente informato circa le caratteristiche dell\u2019operazione finanziaria ed i rischi ad essa connessi, con palese violazione della normativa di settore\u201d<\/p>\n<p>&nbsp;<\/p>\n<p>Il Coordinamento Istituito dalla Confconsumatori e dall\u2019Associazione Nazionale Dalla Parte del Consumatore fa sapere che i principi sanciti nella pronunzia dell\u2019Arbitro per le Controversie Finanziarie sono applicabili, ove ne ricorrano i presupposti, anche nei casi di risparmiatori che abbiano investito il proprio denaro in azioni della Banca Popolare di Bari e della Banca Popolare di Vicenza.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Coordinamento Confconsumatori \u2013 Dalla Parte del Consumatore<\/strong> <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Caso Veneto Banca, l\u2019Arbitro per le controversie finanziarie riconosce il diritto di un associato della Confconsumatori ad ottenere da Banca Apulia il risarcimento del danno patito pari all\u2019intero importo investito in azioni della Veneto Banca. &nbsp; L\u2019Arbitro ha, infatti, stabilito che la responsabilit\u00e0 per la condotta grava sull\u2019intermediario. &nbsp; Si apre, cos\u00ec, la strada alle azioni legali di tutti quei risparmiatori che hanno visto andare in fumo i propri risparmi. &nbsp; \u201cDopo circa tre anni di dure battaglie legali \u2013 afferma l\u2019avv. Emilio Graziuso, Responsabile del Coordinamento Confconsumatori \u2013 Dalla Parte del Consumatore, il quale segue legalmente moltissimi risparmiatori vittime del caso Veneto Banca \u2013 finalmente cominciano a registrarsi le prime pronunzie. L\u2019Arbitro, infatti, ha accolto la tesi da noi sostenuta circa la violazione da parte dell\u2019intermediario nella vendita delle azioni Veneto Banca degli obblighi di diligenza e correttezza. Il risparmiatore, nel caso di specie, cos\u00ec come in molti altri casi che abbiamo portato nelle aule di Tribunale, non era stato adeguatamente informato circa le caratteristiche dell\u2019operazione finanziaria ed i&#8230;<\/p>\n","protected":false},"author":2,"featured_media":34111,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[343],"class_list":["post-119716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-confconsumatori"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/119716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=119716"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/119716\/revisions"}],"predecessor-version":[{"id":119717,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/119716\/revisions\/119717"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/34111"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=119716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=119716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=119716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}