{"id":119778,"date":"2017-12-02T20:00:46","date_gmt":"2017-12-02T19:00:46","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=119778"},"modified":"2017-12-02T20:00:46","modified_gmt":"2017-12-02T19:00:46","slug":"oggiano-multiservizi-storia-di-un-disastro-annunciato","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/oggiano-multiservizi-storia-di-un-disastro-annunciato\/","title":{"rendered":"Oggiano: &#8220;Multiservizi, storia di un disastro annunciato&#8221;"},"content":{"rendered":"<p>7.433.925 euro a tanto ammontano le perdite accumulate dalla Multiservizi negli ultimi sei consecutivi bilanci durante l\u2019Amministrazione Consales e per ultimo Carluccio e pi\u00f9 precisamente:<\/p>\n<p>\u2022 2011 &#8211; 517.288<br \/>\n\u2022 2012 &#8211; 3.165.574<br \/>\n\u2022 2013 &#8211; 1.153.550<br \/>\n\u2022 2014 &#8211; 1.333.219<br \/>\n\u2022 2015 &#8211; 976.580<br \/>\n\u2022 2016 &#8211; 804.485<\/p>\n<p>&nbsp;<\/p>\n<p>Per trovare l\u2019ultimo bilancio in positivo dobbiamo risalire al 2010 durante l\u2019Amministrazione Mennitti!<\/p>\n<p>&nbsp;<\/p>\n<p>E\u2019 notizia delle ultime ore che anche i bilanci 2015 e 2016 sono usciti in perdita, cosa che avevo purtroppo previsto in tempi non sospetti e puntualmente \u201csbeffeggiato\u201d cos\u00ec come tutte le altre volte in cui avevo sollevato dubbi, preoccupazioni e rischi sulla gestione scellerata della Societ\u00e0. Avessero ascoltato solo un decimo delle denunce e delle relative soluzioni proposte sicuramente non saremo arrivati a tale situazione.<\/p>\n<p>&nbsp;<\/p>\n<p>La cosa grave \u00e8 che i responsabili di tale disastro continuano ancora oggi a farla franca, sia gli amministratori che si sono susseguiti nel corso degli anni sia i loro \u201cmentori\u201d politico istituzionali che li hanno nominati sia i dirigenti che avrebbero dovuto controllare, cosi come previsto dalla normativa di riferimento per le partecipate in house.<\/p>\n<p>&nbsp;<\/p>\n<p>Il dissesto finanziario quasi insanabile della Multiservizi ha dei nomi e cognomi ben individuabili, sia politici che tecnici che interni alla stessa Societ\u00e0, ed il fatto che sono in corso varie inchieste della magistratura sulla gestione della partecipata la dice lunga su come costoro abbiano inteso gestire una risorsa pubblica quale \u00e8 la Multiservizi.<\/p>\n<p>&nbsp;<\/p>\n<p>Ovviamente chi sta pagando in prima battuta per tali gestioni scellerate, al netto delle varie azioni di responsabilit\u00e0 in atto e\/o da avviare nei confronti dei responsabili, sono le casse comunali che sono state \u201cmunte\u201d per coprire le perdite in questione e di conseguenza pescando nelle tasche dei cittadini brindisini.<\/p>\n<p>&nbsp;<\/p>\n<p>La Societ\u00e0 si trova in una fase di liquidazione di fatto e non si capisce per quale motivo l\u2019attuale gestione commissariale continua a tergiversare o peggio a proporre piani industriali, buoni solo a lavarsi la coscienza, che andranno comunque avallati dalla Corte dei Conti, cosa alquanto improbabile dopo sei bilanci in rosso e con un passivo complessivo di euro 7.433.925! Sembra quasi che si voglia nascondere la polvere sotto il tappeto e lasciare all\u2019Amministrazione futura il cerino in mano.<br \/>\nSe cos\u00ec \u00e8 la gestione Commissariale farebbe bene convocare tutte le forze politiche, o almeno le pi\u00f9 rappresentative, per avviare un precorso dialettico che porti a soluzioni\/proposte condivise o quanto meno a traghettare il tutto sino all\u2019insediamento della nuova Amministrazione.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Dott. Massimiliano Oggiano<\/strong><br \/>\n<strong> Presidente Associazione Periferia<\/strong><br \/>\n<strong> Gi\u00e0 consigliere comunale<\/strong><br \/>\n<strong> Gi\u00e0 componente Comitato di governace delle partecipate Comune di Brindisi<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>7.433.925 euro a tanto ammontano le perdite accumulate dalla Multiservizi negli ultimi sei consecutivi bilanci durante l\u2019Amministrazione Consales e per ultimo Carluccio e pi\u00f9 precisamente: \u2022 2011 &#8211; 517.288 \u2022 2012 &#8211; 3.165.574 \u2022 2013 &#8211; 1.153.550 \u2022 2014 &#8211; 1.333.219 \u2022 2015 &#8211; 976.580 \u2022 2016 &#8211; 804.485 &nbsp; Per trovare l\u2019ultimo bilancio in positivo dobbiamo risalire al 2010 durante l\u2019Amministrazione Mennitti! &nbsp; E\u2019 notizia delle ultime ore che anche i bilanci 2015 e 2016 sono usciti in perdita, cosa che avevo purtroppo previsto in tempi non sospetti e puntualmente \u201csbeffeggiato\u201d cos\u00ec come tutte le altre volte in cui avevo sollevato dubbi, preoccupazioni e rischi sulla gestione scellerata della Societ\u00e0. Avessero ascoltato solo un decimo delle denunce e delle relative soluzioni proposte sicuramente non saremo arrivati a tale situazione. &nbsp; La cosa grave \u00e8 che i responsabili di tale disastro continuano ancora oggi a farla franca, sia gli amministratori che si sono susseguiti nel corso degli anni sia i loro \u201cmentori\u201d politico istituzionali che li hanno nominati sia i&#8230;<\/p>\n","protected":false},"author":2,"featured_media":4582,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[555,865],"class_list":["post-119778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-multiservizi","tag-oggiano"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/119778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=119778"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/119778\/revisions"}],"predecessor-version":[{"id":119780,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/119778\/revisions\/119780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/4582"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=119778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=119778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=119778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}