{"id":120104,"date":"2017-12-07T11:21:25","date_gmt":"2017-12-07T10:21:25","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=120104"},"modified":"2017-12-06T23:42:32","modified_gmt":"2017-12-06T22:42:32","slug":"teatri-a-vapore-domenica-10-evento-speciale-per-bambini-al-binario-23","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/teatri-a-vapore-domenica-10-evento-speciale-per-bambini-al-binario-23\/","title":{"rendered":"Teatri a Vapore: domenica 10 evento speciale per bambini al Binario 23"},"content":{"rendered":"<p>Domenica 10 dicembre alle ore 17<br \/>\nTeatri a Vapore al Binario 23<br \/>\nEvento speciale per i bambini &#8221;Concerto Fragile&#8221; regia Antonio Catalano con Sara Bevilacqua e Alessandra Manti.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Concerto Fragile \u00e8 suono, \u00e8 poesia, \u00e8 silenzio. \u00c8 un alfabeto teatrale da leggere nei segni, negli oggetti e nei gesti.<\/p>\n<p>E\u2019 il concerto dei bambini che con la propria immaginazione entrano in un mondo di suoni e immagini, si stupiscono e si meravigliano, si divertono, cantano e giocano in uno spettacolo pieno di bellezza poetica da guardare e sentire con gli occhi e col cuore.<\/p>\n<p>&nbsp;<\/p>\n<p>Due esploratrici sonore, collezioniste di suoni, viaggiano per mari e per monti alla ricerca di ritmi e melodie della natura. Sono partite con una valigia in mano. Durante il viaggio scopriranno e cattureranno tantissimi suoni, piccoli rumori che si trasformano in armonie<br \/>\ndelicate e dalla loro collezione nascer\u00e0 un concerto originale e delicato.<\/p>\n<p>&nbsp;<\/p>\n<p>Fragili narrazioni musicali e suggestioni poetiche danno vita alla sinfonia delle stelle, alla serenata per lucciole vagabonde, all\u2019adagio dei mari in tempesta, allo scherzo della civetta dispettosa.<\/p>\n<p>Prenotazione obbligatoria 3494490606<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domenica 10 dicembre alle ore 17 Teatri a Vapore al Binario 23 Evento speciale per i bambini &#8221;Concerto Fragile&#8221; regia Antonio Catalano con Sara Bevilacqua e Alessandra Manti. &nbsp; &nbsp; Concerto Fragile \u00e8 suono, \u00e8 poesia, \u00e8 silenzio. \u00c8 un alfabeto teatrale da leggere nei segni, negli oggetti e nei gesti. E\u2019 il concerto dei bambini che con la propria immaginazione entrano in un mondo di suoni e immagini, si stupiscono e si meravigliano, si divertono, cantano e giocano in uno spettacolo pieno di bellezza poetica da guardare e sentire con gli occhi e col cuore. &nbsp; Due esploratrici sonore, collezioniste di suoni, viaggiano per mari e per monti alla ricerca di ritmi e melodie della natura. Sono partite con una valigia in mano. Durante il viaggio scopriranno e cattureranno tantissimi suoni, piccoli rumori che si trasformano in armonie delicate e dalla loro collezione nascer\u00e0 un concerto originale e delicato. &nbsp; Fragili narrazioni musicali e suggestioni poetiche danno vita alla sinfonia delle stelle, alla serenata per lucciole vagabonde, all\u2019adagio dei&#8230;<\/p>\n","protected":false},"author":2,"featured_media":120105,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[3259,3551],"class_list":["post-120104","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-binario-23","tag-teatri-a-vapore"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/120104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=120104"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/120104\/revisions"}],"predecessor-version":[{"id":120107,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/120104\/revisions\/120107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/120105"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=120104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=120104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=120104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}