{"id":121199,"date":"2017-12-19T13:11:25","date_gmt":"2017-12-19T12:11:25","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=121199"},"modified":"2017-12-19T19:36:38","modified_gmt":"2017-12-19T18:36:38","slug":"natale-insieme-a-cellino-sabato-23-serata-di-beneficenza-con-pizzica-pittule-e-babbo-natale","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/natale-insieme-a-cellino-sabato-23-serata-di-beneficenza-con-pizzica-pittule-e-babbo-natale\/","title":{"rendered":"Natale insieme a Cellino: sabato 23 serata di beneficenza con pizzica, pittule e Babbo Natale"},"content":{"rendered":"<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/12\/natale-cellino.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/12\/natale-cellino-197x300.jpg\" alt=\"\" width=\"197\" height=\"300\" class=\"alignright size-medium wp-image-121200\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/12\/natale-cellino-197x300.jpg 197w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/12\/natale-cellino.jpg 623w\" sizes=\"auto, (max-width: 197px) 100vw, 197px\" \/><\/a>&#8220;Un Natale Insieme&#8221; \u00e8 il tema di una manifestazione organizzata a Cellino San Marco dal Comitato Geste Patronali, dalla Parrocchia Santi Marco e Caterina e dall&#8217;Associazione &#8220;il Cerchio delle Idee&#8221; e con il patrocinio dell&#8217;Amministrazione Comunale.<\/p>\n<p>L&#8217;appuntamento \u00e8 per sabato 23 dicembre, alle ore 19.00, presso il Sagrato della Parrocchia.<br \/>\nLa serata di beneficenza prevede:<\/p>\n<p>&#8211; concerto di pizzica a cura dei ragazzi del Taranta Fesival&#8221;<br \/>\n&#8211; degustazione delle tradizionali &#8220;Pittule&#8221;<br \/>\n&#8211; show cooking a cura del Bar Cosma.<\/p>\n<p>Inoltre, per tutti i bambini (e non solo), vi sar\u00e0 la presenza di Babbo Natale.<\/p>\n<p>Tutta la cittadinanza \u00e8 invitata per condividere questo momento di gioia e allegrai aspettando le feste ormai vicine.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Un Natale Insieme&#8221; \u00e8 il tema di una manifestazione organizzata a Cellino San Marco dal Comitato Geste Patronali, dalla Parrocchia Santi Marco e Caterina e dall&#8217;Associazione &#8220;il Cerchio delle Idee&#8221; e con il patrocinio dell&#8217;Amministrazione Comunale. L&#8217;appuntamento \u00e8 per sabato 23 dicembre, alle ore 19.00, presso il Sagrato della Parrocchia. La serata di beneficenza prevede: &#8211; concerto di pizzica a cura dei ragazzi del Taranta Fesival&#8221; &#8211; degustazione delle tradizionali &#8220;Pittule&#8221; &#8211; show cooking a cura del Bar Cosma. Inoltre, per tutti i bambini (e non solo), vi sar\u00e0 la presenza di Babbo Natale. Tutta la cittadinanza \u00e8 invitata per condividere questo momento di gioia e allegrai aspettando le feste ormai vicine.<\/p>\n","protected":false},"author":2,"featured_media":121200,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[2352,5400],"class_list":["post-121199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-cellino","tag-natale-a-cellino"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/121199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=121199"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/121199\/revisions"}],"predecessor-version":[{"id":121201,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/121199\/revisions\/121201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/121200"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=121199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=121199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=121199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}