{"id":122567,"date":"2018-01-10T16:37:11","date_gmt":"2018-01-10T15:37:11","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=122567"},"modified":"2018-01-10T16:42:22","modified_gmt":"2018-01-10T15:42:22","slug":"domani-si-decide-il-segretario-dellautorita-di-sistema-iaia-udc-che-sia-un-brindisino","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/domani-si-decide-il-segretario-dellautorita-di-sistema-iaia-udc-che-sia-un-brindisino\/","title":{"rendered":"Domani si decide il segretario dell&#8217;Autorit\u00e0 di Sistema, Iaia (UdC): &#8220;che sia un brindisino&#8221;"},"content":{"rendered":"<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/01\/RAFFAELEIAIA2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-2821\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/01\/RAFFAELEIAIA2.jpg\" alt=\"\" width=\"210\" height=\"191\" \/><\/a>Siamo arrivati alla vigilia della riunione dell\u2019Autorit\u00e0 di Sistema Portuale dell\u2019Adriatico meridionale, in questa riunione si dovr\u00e0 prendere un\u2019altra importante decisione per il porto di Brindisi &#8211; Vale a dire la nomina del Segretario Generale dell\u2019Autorit\u00e0 A.D.S.P.<\/p>\n<p>&nbsp;<\/p>\n<p>Chiediamo e rinnoviamo al Dott. S. Giuffr\u00e8, che con il suo delegato per l\u2019amministrazione comunale di Brindisi, che unitamente agli altri rappresentanti dei porti Baresi, facenti parte dell\u2019organismo preposto a tale nomina, di salvaguardare i diritti della nostra realt\u00e0 portuale e non avalli situazione che ci penalizzino ulteriormente facendo in modo che a tale incarico venga nominato un Brindisino.<br \/>\nSig. Commissario , non per questioni campanilistici, ma per rispetto del territorio e della stessa fondamentale funzione del Porto di Brindisi si deve sostenere, come Ella nei mesi pregressi pare abbia gi\u00e0 condiviso, una candidatura Brindisina a Segretario Generale dell\u2019Autorit\u00e0 di Sistema.<\/p>\n<p>&nbsp;<\/p>\n<p>Assistiamo da molti anni ad un progressivo spostamento degli interessi decisionali verso il Baricentrismo in tutti i campi ma nella questione del porto si \u00e8 notato ancora di pi\u00f9, e nonostante le varie prese di posizioni e dati di fatto concreti degli operatori portuali e di alcune associazioni, la politica Regionale e Nazionale \u00e8 rimasta indifferente e ha continuato ad appoggiare logiche che certamente non salvaguardano la citt\u00e0 di Brindisi, anzi la penalizzano ancora di pi\u00f9 emarginandola in un ruolo di sudditanza passiva quando invece, la posizione strategica del nostro porto potrebbe essere il volano della ripresa economica della nostra citt\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Raffaele Iaia<\/strong><br \/>\n<strong>Coordinatore UDC<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siamo arrivati alla vigilia della riunione dell\u2019Autorit\u00e0 di Sistema Portuale dell\u2019Adriatico meridionale, in questa riunione si dovr\u00e0 prendere un\u2019altra importante decisione per il porto di Brindisi &#8211; Vale a dire la nomina del Segretario Generale dell\u2019Autorit\u00e0 A.D.S.P. &nbsp; Chiediamo e rinnoviamo al Dott. S. Giuffr\u00e8, che con il suo delegato per l\u2019amministrazione comunale di Brindisi, che unitamente agli altri rappresentanti dei porti Baresi, facenti parte dell\u2019organismo preposto a tale nomina, di salvaguardare i diritti della nostra realt\u00e0 portuale e non avalli situazione che ci penalizzino ulteriormente facendo in modo che a tale incarico venga nominato un Brindisino. Sig. Commissario , non per questioni campanilistici, ma per rispetto del territorio e della stessa fondamentale funzione del Porto di Brindisi si deve sostenere, come Ella nei mesi pregressi pare abbia gi\u00e0 condiviso, una candidatura Brindisina a Segretario Generale dell\u2019Autorit\u00e0 di Sistema. &nbsp; Assistiamo da molti anni ad un progressivo spostamento degli interessi decisionali verso il Baricentrismo in tutti i campi ma nella questione del porto si \u00e8 notato ancora di pi\u00f9, e&#8230;<\/p>\n","protected":false},"author":2,"featured_media":66941,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[4135,401],"class_list":["post-122567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-autorita-sistema-portuale-brindisi","tag-iaia"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/122567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=122567"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/122567\/revisions"}],"predecessor-version":[{"id":122568,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/122567\/revisions\/122568"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/66941"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=122567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=122567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=122567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}