{"id":123634,"date":"2018-01-25T11:37:29","date_gmt":"2018-01-25T10:37:29","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=123634"},"modified":"2018-01-30T09:56:02","modified_gmt":"2018-01-30T08:56:02","slug":"matarrelli-chiarisce-le-ragioni-della-scelta-di-non-ricandidarsi-le-liste-di-leu-improntate-al-familismo-amorale","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/matarrelli-chiarisce-le-ragioni-della-scelta-di-non-ricandidarsi-le-liste-di-leu-improntate-al-familismo-amorale\/","title":{"rendered":"Matarrelli chiarisce le ragioni della scelta di non ricandidarsi: &#8220;le liste di LeU improntate al familismo amorale&#8221;"},"content":{"rendered":"<p>Di fronte alle moltissime manifestazioni di solidariet\u00e0 ed anche alla diffusa reazione di disimpegno di tanti miei sostenitori, ho il dovere di fornire qualche spiegazione in pi\u00f9 rispetto alla mia scelta di non candidarmi.<\/p>\n<p>&nbsp;<\/p>\n<p>La legge elettorale per come \u00e8 stata concepita avrebbe reso difficilissima la mia elezione e faccio subito un esempio concreto. Uno dei pi\u00f9 recenti sondaggi (Ghisleri), peraltro tra i pi\u00f9 ottimistici, assegna a Liberi e Uguali il 6.3% nazionale e l&#8217;8% in Puglia: secondo queste stime, LeU eleggerebbe un solo deputato (ovviamente al plurinominale) e forse un senatore. Ciononostante io avevo assicurato la mia disponibilit\u00e0 ad essere candidato, ma per sostenere quello che almeno nelle intenzioni doveva essere un progetto politico utile al Paese, e cio\u00e8 la ricostruzione della sinistra.<\/p>\n<p>&nbsp;<\/p>\n<p>Il mio impegno diretto \u00e8 venuto meno nel momento in cui ho assistito, in occasione della compilazione delle liste, a vicende francamente sconcertanti, di cui io stesso non ho memoria precedente. Anche qui faccio un esempio concreto, elenchi ufficiali alla mano che potr\u00f2 produrre se e quando mi saranno richiesti: nel collegio di Lecce si era scelto di candidare in posizione potenzialmente eleggibile Salvatore Piconese, ex segretario provinciale del PD salentino. All&#8217;ultimo momento, con un abile colpo di mano, Ernesto Abaterusso \u2013 consigliere regionale, capogruppo in consiglio regionale e, soprattutto, coordinatore regionale di MdP Art.1 \u2013 ha sostituito Piconese con il figlio Gabriele, peraltro sindaco di Pat\u00f9. Appare in tutta la sua evidenza come questa operazione non abbia nulla di politico, ma risponda esclusivamente alla volont\u00e0 di sistemare non soltanto i fedelissimi, ma addirittura i parenti stretti. Se non \u00e8 familismo amorale questo&#8230;<\/p>\n<p>&nbsp;<\/p>\n<p>E&#8217; chiaro che io a questo gioco non potevo starci. E questa robaccia ha fatto venire meno, oltre alle mie motivazioni ideali, anche, a cascata, quella di molti altri soggetti politicamente riconoscibili, i quali hanno rinunciato alla candidatura di servizio che avevamo messo in piedi per dare un contributo ancora pi\u00f9 concreto.<\/p>\n<p>&nbsp;<\/p>\n<p>A me sorprende che una figura con la biografia politica di D&#8217;Alema abbia avallato questo genere di operazioni; o, meglio, mi viene da pensare che D&#8217;Alema stesso sia rimasto vittima di chi avrebbe dovuto tutelare lui ed il progetto politico.<\/p>\n<p>&nbsp;<\/p>\n<p>A me risulta, e ne ho larga conferma anche dai quotidiani nazionali, che LeU abbia ignorato e calpestato ovunque le richieste nate dai territori, piazzando qua e l\u00e0 per l&#8217;Italia i candidati secondo criteri di convenienza personale e di gruppo, purtroppo dimostrando una sorta di specificit\u00e0 in negativo poich\u00e9, bene o male, gli altri partiti una griglia di criteri improntati al buon senso la hanno utilizzata.<\/p>\n<p>Va da s\u00e9 che la gente resti oltremodo indignata e rischi comprensibilmente di cedere alla pulsione del disertare le urne. Io ad ogni modo voglio chiarire che il 4 marzo, qualunque cosa potr\u00e0 ancora accadere, andr\u00f2 a votare, come sempre nella mia vita.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Toni Matarrelli<\/strong><br \/>\n<strong> Deputato della Repubblica<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Di fronte alle moltissime manifestazioni di solidariet\u00e0 ed anche alla diffusa reazione di disimpegno di tanti miei sostenitori, ho il dovere di fornire qualche spiegazione in pi\u00f9 rispetto alla mia scelta di non candidarmi. &nbsp; La legge elettorale per come \u00e8 stata concepita avrebbe reso difficilissima la mia elezione e faccio subito un esempio concreto. Uno dei pi\u00f9 recenti sondaggi (Ghisleri), peraltro tra i pi\u00f9 ottimistici, assegna a Liberi e Uguali il 6.3% nazionale e l&#8217;8% in Puglia: secondo queste stime, LeU eleggerebbe un solo deputato (ovviamente al plurinominale) e forse un senatore. Ciononostante io avevo assicurato la mia disponibilit\u00e0 ad essere candidato, ma per sostenere quello che almeno nelle intenzioni doveva essere un progetto politico utile al Paese, e cio\u00e8 la ricostruzione della sinistra. &nbsp; Il mio impegno diretto \u00e8 venuto meno nel momento in cui ho assistito, in occasione della compilazione delle liste, a vicende francamente sconcertanti, di cui io stesso non ho memoria precedente. Anche qui faccio un esempio concreto, elenchi ufficiali alla mano che potr\u00f2 produrre&#8230;<\/p>\n","protected":false},"author":2,"featured_media":83685,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[534],"class_list":["post-123634","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-matarrelli"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/123634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=123634"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/123634\/revisions"}],"predecessor-version":[{"id":123635,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/123634\/revisions\/123635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/83685"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=123634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=123634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=123634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}