{"id":124508,"date":"2018-02-05T11:33:38","date_gmt":"2018-02-05T10:33:38","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=124508"},"modified":"2018-02-06T22:52:29","modified_gmt":"2018-02-06T21:52:29","slug":"giovani-imprenditori-di-confindustria-brindisi-visitano-lo-stabilimento-eni-versalis","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/giovani-imprenditori-di-confindustria-brindisi-visitano-lo-stabilimento-eni-versalis\/","title":{"rendered":"Giovani imprenditori di Confindustria Brindisi visitano lo stabilimento Eni Versalis"},"content":{"rendered":"<p>Prima tappa del tour nelle realt\u00e0 industriali di Brindisi, previsto nel programma di lavoro del Presidente dei Giovani Imprenditori di Confindustria Brindisi, Alessandro Calisi, al fine di favorire la conoscenza del tessuto imprenditoriale brindisino di Confindustria Brindisi.<\/p>\n<p>&nbsp;<\/p>\n<p>Una folta delegazione di giovani imprenditori, guidati dal Presidente Calisi, ha visitato lo Stabilimento Eni Versalis di Brindisi.<br \/>\nLa delegazione, dopo l\u2019informativa di Sicurezza necessaria per accedere allo Stabilimento, \u00e8 stata accolta dal Direttore Marcello Perra, dal Responsabile Risorse Umane Gabriele Venera, dalla Responsabile QHSE Lara Politi.<\/p>\n<p>&nbsp;<\/p>\n<p>Il Direttore ha illustrato le particolarit\u00e0 dello Stabilimento, che rappresenta uno dei siti produttivi Versalis tecnologicamente pi\u00f9 avanzato e dove risiedono impianti fra i pi\u00f9 recenti del panorama industriale Versalis, fra cui l\u2019impianto di Cracking che \u00e8 tra i primi d\u2019Europa. L\u2019ing. Perra ha poi presentato i vari cicli produttivi presenti e i vari prodotti spiegandone il loro impiego in una vastissima gamma di settori che fanno parte della nostra vita quotidiana, ribadendo che il fattore essenziale alla base dei grandi risultati raggiunti \u00e8 rappresentato dall\u2019altissimo impegno dell\u2019Eni, di Versalis e del Sito a gestire tutte le fasi produttive, comprese le manutenzioni nel totale rispetto della Sicurezza dell\u2019Ambiente e della salute delle persone che vi operano, siano essi colleghi interni o dipendenti delle imprese terze.<\/p>\n<p>&nbsp;<\/p>\n<p>Il responsabile delle Risorse Umane ha illustrato alcuni dati di estremo interesse per i giovani Industriali quali ad esempio i dati relativi al numero di risorse impiegate nel sito e la ricchezza che rappresenta per il territorio brindisino; ha illustrato l\u2019impegno dell\u2019azienda al rispetto delle diversit\u00e0 e della dignit\u00e0 delle persone e delle norme in genere che regolano il rapporto di lavoro, attestato anche dalla certificazione acquisita SA 8000 relativa al Sistema di \u201cResponsabilit\u00e0 Sociale\u201d;<\/p>\n<p>&nbsp;<\/p>\n<p>La responsabile QHSE infine ha dato una informativa generale sulle performance del sito riguardanti la Sicurezza, l\u2019Ambiente e la Salute delle persone, ribadendo l\u2019impegno aziendale continuo per cercare di migliorare ulteriormente tali performance attraverso investimenti e applicazioni delle migliori tecnologie disponibili sul mercato, sfruttando anche metodologie innovative e di ultima generazione opportunamente rappresentate da \u201cIndustry 4.0\u201d. Un dato per tutti: il sito di Brindisi ha raggiunto ormai 8 anni senza infortuni!<\/p>\n<p>&nbsp;<\/p>\n<p>La delegazione \u00e8 stata poi accompagnata dall\u2019ing. Cosimo Cucinelli in una visita specifica su tutti gli impianti del sito.<\/p>\n<p>&nbsp;<\/p>\n<p>I giovani Imprenditori hanno inoltre presentato le proprie attivit\u00e0, facendo conoscere ai responsabili di Versalis alcune delle realt\u00e0 presenti all\u2019interno del Gruppo Giovani Imprenditori di Confindustria Brindisi.<br \/>\nL\u2019iniziativa ha riscosso positivo apprezzamento da parte dei Giovani e della stessa Versalis.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>CONFINDUSTRIA BRINDISI<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prima tappa del tour nelle realt\u00e0 industriali di Brindisi, previsto nel programma di lavoro del Presidente dei Giovani Imprenditori di Confindustria Brindisi, Alessandro Calisi, al fine di favorire la conoscenza del tessuto imprenditoriale brindisino di Confindustria Brindisi. &nbsp; Una folta delegazione di giovani imprenditori, guidati dal Presidente Calisi, ha visitato lo Stabilimento Eni Versalis di Brindisi. La delegazione, dopo l\u2019informativa di Sicurezza necessaria per accedere allo Stabilimento, \u00e8 stata accolta dal Direttore Marcello Perra, dal Responsabile Risorse Umane Gabriele Venera, dalla Responsabile QHSE Lara Politi. &nbsp; Il Direttore ha illustrato le particolarit\u00e0 dello Stabilimento, che rappresenta uno dei siti produttivi Versalis tecnologicamente pi\u00f9 avanzato e dove risiedono impianti fra i pi\u00f9 recenti del panorama industriale Versalis, fra cui l\u2019impianto di Cracking che \u00e8 tra i primi d\u2019Europa. L\u2019ing. Perra ha poi presentato i vari cicli produttivi presenti e i vari prodotti spiegandone il loro impiego in una vastissima gamma di settori che fanno parte della nostra vita quotidiana, ribadendo che il fattore essenziale alla base dei grandi risultati raggiunti \u00e8&#8230;<\/p>\n","protected":false},"author":2,"featured_media":124509,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[330,2236],"class_list":["post-124508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-confindustria","tag-versalis"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/124508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=124508"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/124508\/revisions"}],"predecessor-version":[{"id":124510,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/124508\/revisions\/124510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/124509"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=124508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=124508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=124508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}