{"id":125241,"date":"2018-02-13T10:58:24","date_gmt":"2018-02-13T09:58:24","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=125241"},"modified":"2018-02-15T10:05:41","modified_gmt":"2018-02-15T09:05:41","slug":"centri-per-limpiego-cisl-fp-il-2018-non-rappresenti-solo-un-numero","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/centri-per-limpiego-cisl-fp-il-2018-non-rappresenti-solo-un-numero\/","title":{"rendered":"Centri per l&#8217;impiego, Cisl FP: &#8220;il 2018 non rappresenti solo un numero&#8221;"},"content":{"rendered":"<p>La Cisl Fp Taranto Brindisi ha inoltrato una nota ai propri vertici regionali, affinch\u00e9 vengano governate le sorti di centinaia di Lavoratrici e Lavoratori pugliesi dei Centri per l\u2019impiego.<\/p>\n<p>&nbsp;<\/p>\n<p>Infatti, sar\u00e0 competenza delle Regioni provvedere agli adempimenti strumentali, conseguenti al trasferimento del personale, che dovranno concludersi, secondo quanto previsto dalla Legge di Stabilit\u00e0, entro il 30 giugno 2018.<\/p>\n<p>&nbsp;<\/p>\n<p>Quindi \u00e8 un anno importante questo 2018 in quanto le Province e le Citt\u00e0 metropolitane continueranno a svolgere, sino al trasferimento regionale, le attivit\u00e0 di gestione del suddetto personale.<\/p>\n<p>&nbsp;<\/p>\n<p>Occorre quindi fare subito ulteriore chiarezza sugli adempimenti burocratici per definire gli aspetti finanziari di tale operazione che non penalizzi il Personale sia dei Centri per l\u2019impiego che di coloro che rimarranno negli organici dell\u2019Ente Provincia.<\/p>\n<p>&nbsp;<\/p>\n<p>Non sar\u00e0 giustificato alcun tipo di scusante!<\/p>\n<p>&nbsp;<\/p>\n<p>Ma se il lato economico desta non poche preoccupazioni, il lato Servizi al Cittadino ci pone in posizione di vero \u201cattacco\u201d.<br \/>\nEbbene s\u00ec!<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cQuesto appare ancora pi\u00f9 allarmante del caso Polizia Provinciale, in quanto i Centri per l\u2019impiego costituiscono una risorsa per la costruzione di percorsi adeguati per l&#8217;inserimento e il reinserimento nel mercato del lavoro nei confronti dei disoccupati, nonch\u00e9 per lavoratori beneficiari di strumenti di sostegno al reddito in costanza di rapporto di lavoro e a rischio di disoccupazione \u2013 spiega il Segretario generale territoriale Cisl Fp Aldo Gemma &#8211; gli organi di governo politico regionale non possono sottrarsi a questo delicato compito e non scongiurare che la colpa del malfunzionamento ricada direttamente sull\u2019utente e su chi opera giornalmente con tanto senso del dovere.\u201d<\/p>\n<p>Adesso tocca alla Regione Puglia porre in essere ogni utile azione per dare concretezza ai disposti normativi.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cLa Cisl Fp non si \u00e8 mai posta con atteggiamento retrivo rispetto alle riforme ma se si assiste ancora oggi a file di donne e uomini in cerca di lavoro nonostante la decantata previsione informatizzata, figuriamoci quanto potrebbero interessare le sorti del relativo Personale \u2013 continua Gemma &#8211; con quale stato d\u2019animo, dunque, dovranno affrontare i drammi di giovani, precari, badanti, disoccupati e categorie di lavoratori protetti se gi\u00e0 le loro sorti professionali non sono state adeguatamente definite!\u201d<\/p>\n<p>&nbsp;<\/p>\n<p>Questa Organizzazione Sindacale sarebbe felice di essere testimone fedele di quanto previsto nei Servizi, nonch\u00e9 di misure di politica attiva del lavoro che abbiano trovato davvero concretezza.<br \/>\nE\u2019 proprio impossibile sognare un sistema in cui il lavoro pubblico, sapientemente indirizzato dalla politica, sia davvero al servizio di chi vive il dramma del lavoro?<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cNoi siamo fiduciosi \u2013 conclude il Segretario &#8211; che la politica si faccia subito parte diligente, in caso contrario ci vedr\u00e0 costretti a rompere ogni indugio ed individuare forme di sostegno alla lotta per l\u2019affermazione della dignit\u00e0 del lavoro pubblico e ancor pi\u00f9 sorreggere al contempo chi un lavoro non lo ha ancora.\u201d<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>UFFICIO STAMPA CISL FP<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Cisl Fp Taranto Brindisi ha inoltrato una nota ai propri vertici regionali, affinch\u00e9 vengano governate le sorti di centinaia di Lavoratrici e Lavoratori pugliesi dei Centri per l\u2019impiego. &nbsp; Infatti, sar\u00e0 competenza delle Regioni provvedere agli adempimenti strumentali, conseguenti al trasferimento del personale, che dovranno concludersi, secondo quanto previsto dalla Legge di Stabilit\u00e0, entro il 30 giugno 2018. &nbsp; Quindi \u00e8 un anno importante questo 2018 in quanto le Province e le Citt\u00e0 metropolitane continueranno a svolgere, sino al trasferimento regionale, le attivit\u00e0 di gestione del suddetto personale. &nbsp; Occorre quindi fare subito ulteriore chiarezza sugli adempimenti burocratici per definire gli aspetti finanziari di tale operazione che non penalizzi il Personale sia dei Centri per l\u2019impiego che di coloro che rimarranno negli organici dell\u2019Ente Provincia. &nbsp; Non sar\u00e0 giustificato alcun tipo di scusante! &nbsp; Ma se il lato economico desta non poche preoccupazioni, il lato Servizi al Cittadino ci pone in posizione di vero \u201cattacco\u201d. Ebbene s\u00ec! &nbsp; \u201cQuesto appare ancora pi\u00f9 allarmante del caso Polizia Provinciale, in quanto&#8230;<\/p>\n","protected":false},"author":2,"featured_media":70895,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[5602,1506],"class_list":["post-125241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-centri-impiego","tag-cisl-fp"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/125241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=125241"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/125241\/revisions"}],"predecessor-version":[{"id":125242,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/125241\/revisions\/125242"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/70895"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=125241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=125241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=125241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}