{"id":126548,"date":"2018-03-02T12:34:33","date_gmt":"2018-03-02T11:34:33","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=126548"},"modified":"2018-03-03T00:12:32","modified_gmt":"2018-03-02T23:12:32","slug":"due-membri-dequipaggio-si-ustionano-a-bordo-della-nave-gasiera-al-deebel-arriva-il-soccorso-della-capitaneria-di-porto-di-brindisi","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/due-membri-dequipaggio-si-ustionano-a-bordo-della-nave-gasiera-al-deebel-arriva-il-soccorso-della-capitaneria-di-porto-di-brindisi\/","title":{"rendered":"Due membri d\u2019equipaggio si ustionano a bordo della nave gasiera Al Deebel: arriva il soccorso della Capitaneria di Porto di Brindisi"},"content":{"rendered":"<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2018\/03\/al-debeel-2.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2018\/03\/al-debeel-2-300x226.jpg\" alt=\"\" width=\"300\" height=\"226\" class=\"alignleft size-medium wp-image-126549\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2018\/03\/al-debeel-2-300x226.jpg 300w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2018\/03\/al-debeel-2.jpg 534w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Dalle 18.10 di ieri, la Capitaneria di Porto di Brindisi \u00e8 stata impegnata in una operazione di evacuazione medica a favore di due marittimi imbarcati sulla motogasiera \u201cAl Deebel\u201d, battente bandiera delle Bahamas diretta verso l\u2019alto adriatico, i quali avevano subito delle ustioni al viso durante alcuni lavori nei pressi dell\u2019inceneritore di bordo.<\/p>\n<p>A causa delle proibitive condizioni meteo-marine in atto \u00e8 risultato impossibile procedere all\u2019evacuazione dei due malcapitati tramite mezzo aereo come era stato disposto inizialmente dal C.I.R.M. \u201ccentro italiano radio medico\u201d, pertanto si \u00e8 deciso di avvinare la nave verso il porto di Brindisi, distante circa 40 miglia.<\/p>\n<p>La motogasiera \u00e8 giunta nella rada nordest del porto adriatico intorno alle ore 23.10 ed \u00e8 stata raggiunta dalla motovedetta S.A.R. CP 844 che ha trasbordo i marittimi e li ha consegnati al 118 p per il trasferimento presso il locale nosocomio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dalle 18.10 di ieri, la Capitaneria di Porto di Brindisi \u00e8 stata impegnata in una operazione di evacuazione medica a favore di due marittimi imbarcati sulla motogasiera \u201cAl Deebel\u201d, battente bandiera delle Bahamas diretta verso l\u2019alto adriatico, i quali avevano subito delle ustioni al viso durante alcuni lavori nei pressi dell\u2019inceneritore di bordo. A causa delle proibitive condizioni meteo-marine in atto \u00e8 risultato impossibile procedere all\u2019evacuazione dei due malcapitati tramite mezzo aereo come era stato disposto inizialmente dal C.I.R.M. \u201ccentro italiano radio medico\u201d, pertanto si \u00e8 deciso di avvinare la nave verso il porto di Brindisi, distante circa 40 miglia. La motogasiera \u00e8 giunta nella rada nordest del porto adriatico intorno alle ore 23.10 ed \u00e8 stata raggiunta dalla motovedetta S.A.R. CP 844 che ha trasbordo i marittimi e li ha consegnati al 118 p per il trasferimento presso il locale nosocomio.<\/p>\n","protected":false},"author":2,"featured_media":126551,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[382,801],"class_list":["post-126548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-capitaneria-di-porto","tag-guardia-costiera"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/126548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=126548"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/126548\/revisions"}],"predecessor-version":[{"id":126552,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/126548\/revisions\/126552"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/126551"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=126548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=126548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=126548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}