{"id":128231,"date":"2018-03-21T11:43:26","date_gmt":"2018-03-21T10:43:26","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=128231"},"modified":"2018-03-21T11:06:40","modified_gmt":"2018-03-21T10:06:40","slug":"zes-attrazione-degli-investimenti-e-blue-economy-sabato-24-marzo-giornata-di-studio-a-bari","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/zes-attrazione-degli-investimenti-e-blue-economy-sabato-24-marzo-giornata-di-studio-a-bari\/","title":{"rendered":"ZES, attrazione degli investimenti e blue economy: sabato 24 marzo giornata di studio a Bari"},"content":{"rendered":"<p>Sabato 24 marzo a partire dalle ore 9.00 nel Pad. 152 &#8211; Sala 2 (Agor\u00e0) della Fiera del Levante, Lungomare Starita a Bari si svolger\u00e0 una giornata di approfondimento sul tema delle ZES (zone economiche speciali) dal titolo \u201cZES, attrazione degli investimenti e blue economy\u201d.<\/p>\n<p>La giornata di studio ha l\u2019obiettivo di fare il punto sull\u2019attivit\u00e0 regionale di approntamento dei piani di sviluppo strategico, atti prodromici alle proposte istitutive delle due ZES pugliesi.<\/p>\n<p>&nbsp;<\/p>\n<p>Al fine di illustrare le importanti ricadute determinate dall\u2019istituzione della ZES, ha assicurato la propria presenza l\u2019Ambasciatore di Bulgaria Marin Raycov, che relazioner\u00e0 sul tema: \u201cLe ZES di Burgas. Un caso empirico di successo.\u201d Grazie alla Zes, infatti, Burgas, che in passato era una piccola citt\u00e0 \u00e8 oramai diventata una delle principali porte europee per il traffico con la Cina, con significative ripercussioni nell\u2019indotto dell\u2019industria, del commercio e dell\u2019economia dell\u2019intero territorio.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cL\u2019esperienza di Burgas- sottolinea il presidente dell\u2019AdSP MAM, Ugo Patroni Griffi- ben si attaglia alla nostra realt\u00e0. La cittadina, infatti, insiste sul Corridoio VIII, progettato per favorire il trasporto di persone e merci nell&#8217;Europa centrale e orientale; collegando i porti di Bari e di Brindisi con l&#8217;Albania, la Macedonia e la Bulgaria. Sebbene il progetto giaccia nei cassetti di Bruxelles, di fatto si sta sviluppando naturalmente: l\u2019economia dei trasporti prescinde dall\u2019intervento del legislatore. Un altro corridoio logistico di fondamentale importanza per l\u2019autorit\u00e0 del Mare Adriatico Meridionale, che permette all\u2019area logistica integrata campano\/lucana\/pugliese di intercettare la via della seta e di offrire a merci e passeggeri un veloce punto di ingresso in Italia e nella UE, \u00e8 l\u2019Autostrada Egnatia. L\u2019autostrada Egnatia, infatti, offre la riduzione dei costi di trasporto, l\u2019innalzamento dei livelli di sicurezza stradale e l\u2019aumento nella velocit\u00e0 nei trasporti. Una serie di vantaggi che hanno reso l\u2019autostrada un ponte di comunicazione tra l\u2019Est e l\u2019Ovest. Si estende: dal Porto di Igoumenitsa fino a Kipi, nella regione dell\u2019Evros, per una lunghezza totale di 670 Km. \u00c8 collegata alle frontiere dell\u2019 Albania, del FYROM, della Bulgaria e della Turchia tramite nove assi verticali e all\u2019Italia da Bari e Brindisi.\u201d<\/p>\n<p>Nel corso della giornata di studio, partendo dall\u2019intervento dell\u2019ambasciatore Raycov e con l\u2019importante apporto dei principali decisori regionali ed esperti di carattere nazionale ci si confronter\u00e0 sulle ZES, straordinarie opportunit\u00e0 di sviluppo dei territori delle regioni meno sviluppate; sulle misure di semplificazione amministrativa che la Regione intende introdurre per rendere particolarmente attrattive le due ZES per gli investitori stranieri e nazionali; sul ruolo strategico della blue e della green economy; sul rapporto cruciale con il Piano Regionale della logistica integrata.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>COMUNICATO STAMPA ADSP MAM<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabato 24 marzo a partire dalle ore 9.00 nel Pad. 152 &#8211; Sala 2 (Agor\u00e0) della Fiera del Levante, Lungomare Starita a Bari si svolger\u00e0 una giornata di approfondimento sul tema delle ZES (zone economiche speciali) dal titolo \u201cZES, attrazione degli investimenti e blue economy\u201d. La giornata di studio ha l\u2019obiettivo di fare il punto sull\u2019attivit\u00e0 regionale di approntamento dei piani di sviluppo strategico, atti prodromici alle proposte istitutive delle due ZES pugliesi. &nbsp; Al fine di illustrare le importanti ricadute determinate dall\u2019istituzione della ZES, ha assicurato la propria presenza l\u2019Ambasciatore di Bulgaria Marin Raycov, che relazioner\u00e0 sul tema: \u201cLe ZES di Burgas. Un caso empirico di successo.\u201d Grazie alla Zes, infatti, Burgas, che in passato era una piccola citt\u00e0 \u00e8 oramai diventata una delle principali porte europee per il traffico con la Cina, con significative ripercussioni nell\u2019indotto dell\u2019industria, del commercio e dell\u2019economia dell\u2019intero territorio. &nbsp; \u201cL\u2019esperienza di Burgas- sottolinea il presidente dell\u2019AdSP MAM, Ugo Patroni Griffi- ben si attaglia alla nostra realt\u00e0. La cittadina, infatti, insiste sul Corridoio VIII,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":110280,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[4098],"class_list":["post-128231","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-autorita-di-sistema"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/128231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=128231"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/128231\/revisions"}],"predecessor-version":[{"id":128237,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/128231\/revisions\/128237"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/110280"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=128231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=128231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=128231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}