{"id":128960,"date":"2018-03-30T19:02:00","date_gmt":"2018-03-30T17:02:00","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=128960"},"modified":"2018-03-31T07:39:22","modified_gmt":"2018-03-31T05:39:22","slug":"il-10-giugno-hai-un-grosso-impegno-da-assolvere-di-antonio-melcore","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/il-10-giugno-hai-un-grosso-impegno-da-assolvere-di-antonio-melcore\/","title":{"rendered":"Il 10 Giugno hai un grosso impegno da assolvere. Di Antonio Melcore"},"content":{"rendered":"<p>Il ministro dell\u2019Interno, Marco Minniti, ha fissato, con proprio decreto, la data per lo svolgimento delle consultazioni per l\u2019elezione diretta dei sindaci e dei consigli comunali, per domenica 10 giugno 2018. L\u2019eventuale turno di ballottaggio per l\u2019elezione diretta dei sindaci avr\u00e0 luogo domenica 24 giugno.<\/p>\n<p>&nbsp;<\/p>\n<p>Sono queste le date in cui ogni brindisino deve impegnarsi a scegliere il futuro di questa citt\u00e0.<br \/>\nDopo l\u2019ennesimo fallimento di una politica improvvisata e inconcludente, ognuno di noi deve sentire sulle proprie spalle il peso di una scelta che non pu\u00f2 essere sbagliata, che non deve essere il frutto di una superficiale visione della politica.<\/p>\n<p>&nbsp;<\/p>\n<p>Parliamo francamente: bisogna aprire gli occhi e guardarsi bene dallo scegliere slogan e improvvisazioni varie. Dovremmo tutti smettere di svenderci per il favore di turno, per l\u2019assurda promessa di un lavoro, per un caff\u00e8. Abbiamo una dignit\u00e0, come cittadini e come uomini e aggiungo che anche il nostro diritto di voto ha una dignit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>Siamo stanchi, lo siamo tutti e lo sono anche io.<br \/>\nNon abbiamo pi\u00f9 la voglia di fare, di credere, di sperare e forse anche di immaginare che qualcosa di buono possa venir fuori da questa citt\u00e0 e dalla sua amministrazione ma bisogna impegnarsi. Bisogna sporcarsi le mani, ancora una volta, per costruire il futuro di questa citt\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00c8 proprio un nostro dovere farlo.<\/p>\n<p>&nbsp;<\/p>\n<p>Dobbiamo informarci su chi vuole amministrare la nostra citt\u00e0, sentire cosa vuole progettare, chiedere come ha intenzione di farlo. Dobbiamo farlo adesso, prima della chiamata alle urne. E dobbiamo farlo in maniera critica, consapevole. Non dimentichiamo chi e come ci ha deluso e distrutto. Non dimentichiamo chi e come ci ha bloccato in questa stasi perenne.<\/p>\n<p>&nbsp;<\/p>\n<p>Siamo stati tutti responsabili della \u201ccommedia politica\u201d messa in scena finora perch\u00e9 il nostro voto \u00e8 stato il trampolino di lancio di attori dal calibro spicciolo, smaniosi di apparire davanti a telecamere e riflettori tradendo la loro stessa dignit\u00e0, e portando a casa iniziative pubbliche senza alcun riflesso positivo.<\/p>\n<p>&nbsp;<\/p>\n<p>Gi\u00e0 lo scorso Maggio, prima dell\u2019insediamento del commissario Giuffr\u00e8, dicevo che dobbiamo armarci di un voto consapevole per le prossime elezioni.<\/p>\n<p>&nbsp;<\/p>\n<p>Brindisi \u00e8 una citt\u00e0 con un potenziale enorme, non ha nulla da invidiare ad altre citt\u00e0 dell\u2019Adriatico; ad altri porti del Mediterraneo. Ci rendiamo conto della grande storia che percorriamo passeggiando in centro? Siamo davvero consapevoli del potenziale del nostro scalo aeroportuale? Delle nostre strutture di svago, i nostri parchi o delle strutture sportive? Per non parlare del potenziale dei nostri cittadini: campioni sportivi, cervelli in fuga, professionisti affermati.<\/p>\n<p>&nbsp;<\/p>\n<p>C\u2019\u00e8 un seme, un fermento che ancora resiste in questa citt\u00e0: associazioni, comitati spontanei e organizzati, o anche singoli cittadini appassionati come me di questa citt\u00e0. Non c\u2019\u00e8 solo la generazione del \u201ctiriamo a campare\u201d: c\u2019\u00e8 chi guarda lontano, e chi cerca ancora di promuovere questa lungimiranza a chi ci \u00e8 accanto, a chi vuole assumersi la responsabilit\u00e0 della nostra amministrazione.<\/p>\n<p>&nbsp;<\/p>\n<p>La speranza \u00e8 che questo seme porti presto frutto e possa impegnarsi per un efficace cambiamento, ora.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Antonio Melcore<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il ministro dell\u2019Interno, Marco Minniti, ha fissato, con proprio decreto, la data per lo svolgimento delle consultazioni per l\u2019elezione diretta dei sindaci e dei consigli comunali, per domenica 10 giugno 2018. L\u2019eventuale turno di ballottaggio per l\u2019elezione diretta dei sindaci avr\u00e0 luogo domenica 24 giugno. &nbsp; Sono queste le date in cui ogni brindisino deve impegnarsi a scegliere il futuro di questa citt\u00e0. Dopo l\u2019ennesimo fallimento di una politica improvvisata e inconcludente, ognuno di noi deve sentire sulle proprie spalle il peso di una scelta che non pu\u00f2 essere sbagliata, che non deve essere il frutto di una superficiale visione della politica. &nbsp; Parliamo francamente: bisogna aprire gli occhi e guardarsi bene dallo scegliere slogan e improvvisazioni varie. Dovremmo tutti smettere di svenderci per il favore di turno, per l\u2019assurda promessa di un lavoro, per un caff\u00e8. Abbiamo una dignit\u00e0, come cittadini e come uomini e aggiungo che anche il nostro diritto di voto ha una dignit\u00e0. &nbsp; Siamo stanchi, lo siamo tutti e lo sono anche io. Non abbiamo&#8230;<\/p>\n","protected":false},"author":2,"featured_media":128961,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1401,1771],"class_list":["post-128960","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-amministrative","tag-melcore"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/128960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=128960"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/128960\/revisions"}],"predecessor-version":[{"id":128962,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/128960\/revisions\/128962"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/128961"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=128960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=128960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=128960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}