{"id":13105,"date":"2014-05-12T19:39:32","date_gmt":"2014-05-12T17:39:32","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=13105"},"modified":"2014-05-12T19:39:32","modified_gmt":"2014-05-12T17:39:32","slug":"venerdi-16-torna-sullonda-della-solidarieta","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/venerdi-16-torna-sullonda-della-solidarieta\/","title":{"rendered":"Venerd\u00ec 16 torna &#8220;Sull&#8217;onda della solidariet\u00e0&#8221;"},"content":{"rendered":"<p>E\u2019 stata organizzata per <strong>Venerd\u00ec 16 Maggio dalle ore 09.00 alle ore 12.00<\/strong> la 2\u00b0 Giornata conclusiva dell\u2019evento <strong>\u201cSull\u2019onda Della Solidarieta\u201d, <\/strong>indetta da ADMO Federazione Italiana (<a href=\"http:\/\/www.admo.it\/\">www.admo.it<\/a>) e dal Comando Generale delle Capitanerie di Porto e Guardia Costiera.<\/p>\n<p>Il primo appuntamento della prima Giornata di Informazione e Sensibilizzazione si\u00a0era tenuto il\u00a0\u00a027 Marzo scorso, presso la struttura della Capitaneria di Porto di Brindisi, grazie alla positiva e concreta collaborazione del Comandante Capitano di Vascello <strong>Mario Valente,<\/strong> con il coinvolgimento del personale militare che opera nella stessa struttura.<\/p>\n<p>In quella occasione,\u00a0assieme ai volontari di <em>A<\/em>DMO Brindisi, era presente il <strong>Dott. Francesco Cucci<\/strong>, Responsabile dell\u2019U.O.C. del P.O. Perrino, che ha informato i partecipanti sulle malattie sangue per il trattamento delle quali \u00e8 necessario il Trapianto di Midollo Osseo, sensibilizzandoli sulle procedure e modalit\u00e0 per la Donazione.<\/p>\n<p>&nbsp;<\/p>\n<p>Per la giornata del 16 Maggio sono stati invitati gli Studenti degli Istituti Superiori della citt\u00e0 di Brindisi con il coordinamento del Dirigente UST Brindisi, Dott. Vincenzo Melilli<strong>. <\/strong>Hanno gi\u00e0 aderito gli Istituti: <strong>Nautico Carnaro, Alberghiero, ITT Giorgi, Tecnico Scientifico Majorana, Liceo Scientifico Fermi &#8211; Monticelli, Prof. S.S Morvillo \u2013 Falcone<\/strong>, ma nelle prossime ore sono attesi altri riscontri positivi.<\/p>\n<p>&nbsp;<\/p>\n<p>I Volontari di <strong><em>A<\/em>DMO Brindisi, <\/strong>avvalendosi anche del supporto scientifico del personale medicoU.O.C. del P.O. PERRINO<strong><\/strong><strong>.<\/strong>\u00a0allestiranno un info-point,con materiale informativo e brochure,nello spazio esterno alla Capitaneria di Porto in viale Regina Margherita.<\/p>\n<p>Il Comandante <strong>Mario Valente <\/strong>accoglier\u00e0 tutti gli intervenuti alla manifestazione, informandoli sulla attivit\u00e0 della stessa struttura; \u00e8 inoltre prevista una visita su una motovedetta della Guardia Costiera, che per l\u2019occasione avr\u00e0 sulla fiancata un banner con il logo di <em>A<\/em>DMO Brindisievento sono state invitate le istituzioni politiche e sportive ed i rappresentati dei Corpi delle Forze Armate di Brindisi<strong>.<\/strong><\/p>\n<p>Tra le adesioni gi\u00e0 arrivate vi \u00e8 quella dell&#8217;Enel Basket Brindisi presieduta dal Dott. Ferdinando Marino che ha garantito la presenza di alcuni atleti della squadra di Serie A.<\/p>\n<p>Per<strong> Simona Sgura, <\/strong>Responsabile di <em>A<\/em>DMO Brindisi, l\u2019iniziativa &#8220;ha <em>come prerogativa il coinvolgimento delle Istituzioni cittadine perch\u00e9 l\u2019aggregazione delle forze e delle sinergie comuni dar\u00e0 un riscontro positivo nel diffondere il messaggio della nostra Associazione<\/em>.<strong>\u00a0<\/strong><em>Per Admo le attenzioni sono sempre pi\u00f9 rivolte ad\u00a0accrescere le adesioni dei cittadini di Brindisi al Registro dei Donatori di Midollo Osseo, in modo tale che aumenti la probabilit\u00e0 di successo nella ricerca di un donatore compatibile e che si diano nuove speranze di Vita a tutti i pazienti in attesa di Trapianto&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>E\u2019 stata organizzata per Venerd\u00ec 16 Maggio dalle ore 09.00 alle ore 12.00 la 2\u00b0 Giornata conclusiva dell\u2019evento \u201cSull\u2019onda Della Solidarieta\u201d, indetta da ADMO Federazione Italiana (www.admo.it) e dal Comando Generale delle Capitanerie di Porto e Guardia Costiera. Il primo appuntamento della prima Giornata di Informazione e Sensibilizzazione si\u00a0era tenuto il\u00a0\u00a027 Marzo scorso, presso la struttura della Capitaneria di Porto di Brindisi, grazie alla positiva e concreta collaborazione del Comandante Capitano di Vascello Mario Valente, con il coinvolgimento del personale militare che opera nella stessa struttura. In quella occasione,\u00a0assieme ai volontari di ADMO Brindisi, era presente il Dott. Francesco Cucci, Responsabile dell\u2019U.O.C. del P.O. Perrino, che ha informato i partecipanti sulle malattie sangue per il trattamento delle quali \u00e8 necessario il Trapianto di Midollo Osseo, sensibilizzandoli sulle procedure e modalit\u00e0 per la Donazione. &nbsp; Per la giornata del 16 Maggio sono stati invitati gli Studenti degli Istituti Superiori della citt\u00e0 di Brindisi con il coordinamento del Dirigente UST Brindisi, Dott. Vincenzo Melilli. Hanno gi\u00e0 aderito gli Istituti: Nautico Carnaro, Alberghiero,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":13106,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[367,382],"class_list":["post-13105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-admo","tag-capitaneria-di-porto"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/13105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=13105"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/13105\/revisions"}],"predecessor-version":[{"id":13107,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/13105\/revisions\/13107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/13106"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=13105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=13105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=13105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}