{"id":131435,"date":"2018-04-30T23:33:09","date_gmt":"2018-04-30T21:33:09","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=131435"},"modified":"2018-04-30T23:33:09","modified_gmt":"2018-04-30T21:33:09","slug":"forza-italia-replica-ai-fuoriusciti-la-scelta-di-cavalera-e-stata-condivisa-veleni-e-clima-da-guerriglia-non-ci-appartengono","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/forza-italia-replica-ai-fuoriusciti-la-scelta-di-cavalera-e-stata-condivisa-veleni-e-clima-da-guerriglia-non-ci-appartengono\/","title":{"rendered":"Forza Italia replica ai fuoriusciti: &#8220;La scelta di Cavalera \u00e8 stata condivisa, veleni e clima da guerriglia non ci appartengono&#8221;"},"content":{"rendered":"<p>Le dichiarazioni fatte durante la conferenza stampa di stamani da alcuni ex iscritti a Forza Italia (molti firmatari del comunicato stampa non rinnovano la tessera dal 2015) non ci sorprendono n\u00e9 ci sconvolgono visto che molti di loro non hanno mai partecipato alla vita di partito come appartenenti allo stesso. Spesso si sono ritrovati a seguire parallelamente diversi contenitori ed ultimamente questa situazione era sotto gli occhi di tutti.<br \/>\nCi limitiamo a dire che sono state pronunciate molte inesattezze.<\/p>\n<p>&nbsp;<\/p>\n<p>La scelta del candidato sindaco Roberto Cavalera \u00e8 stata ampiamente condivisa dagli organismi dirigenti del Partito, oltre che dalla base dello stesso. Totale condivisione \u00e8 stata espressa dai vertici nazionali di Forza Italia, come confermato dal Presidente del Parlamento europeo Antonio Tajani durante la sua recente visita a Brindisi e l&#8217;incontro con lo stesso candidato sindaco.<\/p>\n<p>La coalizione creata intorno all&#8217;avv. Cavalera \u00e8 forte e coesa ed ha le idee chiare sugli interventi da realizzare quando sar\u00e0 alla guida dell&#8217;Amministrazione Comunale di Brindisi.<\/p>\n<p>Forza Italia gode di ottima salute con tanti nuovi ingressi che hanno inteso anche offrire la loro disponibilit\u00e0 a candidarsi alle prossime elezioni comunali.<\/p>\n<p>Non ci interessa, invece, rispondere nel merito alle assurde contestazioni di chi \u00e8 andato via. Veleni e clima da guerriglia non ci appartengono.<\/p>\n<p>Brindisi ha bisogno d&#8217;altro. E noi siamo sintonizzati con i bisogni dei cittadini.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>COMUNICATO STAMPA FORZA ITALIA A FIRMA DI<br \/>\nErnestina Sicilia &#8211; Coordinatrice Cittadina<\/p>\n<p>Giuseppe Calvaruso &#8211; Vice Coordinatore Cittadino<\/p>\n<p>Alessandro De Luca &#8211; Componente Esecutivo Cittadino<\/p>\n<p>Emilio Pettinau &#8211; Coordinatore Cittadino Forza Italia Giovani<\/p>\n<p>Nicola Roppo &#8211; Vice Coordinatore Provinciale Forza Italia Giovani<\/p>\n<p>Teodoro Iaia- Componente Coordinamento Provinciale<\/p>\n<p>Cozzolino Caterina- Componente Coordinamento Provinciale<\/p>\n<p>Alessandra Cuppone &#8211; Componente Coordinamento Cittadino<\/p>\n<p>Maria Cecilia Poli Doria- Componente Coordinamento Cittadino<\/p>\n<p>Tiziana Daccico &#8211; Componente Coordinamento Cittadino<\/p>\n<p>Gianluca Cigliola- Componente Coordinamento Cittadino<\/p>\n<p>Francesco Capodieci &#8211; Componente Coordinamento Cittadino<\/p>\n<p>Livia Antonucci- Componente Coordinamento Cittadino<\/p>\n<p>Antonio Taveri &#8211; Componente Coordinamento Cittadino<\/p>\n<p>Giovanni Barbuto- Componente Coordinamento Cittadino<\/p>\n<p>Giuseppe Guadalupi &#8211; Componente Coordinamento Cittadino<\/p>\n<p>Massimo Scanni &#8211; Componente Coordinamento Cittadino<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le dichiarazioni fatte durante la conferenza stampa di stamani da alcuni ex iscritti a Forza Italia (molti firmatari del comunicato stampa non rinnovano la tessera dal 2015) non ci sorprendono n\u00e9 ci sconvolgono visto che molti di loro non hanno mai partecipato alla vita di partito come appartenenti allo stesso. Spesso si sono ritrovati a seguire parallelamente diversi contenitori ed ultimamente questa situazione era sotto gli occhi di tutti. Ci limitiamo a dire che sono state pronunciate molte inesattezze. &nbsp; La scelta del candidato sindaco Roberto Cavalera \u00e8 stata ampiamente condivisa dagli organismi dirigenti del Partito, oltre che dalla base dello stesso. Totale condivisione \u00e8 stata espressa dai vertici nazionali di Forza Italia, come confermato dal Presidente del Parlamento europeo Antonio Tajani durante la sua recente visita a Brindisi e l&#8217;incontro con lo stesso candidato sindaco. La coalizione creata intorno all&#8217;avv. Cavalera \u00e8 forte e coesa ed ha le idee chiare sugli interventi da realizzare quando sar\u00e0 alla guida dell&#8217;Amministrazione Comunale di Brindisi. Forza Italia gode di ottima salute con&#8230;<\/p>\n","protected":false},"author":2,"featured_media":71281,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[3115,250],"class_list":["post-131435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-amministrative-brindisi","tag-forza-italia"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/131435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=131435"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/131435\/revisions"}],"predecessor-version":[{"id":131436,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/131435\/revisions\/131436"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/71281"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=131435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=131435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=131435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}