{"id":133875,"date":"2018-05-27T10:02:05","date_gmt":"2018-05-27T08:02:05","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=133875"},"modified":"2018-05-27T10:46:57","modified_gmt":"2018-05-27T08:46:57","slug":"giovanni-antonino-si-scusa-dopo-le-polemiche-sul-suo-post-ogni-tanto-qualche-cazzata-la-faccio-anche-io","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/giovanni-antonino-si-scusa-dopo-le-polemiche-sul-suo-post-ogni-tanto-qualche-cazzata-la-faccio-anche-io\/","title":{"rendered":"Giovanni Antonino si scusa dopo le polemiche sul suo post: &#8220;Ogni tanto qualche cazzata la faccio anche io&#8221;"},"content":{"rendered":"<p>Dopo la polemica sul suo post che, sui social, molte persone hanno aggettivato come &#8220;mafioso&#8221;, e dopo la reazione di ben tre candidati sindaco, l&#8217;ex Sindaco di Brindisi Giovanni Antonino, condannato nell&#8217;ambito della cosiddetta &#8220;tangentopoli brindisina&#8221;, si scusa.<br \/>\nLo fa con il seguente post affidato al suo profilo Facebook.<\/p>\n<p>&nbsp;<\/p>\n<p><em>&#8220;Ogni tanto qualche cazzata la faccio anche io. Come scrivere dei post dettati dalla delusione di vedere persone che dicevano di volersi impegnare nel Partito e che poi si defilano, spesso perche costrette con gli argomenti pi\u00f9 disparati a modificare orientamento di voto. <\/em><em> Mi scuso se ho offeso la sensibilit\u00e0 di qualcuno. E<\/em><em>ra solo uno sfogo dettato dalla delusione provata sul piano umano, senza alcun altro significato&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo la polemica sul suo post che, sui social, molte persone hanno aggettivato come &#8220;mafioso&#8221;, e dopo la reazione di ben tre candidati sindaco, l&#8217;ex Sindaco di Brindisi Giovanni Antonino, condannato nell&#8217;ambito della cosiddetta &#8220;tangentopoli brindisina&#8221;, si scusa. Lo fa con il seguente post affidato al suo profilo Facebook. &nbsp; &#8220;Ogni tanto qualche cazzata la faccio anche io. Come scrivere dei post dettati dalla delusione di vedere persone che dicevano di volersi impegnare nel Partito e che poi si defilano, spesso perche costrette con gli argomenti pi\u00f9 disparati a modificare orientamento di voto. Mi scuso se ho offeso la sensibilit\u00e0 di qualcuno. Era solo uno sfogo dettato dalla delusione provata sul piano umano, senza alcun altro significato&#8221;<\/p>\n","protected":false},"author":2,"featured_media":91134,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[5932],"class_list":["post-133875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-giovanni-antonino"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/133875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=133875"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/133875\/revisions"}],"predecessor-version":[{"id":133876,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/133875\/revisions\/133876"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/91134"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=133875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=133875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=133875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}