{"id":134915,"date":"2018-06-07T15:45:11","date_gmt":"2018-06-07T13:45:11","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=134915"},"modified":"2018-06-07T15:22:44","modified_gmt":"2018-06-07T13:22:44","slug":"xxxiii-brindisi-corfu-idrusa-batti-tutti-in-tempo-reale","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/xxxiii-brindisi-corfu-idrusa-batti-tutti-in-tempo-reale\/","title":{"rendered":"XXXIII Brindisi-Corf\u00f9: Idrusa batte tutti in tempo reale"},"content":{"rendered":"<p>Torna a parlare brindisino la classifica in tempo reale della Regata internazionale Brindisi \u2013 Corf\u00f9. Al termine di poco meno di 22 ore di navigazione, infatti, ha tagliato il traguardo per prima l\u2019imbarcazione \u201cIdrusa \u2013 Brin Mar Shop\u201d di Paolo Montefusco, iscritta al Circolo della Vela di Brindisi.<\/p>\n<p>Al secondo posto un\u2019altra imbarcazione storica di questa regata, Monnshine di Fernando Ziccarelli, della Lega Navale Pesaro, che \u00e8 giunta alle boe di arrivo di Kassiopi con cinque minuti di ritardo rispetto all\u2019equipaggio di Montefusco.<\/p>\n<p>&nbsp;<\/p>\n<p>Terzo posto per Nora 57 di Rocco Giurgola, del Circolo Giurgola-Stampi.<\/p>\n<p>&nbsp;<\/p>\n<p>Questa vittoria di Idrusa assume un significato ancora pi\u00f9 importante se si considera la disavventura verificatasi in partenza, davanti alla boa del Trombillo. L\u2019imbarcazione nell\u2019impatto ha subito la rottura della sartia di dritta (il cavo che mantiene l\u2019albero di poppa). Solo grazie ad un equipaggio super esperto la parte danneggiata \u00e8 stata sostituita durante la navigazione (\u00e8 stato necessario salire in testa all\u2019albero). Idrusa ha dovuto rinunciare anche all\u2019utilizzo dello spinnaker per venti leggeri, risultato danneggiato proprio in fase di partenza.<\/p>\n<p>&nbsp;<\/p>\n<p>Adesso si attende la classifica in tempo compensato.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torna a parlare brindisino la classifica in tempo reale della Regata internazionale Brindisi \u2013 Corf\u00f9. Al termine di poco meno di 22 ore di navigazione, infatti, ha tagliato il traguardo per prima l\u2019imbarcazione \u201cIdrusa \u2013 Brin Mar Shop\u201d di Paolo Montefusco, iscritta al Circolo della Vela di Brindisi. Al secondo posto un\u2019altra imbarcazione storica di questa regata, Monnshine di Fernando Ziccarelli, della Lega Navale Pesaro, che \u00e8 giunta alle boe di arrivo di Kassiopi con cinque minuti di ritardo rispetto all\u2019equipaggio di Montefusco. &nbsp; Terzo posto per Nora 57 di Rocco Giurgola, del Circolo Giurgola-Stampi. &nbsp; Questa vittoria di Idrusa assume un significato ancora pi\u00f9 importante se si considera la disavventura verificatasi in partenza, davanti alla boa del Trombillo. L\u2019imbarcazione nell\u2019impatto ha subito la rottura della sartia di dritta (il cavo che mantiene l\u2019albero di poppa). Solo grazie ad un equipaggio super esperto la parte danneggiata \u00e8 stata sostituita durante la navigazione (\u00e8 stato necessario salire in testa all\u2019albero). Idrusa ha dovuto rinunciare anche all\u2019utilizzo dello spinnaker per venti leggeri,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":134501,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1232],"tags":[],"class_list":["post-134915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vela"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/134915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=134915"}],"version-history":[{"count":2,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/134915\/revisions"}],"predecessor-version":[{"id":134920,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/134915\/revisions\/134920"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/134501"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=134915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=134915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=134915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}