{"id":146380,"date":"2018-12-16T12:26:36","date_gmt":"2018-12-16T11:26:36","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=146380"},"modified":"2018-12-16T11:30:42","modified_gmt":"2018-12-16T10:30:42","slug":"fermato-alla-guida-dellauto-rifiuta-di-sottoporsi-ai-controlli-patente-sospesa-auto-confiscata","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/fermato-alla-guida-dellauto-rifiuta-di-sottoporsi-ai-controlli-patente-sospesa-auto-confiscata\/","title":{"rendered":"Fermato alla guida dell&#8217;auto rifiuta di sottoporsi ai controlli: patente sospesa, auto confiscata"},"content":{"rendered":"<p>San Pietro Vernotico: 24enne fermato alla guida della propria autovettura, si rifiuta di sottoporsi agli accertamenti per la verifica dell\u2019eventuale assunzione di stupefacente. La patente di guida \u00e8 stata ritirata e il veicolo sottoposto a sequestro ai fini della confisca. Perquisito \u00e8 stato trovato in possesso di quattro grammi di marijuana occultato nel portamonete. \u00c9 stato segnalato quale assuntore all\u2019autorit\u00e0 amministrativa.<\/p>\n<p>I Carabinieri della Stazione di San Pietro Vernotico hanno deferito in stato di libert\u00e0 un 24enne del luogo per rifiuto dell\u2019accertamento finalizzato a stabilire lo stato di alterazione psicofisica dovuta all\u2019assunzione di sostanze stupefacenti. Il giovane \u00e8 stato controllato nel corso della serata nell\u2019ambito di un posto di controllo alla circolazione stradale, alla guida di una Fiat Punto di propriet\u00e0. Nella circostanza si \u00e8 rifiutato di sottoporsi ad accertamento riguardo all\u2019assunzione di stupefacente ed \u00e8 stato deferito all\u2019Autorit\u00e0 Giudiziaria. La patente di guida gli \u00e8 stata ritirata e il veicolo sottoposto a sequestro ai fini della confisca. Perquisito \u00e8 stato trovato in possesso di quattro grammi di marijuana sottoposta a sequestro, occultati nel giubbino.<\/p>\n<p>Per quanto riguarda il rifiuto dell\u2019accertamento finalizzato al riscontro dello stato di alterazione psicofisica dovuta all\u2019assunzione di sostanze stupefacenti o psicotrope, la norma sanzionatoria punisce tale comportamento con sanzioni di natura penale, pena congiunta dell\u2019arresto e dell\u2019ammenda. All\u2019accertamento del reato consegue la sanzione amministrativa accessoria della sospensione della patente di guida da uno a due anni. Se il veicolo appartiene a persona estranea al reato, la durata della sospensione della patente \u00e8 raddoppiata. Con la sentenza di condanna \u00e8 sempre disposta la confisca del veicolo con il quale \u00e8 stato commesso il reato, salvo che non appartenga a persona estranea. La confisca \u00e8 un provvedimento a carattere sanzionatorio, attraverso il quale la propriet\u00e0 del bene passa dal privato allo Stato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>San Pietro Vernotico: 24enne fermato alla guida della propria autovettura, si rifiuta di sottoporsi agli accertamenti per la verifica dell\u2019eventuale assunzione di stupefacente. La patente di guida \u00e8 stata ritirata e il veicolo sottoposto a sequestro ai fini della confisca. Perquisito \u00e8 stato trovato in possesso di quattro grammi di marijuana occultato nel portamonete. \u00c9 stato segnalato quale assuntore all\u2019autorit\u00e0 amministrativa. I Carabinieri della Stazione di San Pietro Vernotico hanno deferito in stato di libert\u00e0 un 24enne del luogo per rifiuto dell\u2019accertamento finalizzato a stabilire lo stato di alterazione psicofisica dovuta all\u2019assunzione di sostanze stupefacenti. Il giovane \u00e8 stato controllato nel corso della serata nell\u2019ambito di un posto di controllo alla circolazione stradale, alla guida di una Fiat Punto di propriet\u00e0. Nella circostanza si \u00e8 rifiutato di sottoporsi ad accertamento riguardo all\u2019assunzione di stupefacente ed \u00e8 stato deferito all\u2019Autorit\u00e0 Giudiziaria. La patente di guida gli \u00e8 stata ritirata e il veicolo sottoposto a sequestro ai fini della confisca. Perquisito \u00e8 stato trovato in possesso di quattro grammi di marijuana sottoposta&#8230;<\/p>\n","protected":false},"author":2,"featured_media":138764,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-146380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/146380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=146380"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/146380\/revisions"}],"predecessor-version":[{"id":146385,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/146380\/revisions\/146385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/138764"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=146380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=146380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=146380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}