{"id":146493,"date":"2018-12-18T09:43:48","date_gmt":"2018-12-18T08:43:48","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=146493"},"modified":"2018-12-22T17:28:42","modified_gmt":"2018-12-22T16:28:42","slug":"aggredisce-i-carabinieri-con-una-zappa-bloccato-con-lo-spray-al-peperoncino","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/aggredisce-i-carabinieri-con-una-zappa-bloccato-con-lo-spray-al-peperoncino\/","title":{"rendered":"Aggredisce i Carabinieri con una zappa: bloccato con lo spray al peperoncino"},"content":{"rendered":"<p>I Carabinieri della Stazione di Mesagne al termine degli accertamenti hanno deferito in stato di libert\u00e0 un operaio 47 residente del luogo per il reato di minaccia a pubblico ufficiale.<\/p>\n<p>I militari unitamente ad assistente sociale del comune, sono intervenuti al fine di dare piena esecuzione ad un provvedimento di accompagnamento presso una \u201cComunit\u00e0 Educativa\u201d emesso dal Tribunale per i Minorenni di Lecce, nei confronti di una ragazza 16enne e della figlia di 6 mesi. In tale contesto si sono susseguite fasi concitate, un congiunto zio della donna si \u00e8 opposto al trasferimento della minore e della neonata presso la comunit\u00e0, dopo aver urlato a squarciagola la sua disapprovazione ha prelevato dall\u2019orto una zappa e brandendola con aria minacciosa si \u00e8 diretto verso gli astanti.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019uomo ha cos\u00ec continuato ad urlare dicendo che avrebbe ucciso tutti e comunque che avrebbe impedito che la neonata e la madre fossero condotte in altro luogo.<\/p>\n<p>Uno dei due militari intervenuti ha cercato di attirare su di s\u00e8 le attenzioni dell\u2019uomo alla ricerca dello scontro fisico, che ad un certo punto ha abbandonato la zappa per terra e si \u00e8 lanciato in direzione del Carabiniere che rapidamente per rendere inoffensivo l\u2019aggressore ha utilizzato il dispositivo spray di \u201cOleoresina di Capsicum\u201d, spruzzandolo in direzione dell\u2019uomo, neutralizzandone pertanto l\u2019azione.<\/p>\n<p>&nbsp;<\/p>\n<p>Quindi, la minore e l\u2019infante sono state successivamente accompagnate nella Comunit\u00e0 educativa dall\u2019assistente sociale e dal tutore nominato dal Tribunale.<\/p>\n<p>&nbsp;<\/p>\n<p>Il dispositivo spray a base di oleoresina di capsicum, integra gli strumenti di protezione del personale, incrementandone i livelli di sicurezza garantendone, in caso di necessit\u00e0, la possibilit\u00e0 di un uso calibrato. Il citato dispositivo, oltre a costituire uno strumento di dissuasione e autodifesa, contiene un principio attivo naturale a base di \u201coleoresina capsicum\u201d, e costituisce un valido supporto per l\u2019operatore impegnato nei servizi di e \u201cnon ha l\u2019attitudine a recare offesa alla persona\u201d, in quanto contiene una miscela complessiva pari a 20 ml con una percentuale di oleoresina capsicum, disciolto, non superiore al 10% e una concentrazione massima totale di capsaicina e capsaicinoidi pari a 2,5%.<\/p>\n<p>Pertanto non vi sono rischi per coloro i quali vengono attinti, il principio attivo alla base \u00e8 la capsaicina, derivato dai frutti delle piante del genere Capsicum, tra cui il peperoncino.<\/p>\n<p>In particolare, la sostanza produce una rapida irritazione di cute, occhi e vie aeree primarie, determinando un\u2019incapacit\u00e0 di reazione per un tempo di circa 10\/15 secondi ai quali pu\u00f2 seguire una fase di iperattivit\u00e0 (conseguente al disagio fisico percepito) della durata di circa 30 secondi. Lo strumento, deve essere legittimamente impiegato al profilarsi di un\u2019azione violenta o una resistenza attiva, rivolta verso l\u2019operatore e\/o altre persone coinvolte nel contesto operativo, allorch\u00e9 ogni tentativo di negoziazione, mediazione o dissuasione verbale sia fallito.<\/p>\n<p>Pertanto, nel rispetto del principio di proporzionalit\u00e0 tra offesa e difesa, il dispositivo rappresenta un valido strumento volto a neutralizzare temporaneamente un comportamento aggressivo ed evitare che venga portato a conseguenze ulteriori. Il personale del Comando Provinciale, sulla scorta delle disposizioni ricevute superiormente, ha provveduto ad addestrare il personale dipendente e a distribuire il dispositivo ai reparti deputati ai servizi di controllo del territorio, Stazioni ed Aliquote Radiomobili.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I Carabinieri della Stazione di Mesagne al termine degli accertamenti hanno deferito in stato di libert\u00e0 un operaio 47 residente del luogo per il reato di minaccia a pubblico ufficiale. I militari unitamente ad assistente sociale del comune, sono intervenuti al fine di dare piena esecuzione ad un provvedimento di accompagnamento presso una \u201cComunit\u00e0 Educativa\u201d emesso dal Tribunale per i Minorenni di Lecce, nei confronti di una ragazza 16enne e della figlia di 6 mesi. In tale contesto si sono susseguite fasi concitate, un congiunto zio della donna si \u00e8 opposto al trasferimento della minore e della neonata presso la comunit\u00e0, dopo aver urlato a squarciagola la sua disapprovazione ha prelevato dall\u2019orto una zappa e brandendola con aria minacciosa si \u00e8 diretto verso gli astanti. &nbsp; L\u2019uomo ha cos\u00ec continuato ad urlare dicendo che avrebbe ucciso tutti e comunque che avrebbe impedito che la neonata e la madre fossero condotte in altro luogo. Uno dei due militari intervenuti ha cercato di attirare su di s\u00e8 le attenzioni dell\u2019uomo alla ricerca&#8230;<\/p>\n","protected":false},"author":2,"featured_media":146494,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-146493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/146493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=146493"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/146493\/revisions"}],"predecessor-version":[{"id":146495,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/146493\/revisions\/146495"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/146494"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=146493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=146493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=146493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}