{"id":15026,"date":"2014-06-07T17:21:51","date_gmt":"2014-06-07T15:21:51","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=15026"},"modified":"2014-10-15T19:06:17","modified_gmt":"2014-10-15T17:06:17","slug":"oggiano-lppdt-sullemergenza-abitativa-a-parco-bove","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/oggiano-lppdt-sullemergenza-abitativa-a-parco-bove\/","title":{"rendered":"Oggiano (Lppdt) sull&#8217;emergenza abitativa a Parco Bove"},"content":{"rendered":"<p>Il piano per affrontare l&#8217;emergenza abitativa di Parco Bove\u00a0 venne deliberato nel lontano 2002 su proposta dello scrivente ed approvato dall&#8217;allora Consiglio Comunale. Quel piano prevedeva una serie d&#8217;interventi per dare una sistemazione dignitosa a circa 130 famiglie che subito dopo il dopoguerra\u00a0 furono temporaneamente alloggiate in baracche che col tempo furono trasformate in abitazioni!<\/p>\n<p>In quella proposta era previsto, cos\u00ec come poi \u00e8 successo, il trasferimento di circa\u00a0 70 nuclei familiari nei nuovi alloggi di piazza Raffaello e via Spadini al rione S. Elia, e le rimanenti famiglie avrebbero trovato collocazione in viale Torretta di fronte al supermercato Famila. La passata Amministrazione riusc\u00ec ad attivare tutte quelle procedure (reperimento dei canali di finanziamento, progettazione e costruzione) dei primi 28 alloggi che finalmente sono stati assegnati ieri, dopo una serie di lungaggini incomprensibili, \u00a0ad altrettante famiglie di Parco Bove.<\/p>\n<p>Per risolvere definitivamente il problema delle rimanenti famiglie, e&#8217; bene precisare, nella passata consiliatura l\u2019Amministrazione Mennitti ottenne un finanziamento di 3.800.000 euro rinvenienti dal Programma straordinario di edilizia residenziale pubblica del Ministero delle Infrastrutture a cui si aggiunsero 700.000 euro di fondi propri (regolarmente stanziati in bilancio) per la costruzione di ulteriori 45\/50 alloggi comunali, sempre in zona \u201cTorretta\u201d, da destinare alle rimanenti famiglie residenti\/assegnatarie di Parco Bove!<\/p>\n<p>Non si capisce pertanto perch\u00e9 a distanza di due anni dal suo insediamento l&#8217;amministrazione Consales non \u00e8 riuscita a cantierizzare ci\u00f2 che gi\u00e0 era pronto e regolarmente finanziato, provvedendo solo a gestire una normale procedura di assegnazioni di alloggi gi\u00e0 pronti da diverso tempo! L&#8217;8 gennaio scorso presentavo una interrogazione urgente, per chiedere chiarimenti in merito a tali argomenti, puntualmente disattesa come spesso succede con tutte le altre interrogazioni ed interpellanze indirizzate all&#8217;Amministrazione Consales!<\/p>\n<p>Leggiamo invece nelle dichiarazioni virgolettate dell&#8217;assessore Luperti che il Comune sta chiedendo un finanziamento di 5.000.000 di euro per la costruzione di 50 alloggi da destinare alle rimanenti famiglie di Parco Nove, facendo anche intendere\u00a0 che si \u00e8 in fase d&#8217;individuazione dell&#8217;area dove sorgeranno: sarebbe opportuno che qualcuno ricordasse e\u00a0 comunicasse allo stesso di non perdere ulteriore tempo con roboanti e fuorvianti dichiarazioni e che i soldi sono stati gi\u00e0 assegnati attraverso il PRUACS in dotazione alla Regione Puglia che dovr\u00e0 semplicemente rigirarli al Comune\u00a0 di Brindisi previa la sottoscrizione della relativa convenzione, sempre che gi\u00e0 non sia stata sottoscritta; inoltre bisognerebbe ricordare sempre allo stesso che l&#8217;aerea interessata e&#8217; la stessa dove sono stati costruiti i primi 28 alloggi e cio\u00e8 in viale Torretta!<\/p>\n<p>Tanto dovevo per una corretta informazione sulle vicende di Parco Bove.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>COMUNICATO STAMPA MASSIMILIANO OGGIANO &#8211; CONSIGLIERE COMUNALE DE LA PUGLIA PRIMA DI TUTTO<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il piano per affrontare l&#8217;emergenza abitativa di Parco Bove\u00a0 venne deliberato nel lontano 2002 su proposta dello scrivente ed approvato dall&#8217;allora Consiglio Comunale. Quel piano prevedeva una serie d&#8217;interventi per dare una sistemazione dignitosa a circa 130 famiglie che subito dopo il dopoguerra\u00a0 furono temporaneamente alloggiate in baracche che col tempo furono trasformate in abitazioni! In quella proposta era previsto, cos\u00ec come poi \u00e8 successo, il trasferimento di circa\u00a0 70 nuclei familiari nei nuovi alloggi di piazza Raffaello e via Spadini al rione S. Elia, e le rimanenti famiglie avrebbero trovato collocazione in viale Torretta di fronte al supermercato Famila. La passata Amministrazione riusc\u00ec ad attivare tutte quelle procedure (reperimento dei canali di finanziamento, progettazione e costruzione) dei primi 28 alloggi che finalmente sono stati assegnati ieri, dopo una serie di lungaggini incomprensibili, \u00a0ad altrettante famiglie di Parco Bove. Per risolvere definitivamente il problema delle rimanenti famiglie, e&#8217; bene precisare, nella passata consiliatura l\u2019Amministrazione Mennitti ottenne un finanziamento di 3.800.000 euro rinvenienti dal Programma straordinario di edilizia residenziale pubblica del&#8230;<\/p>\n","protected":false},"author":2,"featured_media":11264,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[865],"class_list":["post-15026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-oggiano"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/15026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=15026"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/15026\/revisions"}],"predecessor-version":[{"id":15027,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/15026\/revisions\/15027"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/11264"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=15026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=15026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=15026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}