{"id":150675,"date":"2019-03-01T12:25:58","date_gmt":"2019-03-01T11:25:58","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=150675"},"modified":"2019-03-01T12:25:58","modified_gmt":"2019-03-01T11:25:58","slug":"domenica-le-primarie-per-scegliere-il-segretario-del-pd-ecco-lelenco-dei-seggi-allestiti-in-provincia-di-brindisi","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/domenica-le-primarie-per-scegliere-il-segretario-del-pd-ecco-lelenco-dei-seggi-allestiti-in-provincia-di-brindisi\/","title":{"rendered":"Domenica le primarie per scegliere il Segretario del PD: ecco l&#8217;elenco dei seggi allestiti in Provincia di Brindisi"},"content":{"rendered":"<p>Domenica 3 marzo, dalle ore 8:00 alle ore 20:00 si terranno le primarie per eleggere il Segretario Nazionale del Partito Democratico ed i componenti dell&#8217;Assemblea Nazionale.<\/p>\n<p>I candidati alla carica di segretario nazionale del Partito Democratico sono: Maurizio Martina, Nicola Zingaretti e Roberto Giachetti.<\/p>\n<p>Al voto pu\u00f2 partecipare chiunque anche se non iscritto al Partito Democratico.<\/p>\n<p>Possono votare tutti gli iscritti e gli elettori che dichiarino di riconoscersi nella proposta politica del Partito, di sostenerlo alle elezioni, e accettino di essere registrate nell\u2019Albo pubblico delle elettrici e degli elettori. I giovani al di sopra dei 16 anni, i fuori sede e gli extracomunitari devono aver fatto gi\u00e0 la registrazione online.<\/p>\n<p>Per poter votare, l\u2019elettore dovr\u00e0 portare un documento di riconoscimento, la tessera elettorale e versare un contributo di 2 euro<\/p>\n<p>Queste le sedi che ospiteranno i seggi :<br \/>\nBrindisi: Sede del PD Via Osanna 61<br \/>\nCarovigno: sede del PD corso Vittorio Emanuele 35<br \/>\nCeglie Messapica: locale pubblico via xxsettembre 89<br \/>\nCellino San Marco: sede del PD<br \/>\nCisternino: circolo PD via Roma 52<br \/>\nErchie: circolo PD via Grassi<br \/>\nFasano: laboratorio urbano Corso Vittorio Emanuele<br \/>\nFrancavilla F.na: teatro Imperiali Municipio<br \/>\nLatiano: Palazzo Imperiali piazza Umberto I<br \/>\nMesagne: circolo PD via Roma 33<br \/>\nOria: circolo PD via Roma 35<br \/>\nOstuni: biblioteca comunale Dott. Francesco Rodio<br \/>\nSan Michele: locale pubblico via De Amicis 41<br \/>\nS. Vito dei Normanni: circolo PD via Tasso<br \/>\nSan Donaci: circolo PD Via Cellino 48<br \/>\nSan Pancrazio: circolo PD via Duca degli Abruzzi<br \/>\nSan Pietro: circolo PD via Brindisi114<br \/>\nTorchiarolo: circolo PD Umberto I ,1<br \/>\nTorre Santa Susanna: circolo PD piazza Umberto I<br \/>\nVilla Castelli: locale pubblico via Belvedere 94<\/p>\n<p>Le liste della provincia di Brindisi per l&#8217;elezione dei delegati all&#8217;assemblea nazionale sono cos\u00ec composte:<\/p>\n<p>LISTA PER MARTINA SEGRETARIO<br \/>\n1. Francesco Cannalire<br \/>\n2. Daniela Faggiano<br \/>\n3. Ivo Francavilla<br \/>\n4. Nicoletta Pannofino<br \/>\n5. Vincenzo Miccoli<\/p>\n<p>PIAZZA GRANDE CON ZINGARETTI<br \/>\n1. Francesco Rogoli<br \/>\n2. Maria Luce Rollo<br \/>\n3. Marcello Cafueri<br \/>\n4. Sara Scalera<br \/>\n5. Mimmo Tardio<\/p>\n<p>LA PUGLIA PER ZINGARETTI<br \/>\n1. Sabrina Birtolo<br \/>\n2. Sergio Montanaro<br \/>\n3. Ilaria Roma<br \/>\n4. Domenico Conte<br \/>\n5. Antonella Vincenti<\/p>\n<p>LISTA PER GIACHETTI SEGRETARIO<br \/>\n1 Nicola Cavallo<br \/>\n2 Maria Rizzo<br \/>\n3 Damiano Cal\u00f2<br \/>\n4 Miriam Solazzo<br \/>\n5 Oronzo Cavallo<\/p>\n<p>Partito Democratico di Brindisi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domenica 3 marzo, dalle ore 8:00 alle ore 20:00 si terranno le primarie per eleggere il Segretario Nazionale del Partito Democratico ed i componenti dell&#8217;Assemblea Nazionale. I candidati alla carica di segretario nazionale del Partito Democratico sono: Maurizio Martina, Nicola Zingaretti e Roberto Giachetti. Al voto pu\u00f2 partecipare chiunque anche se non iscritto al Partito Democratico. Possono votare tutti gli iscritti e gli elettori che dichiarino di riconoscersi nella proposta politica del Partito, di sostenerlo alle elezioni, e accettino di essere registrate nell\u2019Albo pubblico delle elettrici e degli elettori. I giovani al di sopra dei 16 anni, i fuori sede e gli extracomunitari devono aver fatto gi\u00e0 la registrazione online. Per poter votare, l\u2019elettore dovr\u00e0 portare un documento di riconoscimento, la tessera elettorale e versare un contributo di 2 euro Queste le sedi che ospiteranno i seggi : Brindisi: Sede del PD Via Osanna 61 Carovigno: sede del PD corso Vittorio Emanuele 35 Ceglie Messapica: locale pubblico via xxsettembre 89 Cellino San Marco: sede del PD Cisternino: circolo PD via&#8230;<\/p>\n","protected":false},"author":2,"featured_media":150686,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-150675","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/150675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=150675"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/150675\/revisions"}],"predecessor-version":[{"id":150687,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/150675\/revisions\/150687"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/150686"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=150675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=150675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=150675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}