{"id":151382,"date":"2019-03-13T14:52:11","date_gmt":"2019-03-13T13:52:11","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=151382"},"modified":"2019-03-13T21:56:01","modified_gmt":"2019-03-13T20:56:01","slug":"42enne-ubriaca-e-senza-patente-danneggia-auto-in-sosta-denunciata","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/42enne-ubriaca-e-senza-patente-danneggia-auto-in-sosta-denunciata\/","title":{"rendered":"42enne ubriaca e senza patente danneggia auto in sosta: denunciata"},"content":{"rendered":"<p>A Brindisi, i Carabinieri della Sezione Radiomobile a conclusione degli accertamenti, hanno deferito in stato di libert\u00e0 una 42enne del luogo per rifiuto di sottoporsi ad accertamenti finalizzati a stabilire la guida in condizioni di alterazione psicofisica dovuta all\u2019assunzione di droghe e di alcol. I fatti si sono verificati poco dopo la mezzanotte, quando la pattuglia \u00e8 stata attivata da alcuni cittadini che si erano rivolti al numero di pronto intervento 112 in quanto proprietari di auto in sosta che erano state danneggiate dalle manovre della vettura condotta da una donna che \u00e8 stata cos\u00ec identificata. La stessa si \u00e8 presentata agli operanti in evidente stato di agitazione profferendo frasi sconnesse, in equilibrio precario ed emanando un alito fortemente vinoso. La stessa \u00e8 risultata priva del documento di identificazione, nonch\u00e9 di guida, in quanto non ha mai conseguito la patente; presenta a carico tutta una serie di censure penali per reati relativi allo stupefacente. Nella circostanza ha rifiutato sia di sottoporsi all\u2019accertamento per la verifica dello stato di ebbrezza sia per l\u2019eventuale assunzione di sostanze stupefacenti. Il 73enne proprietario della vettura, originario di Villa Castelli, ha riferito che poco prima aveva affidato le chiavi del suo veicolo alla donna che le aveva richieste per effettuare un giro in piazza. La donna \u00e8 stata anche sanzionata amministrativamente per la guida senza patente poich\u00e9 mai conseguita, mentre il proprietario del veicolo risponder\u00e0 del reato di \u201cincauto affidamento\u201d, poich\u00e9 lo ha affidato o ne ha consentito la guida a persona che non ha conseguito la corrispondente patente di guida. L\u2019autovettura \u00e8 stata sottoposta a fermo amministrativo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Brindisi, i Carabinieri della Sezione Radiomobile a conclusione degli accertamenti, hanno deferito in stato di libert\u00e0 una 42enne del luogo per rifiuto di sottoporsi ad accertamenti finalizzati a stabilire la guida in condizioni di alterazione psicofisica dovuta all\u2019assunzione di droghe e di alcol. I fatti si sono verificati poco dopo la mezzanotte, quando la pattuglia \u00e8 stata attivata da alcuni cittadini che si erano rivolti al numero di pronto intervento 112 in quanto proprietari di auto in sosta che erano state danneggiate dalle manovre della vettura condotta da una donna che \u00e8 stata cos\u00ec identificata. La stessa si \u00e8 presentata agli operanti in evidente stato di agitazione profferendo frasi sconnesse, in equilibrio precario ed emanando un alito fortemente vinoso. La stessa \u00e8 risultata priva del documento di identificazione, nonch\u00e9 di guida, in quanto non ha mai conseguito la patente; presenta a carico tutta una serie di censure penali per reati relativi allo stupefacente. Nella circostanza ha rifiutato sia di sottoporsi all\u2019accertamento per la verifica dello stato di ebbrezza sia&#8230;<\/p>\n","protected":false},"author":2,"featured_media":130350,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-151382","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/151382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=151382"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/151382\/revisions"}],"predecessor-version":[{"id":151386,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/151382\/revisions\/151386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/130350"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=151382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=151382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=151382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}